{"id":12219,"date":"2008-05-07T10:48:00","date_gmt":"2008-05-07T10:48:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=12219"},"modified":"2008-05-07T10:48:00","modified_gmt":"2008-05-07T10:48:00","slug":"maria-inspira-formas-criativas-de-solidariedade","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/maria-inspira-formas-criativas-de-solidariedade\/","title":{"rendered":"Maria inspira formas criativas de solidariedade"},"content":{"rendered":"<p>Peregrina\u00e7\u00e3o ao Santu\u00e1rio de Schoenstatt <!--more--> Os santu\u00e1rios, sendo locais de \u201cora\u00e7\u00e3o, promo\u00e7\u00e3o vocacional e espiritualidade mariana\u201d, podem \u201cpromover iniciativas evangelizadoras\u201d e \u201cser espa\u00e7o e momento para acolher e servir o pobre como Maria\u201d, afirmou o Bispo de Aveiro<\/p>\n<p>D. Ant\u00f3nio Francisco convidou o Santu\u00e1rio de Schoenstatt e as  pessoas que a ele peregrinaram, na tarde do primeiro Domingo de Maio, a assumirem uma voca\u00e7\u00e3o de servi\u00e7o aos pobres, em linha com o plano pastoral diocesano. Os santu\u00e1rios, sendo locais de \u201cora\u00e7\u00e3o, promo\u00e7\u00e3o vocacional e espiritualidade mariana\u201d, podem \u201cpromover iniciativas evangelizadoras\u201d e \u201cser espa\u00e7o e momento para acolher e servir o pobre como Maria\u201d, que em Schoenstatt \u00e9 invocada como \u201cM\u00e3e admir\u00e1vel\u201d. \u201cOxal\u00e1 os santu\u00e1rios descubram tamb\u00e9m esta miss\u00e3o (\u2026). Os pobres exigem de n\u00f3s uma ac\u00e7\u00e3o consequente\u201d, afirmou o Bispo de Aveiro, pedindo \u00e0 m\u00e3e de Jesus \u201cque inspire formas criativas de solidariedade\u201d.<\/p>\n<p>Vivendo-se o dia da M\u00e3e, D. Ant\u00f3nio saudou todas as m\u00e3es, que s\u00e3o \u201csantu\u00e1rio humano onde se toca a bondade de Deus\u201d. Deixou ainda uma palavra sobre os meios de comunica\u00e7\u00e3o social, cujo dia mundial se comemorava no Domingo da Ascens\u00e3o. Quem trabalha na comunica\u00e7\u00e3o social deve procurar a verdade sobre o Homem, \u201cdefendendo-a daqueles que tentam extingui-la\u201d.<\/p>\n<p>Antes da Eucaristia, que concluiu a peregrina\u00e7\u00e3o, o Santu\u00e1rio situado na Col\u00f3nia Agr\u00edcola da Gafanha da Nazar\u00e9 dedicou a tarde \u00e0s crian\u00e7as e aos jovens. Um coro cantou m\u00fasicas infantis e a Nossa Senhora, houve representa\u00e7\u00f5es teatrais, pintura facial e trabalhos manuais.<\/p>\n<p>Respondendo ao apelo do Santu\u00e1rio, muitas pessoas ofereceram enxovais de crian\u00e7as que v\u00e3o agora ser canalizados para institui\u00e7\u00f5es de apoio infantil e a m\u00e3es desprotegidas.<\/p>\n<p>De salientar que algumas pessoas das par\u00f3quias de Salreu, Oliveirinha, Bustos e Gafanha da Nazar\u00e9 se dirigiram ao santu\u00e1rio a p\u00e9. Esta poder\u00e1 ser uma pr\u00e1tica a \u201cdesenvolver no futuro\u201d, conforme referiu ao Correio do Vouga o P.e Jos\u00e9 Melo, respons\u00e1vel do Santu\u00e1rio, \u201cse cada par\u00f3quia se organizar em sintonia com o seu p\u00e1roco\u201d.<\/p>\n<p>A peregrina\u00e7\u00e3o diocesana de 2008 a Schoenstatt, com cerca de dois milhares de pessoas, foi uma das mais concorridas dos \u00faltimos anos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Peregrina\u00e7\u00e3o ao Santu\u00e1rio de Schoenstatt<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-12219","post","type-post","status-publish","format-standard","hentry","category-destaque"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/12219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=12219"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/12219\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=12219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=12219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=12219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}