{"id":16103,"date":"2006-04-03T14:44:00","date_gmt":"2006-04-03T14:44:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=16103"},"modified":"2006-04-03T14:44:00","modified_gmt":"2006-04-03T14:44:00","slug":"um-campeonato-em-tres-frentes","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/um-campeonato-em-tres-frentes\/","title":{"rendered":"Um campeonato em tr\u00eas frentes"},"content":{"rendered":"<p>Quem desce, quem vai \u00e0 Europa? <!--more--> A 25\u00aa jornada da Super Liga n\u00e3o foi prop\u00edcia em novidades e surpresas. Deste modo, Porto, Sporting e Benfica venceram os seus jogos solidificando cada vez mais as suas posi\u00e7\u00f5es. Os drag\u00f5es abriram a jornada e arrasaram um Belenenses que tarda em sair de situa\u00e7\u00e3o complicada na tabela. O Sporting venceu facilmente o Beira-Mar fruto de dois golos marcados nos primeiros 10 minutos. O Benfica teve maiores dificuldades para levar de vencido o Gil Vicente, at\u00e9 porque alguns jogadores evidenciavam o cansa\u00e7o provocado pelo compromisso europeu de 4\u00aa feira, na Noruega. Na pr\u00f3xima 5\u00aa feira os encarnados voltam a jogar para a Ta\u00e7a UEFA, desta vez perante o Inter de Mil\u00e3o na Luz.<\/p>\n<p>Na luta pelos restantes lugares europeus, o Nacional refor\u00e7ou a tend\u00eancia j\u00e1 aqui escrita confirmando ser o mais s\u00e9rio candidato ao quarto lugar depois de derrotar a Acad\u00e9mica por 2-1. <\/p>\n<p>Nitidamente em quebra neste grupo est\u00e1 o Beira Mar e o Boavista, que merc\u00ea de um empate caseiro frente ao aflito Pa\u00e7os de Ferreira (1-1), despediu Sanchez do comando t\u00e9cnico da equipa.<\/p>\n<p>Na fuga \u00e0 despromo\u00e7\u00e3o o Estrela marcou passo e espera que a matem\u00e1tica confirme a impossibilidade da manuten\u00e7\u00e3o. <\/p>\n<p>Pa\u00e7os de Ferreira e Guimar\u00e3es empataram fora de portas e aproximaram-se da Acad\u00e9mica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quem desce, quem vai \u00e0 Europa?<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-16103","post","type-post","status-publish","format-standard","hentry","category-desporto"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/16103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=16103"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/16103\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=16103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=16103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=16103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}