{"id":16105,"date":"2006-04-03T14:44:00","date_gmt":"2006-04-03T14:44:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=16105"},"modified":"2006-04-03T14:44:00","modified_gmt":"2006-04-03T14:44:00","slug":"financas-publicas-tres-posicoes","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/financas-publicas-tres-posicoes\/","title":{"rendered":"Finan\u00e7as p\u00fablicas &#8211; tr\u00eas posi\u00e7\u00f5es"},"content":{"rendered":"<p>Quest\u00f5es sociais <!--more--> 1. As finan\u00e7as p\u00fablicas incluem a fiscalidade, o or\u00e7amento, a d\u00edvida p\u00fablica e problemas afins. Constituem uma condicionante decisiva da vida colectiva, reflectindo-se em elevado n\u00famero de fam\u00edlias e de cidad\u00e3os. Por tal motivo, bem se compreende que as finan\u00e7as p\u00fablicas estejam hoje no centro das preocupa\u00e7\u00f5es pol\u00edticas. A\u00ed sobressai o grave problema do d\u00e9fice or\u00e7amental, que tanto ocupa e divide a opini\u00e3o p\u00fablica e as for\u00e7as pol\u00edticas e sociais.<\/p>\n<p>2. H\u00e1 tr\u00eas posi\u00e7\u00f5es bastante distintas em rela\u00e7\u00e3o \u00e0s finan\u00e7as p\u00fablicas. A corrente expansionista entende que a despesa p\u00fablica deve aumentar consideravelmente para a melhoria das condi\u00e7\u00f5es sociais e para que, atrav\u00e9s do investimento, se atinjam ritmos mais acelerados de crescimento econ\u00f3mico e de desenvolvimento.<\/p>\n<p>A corrente restritiva entende que deve ser controlado o aumento da despesa e limitado o d\u00e9fice, a fim de que n\u00e3o vivamos acima das nossas possibilidades e n\u00e3o transfira-mos, para gera\u00e7\u00f5es futuras, as consequ\u00eancias do endividamento excessivo.<\/p>\n<p>A corrente restritiva, com responsabilidade social, entende que deve ser controlado o aumento da despesa, sem se prejudicarem \u2014 antes pelo contr\u00e1rio \u2014 os estratos sociais pobres, exclu\u00eddos ou atingidos por outros graves problemas que justificam financimento p\u00fablico.<\/p>\n<p>3. O ilustre fiscalista (e antigo ministro das finan\u00e7as de um governo socialista), Dr. Medina Carreira, \u00e9 uma das individualidades que, mais lucidamente, vem chamando a aten\u00e7\u00e3o para a gravidade do endividamento excessivo. No seu entendimento, imp\u00f5e-se controlar a despesa, reestrutur\u00e1-la, aumentar a receita e n\u00e3o prejudicar os referidos estratos sociais desfavorecidos.<\/p>\n<p>Em artigo publicado recentemente (&#8220;Di\u00e1rio Econ\u00f3mico&#8221; de 25 de Fevereiro) afirma que, ao longo dos \u00faltimos quarenta anos, &#8220;a taxa m\u00e9dia e anual de expans\u00e3o do produto interno bruto situou-se nos 4,5 por cento, a dos impostos nos 6,5 e a das despesas p\u00fablicas totais nos 7,5 por cento. Isto \u00e9, a riqueza criada cresceu 6 vezes, os impostos 12 vezes e a despesa p\u00fablica total 18 vezes&#8221;.<\/p>\n<p>Aumentando as despesas mais do que a produ\u00e7\u00e3o, qual ser\u00e1 o resultado? \u2014 Segundo este autor, caminha-se para uma situa\u00e7\u00e3o insustent\u00e1vel, se os pressupostos n\u00e3o forem alterados.<\/p>\n<p>4. A Confer\u00eancia Episcopal Portuguesa, na sua Carta Pastoral, de 15 de Setembro \u00faltimo, tamb\u00e9m j\u00e1 alertou para este grav\u00edssimo problema. A\u00ed afirma: &#8220;a espiral de despesa a que se tem assistido nas \u00faltimas d\u00e9cadas manifesta uma cultura de despesismo e facilidade, altamente lesiva do bem comum dos cidad\u00e3os.<\/p>\n<p>&#8220;A confian\u00e7a na economia passa pelo equil\u00edbrio das contas p\u00fablicas. Tal tarefa, espec\u00edfica do Estado, exige a participa\u00e7\u00e3o de todos os cidad\u00e3os&#8221; (&#8230;) (n\u00ba 22).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quest\u00f5es sociais<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61],"tags":[],"class_list":["post-16105","post","type-post","status-publish","format-standard","hentry","category-actualidade"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/16105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=16105"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/16105\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=16105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=16105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=16105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}