{"id":17694,"date":"2011-07-13T09:24:00","date_gmt":"2011-07-13T09:24:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=17694"},"modified":"2011-07-13T09:24:00","modified_gmt":"2011-07-13T09:24:00","slug":"as-pessoas-precisam-de-estar-conversar-e-partilhar-com-o-padre","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/as-pessoas-precisam-de-estar-conversar-e-partilhar-com-o-padre\/","title":{"rendered":"&#8220;As pessoas precisam de estar, conversar e partilhar com o padre&#8221;"},"content":{"rendered":"<p>P.e Jo\u00e3o Paulo Sarabando Marques, 49 anos, \u00e9 p\u00e1roco de Macinhata e Valongo do Vouga. Comemorou no dia 6 de Julho 25 anos de ordena\u00e7\u00e3o presbiteral. O dia foi assinalado por uma celebra\u00e7\u00e3o em Macinhata do Vouga. No domingo, 10 de Julho, ambas as comunidades celebraram as bodas de prata sacerdotais em Valongo do Vouga. Entrevista conduzida por Jorge Pires Ferreira.<\/p>\n<p>CORREIO DO VOUGA &#8211; Como est\u00e1 a viver estas comemora\u00e7\u00f5es, que tiveram ontem [entrevista realizada no dia 7 de Julho] um momento muito significativo com a celebra\u00e7\u00e3o da Eucaristia em Macinhata do Vouga (ver p\u00e1gina 5)?<\/p>\n<p>JO\u00c3O PAULO SARABANDO MARQUES &#8211; N\u00e3o sou muito de datas nem de celebra\u00e7\u00f5es. Esque\u00e7o-me do meu dia de anos\u2026 Mas penso que tem algum significado assinalar este momento. Parece-me que pode ser testemunho para os mais novos, dado que para mim faz todo o sentido ser padre. Sou muito feliz como padre e como pessoa. De algum modo isso pode servir de incentivo para outros. <\/p>\n<p>Na celebra\u00e7\u00e3o de ontem, al\u00e9m de di\u00e1conos, padres e leigos, estiveram tr\u00eas bispos: D. Ant\u00f3nio Francisco, D. Ant\u00f3nio Marcelino (que presidiu, a pedido de D. Ant\u00f3nio Francisco), e D. Ant\u00f3nio dos Santos. Surpreendeu-o?<\/p>\n<p>N\u00e3o porque fazia sentido. De algum modo, quem me acompanhou mais, ao longo destes anos, foi D. Ant\u00f3nio Marcelino, embora eu tivesse sido ordenado por D. Manuel de Almeida Trindade, que, como disse na celebra\u00e7\u00e3o, \u00e9 o meu pai na f\u00e9. Foi um homem que me marcou muito. <\/p>\n<p>Foi o \u00faltimo padre da Diocese de Aveiro ordenado por D. Manuel (1918 &#8211; 2008)?<\/p>\n<p>N\u00e3o tenho bem a certeza. Esteve o D. Ant\u00f3nio Marcelino, que na maior parte deste tempo foi quem me acompanhou, quem me incentivou, quem me abriu perspectivas e empurrou para muitas das coisas que fui fazendo. Esteve D. Ant\u00f3nio Francisco, Bispo da Diocese. \u00c9 o meu bispo. E o D. Ant\u00f3nio dos Santos, que \u00e9 da minha terra. Fazia todo o sentido que o convidasse e eu sei que ele teve muito gosto em estar. Ontem [6 de Julho] brinquei na celebra\u00e7\u00e3o dizendo que D. Ant\u00f3nio dos Santos foi baptizado na par\u00f3quia de Vagos porque a de Santo Ant\u00f3nio n\u00e3o existia na altura. Sempre que ele me encontrava, dizia: \u201cTu lembra-te que fomos baptizados na mesma pia\u201d. H\u00e1 uma afinidade quase familiar. De resto, al\u00e9m da fam\u00edlia pr\u00f3xima, n\u00e3o convidei mais ningu\u00e9m. Mas disse \u00e0s pessoas que ia celebrar porque a minha fam\u00edlia, neste momento, s\u00e3o as pessoas com quem estou a trabalhar.<\/p>\n<p>Neste momento est\u00e1 nas par\u00f3quias de Macinhata e Valongo do Vouga, mas ao longo do seu trabalho, passou por quase todo o arciprestado de \u00c1gueda\u2026<\/p>\n<p>Fui ordenado quando j\u00e1 estava em \u00cdlhavo a trabalhar como di\u00e1cono. Fui ordenado no Santu\u00e1rio de Vagos.<\/p>\n<p>Porqu\u00ea em Vagos, quando imediatamente antes e depois as ordena\u00e7\u00f5es foram sempre na S\u00e9?<\/p>\n<p>Eu tinha trabalhado no Secretariado Diocesano da Pastoral Juvenil. Nesse dia (6 de Julho de 1986), a malta jovem estava em Vagos, havia l\u00e1 um grande encontro, pelo que a ordena\u00e7\u00e3o foi aprazada para esse local e dia. O Santu\u00e1rio faz todo o sentido para mim, que sou de Vagos. As pessoas dali t\u00eam uma rela\u00e7\u00e3o muito pr\u00f3xima com o santu\u00e1rio. Os meus pais casaram l\u00e1. Havia e ainda h\u00e1 o costume de quando as m\u00e3es d\u00e3o \u00e0 luz irem l\u00e1 apresentar os filhos. Tamb\u00e9m l\u00e1 fui apresentado pela minha m\u00e3e.<\/p>\n<p>De \u00cdlhavo, ap\u00f3s tr\u00eas ou quatro anos, fui para \u00c1gueda, onde estive um ano. Depois, D. Ant\u00f3nio Marcelino desafiou-me a ir para Recard\u00e3es, onde havia bolsas de pobreza muito graves, por causa das cer\u00e2micas de barro vermelho, incluindo prostitui\u00e7\u00e3o infantil. Fiquei tamb\u00e9m com Castanheira do Vouga e dava aulas na Escola Secund\u00e1ria Marques de Castilho. Entretanto, fiquei com Barr\u00f4, por doen\u00e7a do P.e Jo\u00e3o Paulo Capela, e a seguir com Espinhel, devido \u00e0 doen\u00e7a do P.e Manuel Ferreira. Mais tarde, fiquei com Valongo. Entretanto, j\u00e1 tinha deixado Barr\u00f4 e Espinhel. Depois adoeceu o P.e Augusto e eu fiquei com Macinhata. Agora estou com a parte norte do arciprestado de \u00c1gueda.<\/p>\n<p>Referiu a pobreza. Para si, o lado mais social da pastoral sempre foi importante, tendo estado na origem do Centro Social e Paroquial de Recard\u00e3es\u2026<\/p>\n<p>Nasceu para dar resposta \u00e0s bolsas de pobreza. N\u00e3o faz sentido que a gente celebre e reze se isso n\u00e3o tem consequ\u00eancia na vida das pessoas. E a vida das pessoas come\u00e7a pelo comer, pela dignidade humana \u2013 coisas que s\u00e3o b\u00e1sicas. A minha inclina\u00e7\u00e3o para esse tipo de coisas mant\u00e9m-se. Em Recard\u00e3es, a obra tornou-se gigantesca por causa das circunst\u00e2ncias. H\u00e1 momentos em que as coisas funcionam. Naquele caso funcionou. A transforma\u00e7\u00e3o foi de facto muito grande. Na altura, abarc\u00e1mos Recard\u00e3es, Barr\u00f4, Aguada e come\u00e7amos a transportar crian\u00e7as e m\u00e3es para dar forma\u00e7\u00e3o, para que pudessem sair da situa\u00e7\u00e3o de pobreza em que estavam. Nunca tive da interven\u00e7\u00e3o social uma no\u00e7\u00e3o assistencialista. Na linha da doutrina social da Igreja, n\u00f3s existimos para promover e n\u00e3o para assistir. O trabalho que n\u00e3o for feito na linha da promo\u00e7\u00e3o \u00e9 trabalho deitado ao lixo.<\/p>\n<p>Hoje os problemas s\u00e3o outros. H\u00e1 pobreza nas suas actuais par\u00f3quias?<\/p>\n<p>\u00c9 muito complicado, sobretudo em Valongo. Macinhata tem umas situa\u00e7\u00f5es de droga, de fam\u00edlias desestruturadas, mas s\u00e3o ilhas. Em Valongo, o problema \u00e9 n\u00e3o haver emprego. H\u00e1 muitas pessoas em situa\u00e7\u00e3o prec\u00e1ria. Os mil e muitos postos de trabalho que havia desapareceram devido a fal\u00eancias. As empresas que deram \u00e2nimo \u00e0 freguesia desapareceram. As pessoas subsistem com a pequena horta, os animais que criam em casa. V\u00e3o vivendo, mas n\u00e3o se produz riqueza. A par\u00f3quia \u00e9 pobre. Quando assumi Valongo, pareceu necess\u00e1rio intervir ao n\u00edvel das fam\u00edlias e cri\u00e1mos em parceria com a Seguran\u00e7a Social um servi\u00e7o de interven\u00e7\u00e3o comunit\u00e1ria, que mantemos com t\u00e9cnicas e a boa vontade do voluntariado. O servi\u00e7o acompanha perto de 150 fam\u00edlias nas duas par\u00f3quias, ajudando a aceder aos direitos b\u00e1sicos, ao rendimento m\u00ednimo e outros apoios. Fornece alimentos em parceria com o Banco Alimentar, d\u00e1 vestu\u00e1rio, procura emprego, d\u00e1 forma\u00e7\u00e3o, sobretudo \u00e0s m\u00e3es, para saberem funcionar com a economia dom\u00e9stica, por exemplo. A m\u00e3e \u00e9 a estrutura da casa.<\/p>\n<p>O P.e Jo\u00e3o Paulo gosta de dar protagonismos aos leigos. D\u00e1 liberdade e poder para fazerem o que devem fazer. \u00c9 uma op\u00e7\u00e3o consciente?<\/p>\n<p>\u00c9 sobretudo uma op\u00e7\u00e3o de vida crist\u00e3. Do Conc\u00edlio para c\u00e1, j\u00e1 toda a gente deve ter percebido que n\u00f3s somos todos povo de Deus. N\u00e3o h\u00e1 castas. Costumo dizer \u00e0s pessoas: \u201cEu s\u00f3 sou o padre\u201d. Ou seja, a Igreja n\u00e3o come\u00e7a nem termina em mim. Eu fa\u00e7o parte do povo de Deus e tenho fun\u00e7\u00f5es espec\u00edficas. Por princ\u00edpio, sou eu que presido \u00e0 Eucaristia e a outros sacramentos, mas n\u00e3o tenho que ser eu a tomar conta da catequese ou da caridade. N\u00e3o sou eu que tenho de tomar conta da liturgia. Aqueles que fazem parte da comunidade t\u00eam responsabilidades como as minhas, sendo diferentes. O que temos de fazer? Entre n\u00f3s, coordenar o funcionamento e cada um assumir as responsabilidades na \u00e1rea que lhe compete. Quando o padre assume demasiado protagonismo, se o padre desparece, a Igreja desaparece. O padre leva a Igreja consigo. Costumo dizer que n\u00e3o sou padre de lado nenhum. Sou padre da Igreja de Jesus Cristo. E estou ao servi\u00e7o da Igreja, que n\u00e3o est\u00e1 s\u00f3 em Valongo ou Macinhata, mas est\u00e1 por a\u00ed, em todo o lado. Neste momento, estou p\u00e1roco destas terras. Mas n\u00e3o sou. Ser, sou da Igreja.<\/p>\n<p>Isso faz com que os leigos assumam as suas responsabilidades.<\/p>\n<p>Se o padre que me substituir for inteligente, s\u00f3 tem que entrar no carril e manter-se na sua posi\u00e7\u00e3o de padre. Tenho algum orgulho nessa capacidade. \u00c0s vezes at\u00e9 parece que empurro o trabalho para os outros. Mas, ultrapassando as capacidades das pessoas, as pessoas perdem dignidade e o lugar. E \u00e9 preciso que tenham lugar, vez e voz. Mas tamb\u00e9m n\u00e3o deixo que ningu\u00e9m ocupe o meu lugar. H\u00e1 situa\u00e7\u00f5es em que sinto que se fosse eu a fazer poderia fazer melhor e mais r\u00e1pido. Mas se n\u00e3o forem as pessoas a fazer, n\u00e3o \u00e9 amassado por elas. Eu sou fermento desta massa que \u00e9 a igreja que est\u00e1 aqui. Fermento sem massa, n\u00e3o faz p\u00e3o. P\u00e3o com muito fermento fica balofo. \u00c9 preciso conten\u00e7\u00e3o e ter a paci\u00eancia de dar \u00e0s pessoas o tempo necess\u00e1rio para que possam levar por diante os projectos a que nos propomos. N\u00e3o me tenho dado nada mal com isto, antes pelo contr\u00e1rio.<\/p>\n<p>Tamb\u00e9m \u00e9 conhecido pela sua frontalidade\u2026<\/p>\n<p>\u2026Alguns at\u00e9 lhe chamam m\u00e1 educa\u00e7\u00e3o. N\u00e3o sou muito de ter indiferen\u00e7as. As pessoas, perante mim, t\u00eam posi\u00e7\u00e3o. Ou gostam ou detestam. N\u00e3o h\u00e1 meios termos. De facto, tenho uma personalidade vincada. Sei muito bem o que quero. Procuro gastar muito tempo a amassar o que quero, para n\u00e3o ter explos\u00f5es moment\u00e2neas. Mas ao saber o que quero, procuro afirm\u00e1-lo com toda a clareza de que sou capaz. N\u00e3o tenho muito jeito para escolher palavras. N\u00e3o faz parte da minha idiossincrasia. Nem sempre tenho raz\u00e3o. A idade tamb\u00e9m traz isso. Eu j\u00e1 tive raz\u00e3o.<\/p>\n<p>J\u00e1 achou que tinha sempre raz\u00e3o?<\/p>\n<p>J\u00e1. Agora nem por isso. E j\u00e1 me deslumbro com a raz\u00e3o dos outros, que \u00e9 uma coisa que s\u00f3 se aprende com a idade. Por mais que queiramos, um homenzinho novo n\u00e3o \u00e9 capaz de apreciar a raz\u00e3o dos outros. Mas eu j\u00e1 sou.<\/p>\n<p>O que mais aprendeu com a idade?<\/p>\n<p>Alguma maturidade interior e exterior. H\u00e1 adolescentes com 50 anos, se nunca tiveram vontade de crescer. Se eu sou um bocado crian\u00e7a e adolescente nalgumas coisas? Sou. Mas sou por op\u00e7\u00e3o, porque se deve manter esse lado em algumas coisas. Mas a minha forma de olhar o mundo e o que est\u00e1 por detr\u00e1s das coisas mudou. Tenho a no\u00e7\u00e3o clara de que consegui adquirir isso e tenho de dar gra\u00e7as a Deus pela diversidade e riqueza da vida que tenho tido. Experimentei situa\u00e7\u00f5es muito diferentes, contactei com muitas pessoas. Conheci o mundo desde muito novo. Digo aos pais que deixem os filhos viajar\u2026<\/p>\n<p>Tamb\u00e9m viajou quando era novo?<\/p>\n<p>Comecei a sair de Portugal e a viajar pela Europa muito novo, \u00e0 minha custa, quando era seminarista. Os meus pais pagavam o bilhete de inter-rail e o resto eu ganhava aqui e acol\u00e1 para ir andando, nas f\u00e9rias, que eram de tr\u00eas meses, uma imensid\u00e3o de tempo. S\u00f3 n\u00e3o fui \u00e0 R\u00fassia, mas fui a alguns pa\u00edses de Leste: Pol\u00f3nia, Checoslov\u00e1quia&#8230; Apanhei ma\u00e7\u00e3s na Esc\u00f3cia, lavei pratos no Luxemburgo, fiz vindimas no sul de Espanha. Ganhei a no\u00e7\u00e3o de que o mundo n\u00e3o \u00e9 bem a minha aldeia. \u00c9 um bocadinho maior. E aquilo que eu absolutizava podia ser relativizado. Se passo a fronteia para o lado de l\u00e1, ganho uma abertura para poder encarar a vida de outra maneira, para ir fundando as ra\u00edzes num espa\u00e7o maior. Uma \u00e1rvore que cresce num vaso \u00e9 sempre uma \u00e1rvore atrofiada.<\/p>\n<p>\u00c9 j\u00e1 um dos padres h\u00e1 mais tempo no arciprestado de \u00c1gueda. Como \u00e9 a rela\u00e7\u00e3o com os outros colegas do arciprestado?<\/p>\n<p>Para al\u00e9m de padres, somos amigos. Tenho muito orgulho nisso e \u00e9 importante que tamb\u00e9m demos testemunho por esse lado. \u00c0s vezes n\u00e3o h\u00e1 entre os padres entrosamento, di\u00e1logo, partilha e provoca\u00e7\u00e3o m\u00fatua. Aqui h\u00e1. Somos amigos, trabalhamos bem em conjunto. Somos muito diferentes, mas tamb\u00e9m passeamos, jantamos juntos na Quinta-feira Santa, fazemos a nossa ceia no Natal. As nossas reuni\u00f5es de clero arciprestal terminam sempre com um almo\u00e7o. Pode n\u00e3o ser muito, mas \u00e9 um momento em que estamos juntos, brincamos, \u00e0s vezes dizemos coisas s\u00e9rias e at\u00e9 saem iniciativas. Funcion\u00e1mos muit\u00edssimo bem. Gosto do ambiente do clero arciprestal.<\/p>\n<p>Como diz, \u201cest\u00e1\u201d p\u00e1roco de Macinhata e Valongo. Tem projectos para o futuro?<\/p>\n<p>N\u00e3o fa\u00e7o projectos. Melhor, os meus projectos s\u00e3o em fun\u00e7\u00e3o do trabalho que tenho actualmente. E a\u00ed tenho muitos. Quanto a dizer se quero isto ou se vou para acol\u00e1, nada. Isso depende pura e simplesmente do bispo e do di\u00e1logo que o bispo tiver comigo. Mantendo eu \u00e0 cabe\u00e7a a disponibilidade para tudo, desde que avaliado em di\u00e1logo. Se me pedirem uma coisa que eu ache que n\u00e3o sou capaz de fazer ou que n\u00e3o me faz feliz, tenho de dizer com clareza e n\u00e3o o aceito. Se me lan\u00e7arem um desafio novo de algo que acho que sou capaz de fazer, aceito.<\/p>\n<p>Come\u00e7ou por afirmar-se feliz como padre. A voca\u00e7\u00e3o sacerdotal \u00e9 importante para o mundo?<\/p>\n<p>Muito importante. Ali\u00e1s, se h\u00e1 algum problema no mundo de hoje, \u00e9 a falta de lideran\u00e7as. N\u00e3o s\u00f3 na Igreja, mas sobretudo na sociedade. Perdemos as grandes refer\u00eancias. A Europa \u00e9 um sonho de pessoas que tinham ideias claras. Mas hoje n\u00e3o temos lideran\u00e7as fortes. A Igreja precisa de lideran\u00e7a por parte dos que apesar de tudo ainda s\u00e3o rosto da Igreja. O padre \u00e9 rosto da Igreja. Se h\u00e1 algo que me preocupa \u00e9 o facto de estarmos assoberbados por trabalho e n\u00e3o termos tempo para as pessoas. Isso \u00e9 muito mau. As pessoas precisam de estar, conversar e partilhar com o padre. \u00c0s vezes \u00e9 mais dif\u00edcil encontrar o padre do que o presidente da c\u00e2mara. Uma vez, D. Ant\u00f3nio dos Santos disse-me: \u201cVou-te dizer quais s\u00e3o os tr\u00eas segredos para ser um bom p\u00e1roco\u201d \u2013 porque ele foi. \u00c9 raro encontrar um bispo que tenha passado por essa situa\u00e7\u00e3o. S\u00e3o mais de estufa, o que \u00e0s vezes mau. Quem comanda tropas tem de saber o que \u00e9 a tropa. Uma parte substancial de n\u00f3s somos p\u00e1rocos. E o D. Ant\u00f3nio dos Santos disse-me: \u201cPrimeiro, conhecer as pessoas. Segundo, conhecer muito bem as pessoas. Terceiro, conhecer muito bem as pessoas e dar-se bem com elas\u201d. Ao longo destes 25 anos percebi claramente isso. Quando se consegue estar pr\u00f3ximo, n\u00e3o s\u00f3 n\u00e3o se fala de cor, porque se leva para a celebra\u00e7\u00e3o aquilo que \u00e9 da vida, como temos a solidariedade delas. Sentem-se comprometidas connosco e com os nossos projectos. Tenho procurado cumprir isto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>P.e Jo\u00e3o Paulo Sarabando Marques, 49 anos, \u00e9 p\u00e1roco de Macinhata e Valongo do Vouga. Comemorou no dia 6 de Julho 25 anos de ordena\u00e7\u00e3o presbiteral. O dia foi assinalado por uma celebra\u00e7\u00e3o em Macinhata do Vouga. No domingo, 10 de Julho, ambas as comunidades celebraram as bodas de prata sacerdotais em Valongo do Vouga. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[57],"tags":[],"class_list":["post-17694","post","type-post","status-publish","format-standard","hentry","category-entrevista"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/17694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=17694"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/17694\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=17694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=17694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=17694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}