{"id":18088,"date":"2011-09-29T09:37:00","date_gmt":"2011-09-29T09:37:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=18088"},"modified":"2011-09-29T09:37:00","modified_gmt":"2011-09-29T09:37:00","slug":"mais-e-melhor-escutismo-para-um-maior-numero-de-jovens","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/mais-e-melhor-escutismo-para-um-maior-numero-de-jovens\/","title":{"rendered":"Mais e melhor escutismo para um maior n\u00famero de jovens"},"content":{"rendered":"<p>Manuel Santos, 53 anos, gestor e empres\u00e1rio, iniciou no domingo passado o terceiro mandato \u00e0 frente do Corpo Nacional de Escutas (CNE) na Regi\u00e3o de Aveiro. Nesta entrevista, o chefe  regional revela como deseja um escutismo de seriedade e alegria, alicer\u00e7ado na comunh\u00e3o com a Igreja, que conduza os jovens \u00e0 verdadeira felicidade, e informa que a t\u00e3o ansiada sede regional dever\u00e1 avan\u00e7ar antes do final do ano. Entrevista conduzida por Jorge Pires Ferreira.<\/p>\n<p>CORREIO DO VOUGA &#8211; Como est\u00e1 o esp\u00edrito escutista na Regi\u00e3o de Aveiro actualmente?<\/p>\n<p>MANUEL SANTOS &#8211; Percebo e sinto o escutismo como um movimento de crian\u00e7as e jovens que vivem e crescem em din\u00e2micas de valores que os pr\u00f3prios assumem como compromissos orientadores de vida. Quando tudo isto acontece em pleno, o movimento acontece e cria envolv\u00eancias de alegria, responsabilidade e solidariedade. E isto, felizmente, \u00e9 o dia-a-dia dos escuteiros da Regi\u00e3o de Aveiro [circunscri\u00e7\u00e3o escutista correspondente \u00e0 Diocese de Aveiro]. Cada vez assistimos a um maior empenhamento e rigor dos nossos dirigentes e isto traduz-se tamb\u00e9m em felicidade para os mais novos. O escutismo \u00e9 hoje uma marca s\u00e9ria na maioria das nossas comunidades e consegue criar a diferen\u00e7a pela afirma\u00e7\u00e3o dos valores que nos s\u00e3o mais queridos: delicadeza, car\u00e1cter, servi\u00e7o e o sentido de Deus que nos une na Igreja que nos acolhe. Temos algumas mas pequenas excep\u00e7\u00f5es onde nem tudo funciona como todos desejar\u00edamos. Tamb\u00e9m para isso, a m\u00e3o amiga mas exigente da Junta Regional quer indicar e trilhar os caminhos de verdade que hoje os nossos jovens nos exigem com todo o seu direito.<\/p>\n<p>Inicia o seu terceiro mandato. Em jeito de balan\u00e7o, como avalia os \u00faltimos tr\u00eas anos (segundo mandato)?<\/p>\n<p>Nos \u00faltimos anos dez a vinte anos \u2013 em cuja condu\u00e7\u00e3o dos destinos escutistas eu colaborei noutras fun\u00e7\u00f5es que n\u00e3o a de chefe regional \u2013, sempre temos sentido um crescer na qualidade. E isto deve-se a uma maior sintonia de valores apreendidos e assumidos pelas equipas regionais, pela maioria dos formadores e pela grande maioria dos chefes de agrupamento \u2013 s\u00e3o eles os fi\u00e9is condutores da forma de interpretar o escutismo nas suas comunidades.<\/p>\n<p>O \u00faltimo mandato ficou marcado pelo acampamento regional (Acareg), realizado em 2009 nas acolhedoras terras de Vagos. Um acampamento, para al\u00e9m da grande festa da comunh\u00e3o entre todos os escuteiros, comunidade que nos acolhe e familiares e amigos que nos visitam, \u00e9 sempre o melhor espa\u00e7o de avalia\u00e7\u00e3o para o trabalho desenvolvido. Por tudo o que aconteceu, verificamos que os nossos escuteiros s\u00e3o felizes, crescem no seu progresso e gostam mesmo muito do escutismo.<\/p>\n<p>Outro ponto forte, que n\u00e3o tem apenas a ver com o Escutismo, foi a participa\u00e7\u00e3o massiva no Dia da Igreja Diocesana de 2010. Gra\u00e7as a Deus que a nossa Diocese soube encontrar uma forma nova de nos envolver na comunh\u00e3o que precisamos todos de construir em Igreja, quer para n\u00f3s quer para o exterior, que precisa de ver nos crist\u00e3os sinais vis\u00edveis de alegria e esperan\u00e7a.<\/p>\n<p>A funda\u00e7\u00e3o de um novo agrupamento do CNE em S\u00e3o Louren\u00e7o do Bairro foi e continua a ser um sinal de alegria e de juventude em Igreja na Bairrada profunda e genu\u00edna.<\/p>\n<p>E quais foram os pontos fracos?<\/p>\n<p>Tamb\u00e9m os temos. N\u00e3o cri\u00e1mos mais agrupamentos. Embora dependa tamb\u00e9m de outras entidades e das estruturas da Igreja local, assumimos como culpa nossa o n\u00e3o sermos capazes de debelar alguns obst\u00e1culos que n\u00e3o permitem a centenas de crian\u00e7as e jovens da nossa diocese conhecer e viver esta alegria de crescer em Jesus pelo escutismo em Igreja.<\/p>\n<p>N\u00e3o realizarmos o S\u00e3o Jorge [encontro anual no fim de Abril] foi outra falha. N\u00e3o foi por uma quest\u00e3o casual, m\u00e1 vontade ou indisponibilidade para o servi\u00e7o. Nada disto. N\u00e3o fazemos as nossas actividades apenas por fazer, para cumprir planos ou meras festinhas de calend\u00e1rio. Todas as actividades t\u00eam de ter sempre o maior sentido pedag\u00f3gico. Quando n\u00e3o existem condi\u00e7\u00f5es da comunidade local que nos acolhe, do agrupamento ou da Igreja local, optamos por n\u00e3o realizar. Aconteceu ainda aquilo que considero mais preocupante. Embora focos isolados, assistimos \u00e0quilo a que poderei chamar uma falta de sintonia de valores em entidades que considero os guardi\u00f5es dos mesmos. Um educador do CNE n\u00e3o pode, nunca, estar em situa\u00e7\u00f5es d\u00fabias perante a sociedade e muito menos perante a Igreja. Se assumimos em pleno o projecto de baptizados em Cristo, a nossa lei de escuteiro e os nossos princ\u00edpios obrigam-nos a ser exemplo claro de vida. Se n\u00e3o formos esta fonte l\u00edmpida para os jovens, corremos o perigo de mergulharmos no lodo falso da hipocrisia que j\u00e1 vai atolando algumas franjas da nossa sociedade. O escutismo tem tudo para n\u00e3o virar barcos para o loda\u00e7al. Apesar de alguns \u201cimportantes\u201d nos quererem induzir pelo caminho mais perto, n\u00e3o \u00e9 por a\u00ed que vamos. E o nosso Bispo quer-nos por caminhos de vida e na \u00e1gua l\u00edmpida da verdade.<\/p>\n<p>Por \u00faltimo, o ponto fraco da burocracia e tecnocracia que envolveram o projecto da nossa sede. Faltou da parte das entidades envolvidas ou dos seus profissionais algum respeito pela forma volunt\u00e1ria e gratuita com que nos empenhamos nestes projectos para bem das pr\u00f3prias comunidades. Houve desgaste, um constante pedir de pap\u00e9is, alguns repetidos, atrasos sucessivos que mais pareciam for\u00e7ar ao desinteresse e abandono do projecto. Felizmente, mesmo ao terminar o mandato, ficou tudo aprovado pelas entidades competentes. Assim, quase poder\u00edamos considerar um ponto forte do \u00faltimo mandato.<\/p>\n<p>Para 2011-14, quais s\u00e3o os maiores objectivos?<\/p>\n<p>Mais e melhor escutismo para um maior n\u00famero de jovens. Este \u00e9 ser\u00e1 sempre o nosso objectivo primordial. Todo o resto \u00e9 uma soma de outros objectivos que bem integrados numa estrat\u00e9gia solida contribuir\u00e3o para a prossecu\u00e7\u00e3o do principal objectivo. Assim, mais e melhor forma\u00e7\u00e3o de adultos, a abertura de novos agrupamentos, o Acareg  e a sede regional s\u00e3o aqueles objectivos mais vis\u00edveis e com maior peso no pr\u00f3ximo tri\u00e9nio.<\/p>\n<p>Voltando \u00e0 sede regional, como est\u00e1 ent\u00e3o o processo? H\u00e1 data prevista para o in\u00edcio da constru\u00e7\u00e3o? Quando vai custar? <\/p>\n<p>Fruto da tenacidade da nossa \u201cPatrulha da Sede\u201d, cujo guia \u00e9 o chefe Norberto Correia, conseguimos finalmente a aprova\u00e7\u00e3o do projecto. N\u00e3o digo o n\u00famero de anos envolvidos. \u00c9 dram\u00e1tico este tipo de atrasos que a todos prejudica e desmotiva. Felizmente, n\u00e3o nos conseguiram desmotivar e j\u00e1 procuramos or\u00e7amentos em empreiteiros que queiram construir a sede. Vai ser constru\u00edda entre o Mercado de Santiago e a Urbaniza\u00e7\u00e3o Vila Jovem, na zona que julgo denominada Santiago ou Eucalipto. Estamos a trabalhar para dar in\u00edcio \u00e0s obras ainda este ano. Prevemos um custo que deve ultrapassar o meio milh\u00e3o de euros e temos parte desse dinheiro. Apesar das dificuldades, saberemos encontrar em toda a regi\u00e3o os apoios amigos para levar este edif\u00edcio at\u00e9 \u00e0 sua conclus\u00e3o.<\/p>\n<p>Ser\u00e1 um fracasso desta chefia se em 2014 as obras n\u00e3o estiverem bem avan\u00e7adas?<\/p>\n<p>Sim, ser\u00e1 um fracasso desta chefia, mas tamb\u00e9m de todos os que connosco trabalham de perto neste projecto. Mas at\u00e9 por tudo aquilo que eles fazem e porque d\u00e3o sempre o seu melhor, o fracasso n\u00e3o vai acontecer. N\u00e3o avan\u00e7o datas para n\u00e3o cair em estrat\u00e9gias pol\u00edticas que por vezes s\u00e3o duvidosas. E n\u00f3s at\u00e9 j\u00e1 fomos eleitos! Nem tudo depende de n\u00f3s, podem surgir problemas de implanta\u00e7\u00e3o que gastam algum tempo, mas estamos preparados para avan\u00e7ar em tempos aceit\u00e1veis. Como diz o outro: fracasso \u00e9 coisa que n\u00e3o nos assiste.<\/p>\n<p>Acampamento regional. Onde e quanto vai ser?<\/p>\n<p>O 18.\u00ba Acareg vai acontecer em 2014. Ainda n\u00e3o escolhemos o local, mas come\u00e7aremos a estudar os poss\u00edveis e tamb\u00e9m esperamos a generosidade amiga e espont\u00e2nea de algum munic\u00edpio da nossa Regi\u00e3o que nos queira receber da forma amiga e solid\u00e1ria como o munic\u00edpio de Vagos nos soube acolher no \u00faltimo acampamento regional.<\/p>\n<p>Na proposta de plano de ac\u00e7\u00e3o, a Junta eleita afirmava que queria dotar o Campo de S\u00e3o Jacinto, agora sob a al\u00e7ada da Regi\u00e3o de Aveiro, de gest\u00e3o profissional. O que se pretende em concreto? O campo \u00e9 uma fonte de receitas ou de despesas para Aveiro?<\/p>\n<p>Descobrimos no Campo de S\u00e3o Jacinto um potencial muito importante para o CNE, para a comunidade local e para a nossa regi\u00e3o, designadamente o concelho de Aveiro. Temos milhares de jovens de todas as partes do mundo que v\u00eam a S\u00e3o Jacinto e a Aveiro viver as suas actividades, mas tamb\u00e9m partilhar e conhecer muito da vida local. As nossas entidades respons\u00e1veis locais ainda n\u00e3o perceberam o potencial que isto pode significar para as cidades e vilas envolventes. Um escuteiro feliz partilha com outros escuteiros e com a sua fam\u00edlia. E n\u00f3s temos tanto para dar. Do mar, pela ria, \u00e0s serras. Do peixe e marisco \u00e0 vitela e ao leit\u00e3o. E temos tudo isto num raio de duas dezenas de quil\u00f3metros. Cabe-nos a n\u00f3s, como cidad\u00e3os respons\u00e1veis, sensibilizar as entidades para todo este potencial de partilha, de conhecimento, mas tamb\u00e9m de mercado, de que todos hoje precisamos. At\u00e9 hoje, apesar de alguns esfor\u00e7os de comunica\u00e7\u00e3o, ainda pouco ou nada conseguimos. Da nossa parte, o Campo de S\u00e3o Jacinto j\u00e1 tem um or\u00e7amento interessante. Ao contr\u00e1rio de gest\u00f5es anteriores, geram-se agora algumas mais-valias financeiras. Quando trabalhamos e nos apercebemos de todo este potencial quer humano quer econ\u00f3mico temos de saber encontrar formas de gest\u00e3o que assegurem maior rigor em tudo aquilo que fazemos. Esse rigor dever\u00e1 resultar num maior valor que  permita a gest\u00e3o profissional e assim a integra\u00e7\u00e3o de mais pessoas ao servi\u00e7o no campo. Acredito que estamos em condi\u00e7\u00f5es de fazer este estudo e arrancar para um projecto de maior qualidade e notoriedade para S\u00e3o Jacinto.<\/p>\n<p>Quantos agrupamentos h\u00e1 actualmente? Quantos escuteiros na totalidade?<\/p>\n<p> Temos hoje 44 agrupamentos e, como j\u00e1 referi nos nossos pontos fracos, n\u00e3o temos agrupamentos em forma\u00e7\u00e3o. O CNE nesta Regi\u00e3o de Aveiro e segundo as indica\u00e7\u00f5es dos \u00faltimos censos tem 2536 escuteiros e 550 dirigentes, perfazendo um efectivo de 3086 associados.<\/p>\n<p>O CNE \u00e9 um movimento juvenil, mas na proposta de plano de ac\u00e7\u00e3o foca-se mais a forma\u00e7\u00e3o de adultos, dirigentes. \u00c9 a\u00ed que se joga a sa\u00fade do movimento?<\/p>\n<p>Com toda a certeza. Apesar do Escutismo ser um \u201cjogo\u201d de jovens, o adulto \u00e9 pe\u00e7a importante neste jogo. O adulto educador\/evangelizador tem de ter uma carga que por si conduz as crian\u00e7as e os jovens a projectos de felicidade. Tem de ser aquele que sem falar muito, na serenidade do seu exemplo, transmite mais do que aquilo que se transmite em horas de teorias insipidas. Hoje trabalhamos para uma gera\u00e7\u00e3o de jovens do melhor que temos, inteligentes, generosos e amigos e, felizmente, cada vez mais bem formados em v\u00e1rias \u00e1reas e tamb\u00e9m na vertente acad\u00e9mica. Eles, no escutismo, n\u00e3o precisam de \u201cprofessores\u201d, precisam de pessoas s\u00e9rias, amigas e competentes. A seriedade e amizade, o adulto j\u00e1 as tem de ter e perceber. Costumo dizer que n\u00f3s, no CNE, formamos, n\u00e3o transformamos. Quanto \u00e0 compet\u00eancia e a capacidade pedag\u00f3gica para perceber as novas metodologias e outras maneiras de partilhar este projecto de Baden-Powell, isso acontece e partilha-se com muito rigor nos v\u00e1rios cursos e jornadas de forma\u00e7\u00e3o que o CNE oferece.<\/p>\n<p>Para lema do tri\u00e9nio escolheram parte do Salmo 62. Pretendem reafirmar a matriz cat\u00f3lica do escutismo? Porqu\u00ea? Est\u00e1 em eros\u00e3o?<\/p>\n<p>Tudo na vida est\u00e1 sujeito a eros\u00e3o. At\u00e9 com a pedra mais preciosa, apesar da maior resist\u00eancia, h\u00e1 formas de eros\u00e3o que lhe ocultam o brilho. Hoje, os factores de eros\u00e3o na nossa sociedade s\u00e3o muitos e se n\u00e3o existir um cuidado continuado na protec\u00e7\u00e3o e defesa daquilo que nos \u00e9 querido e que se torna ess\u00eancia na constru\u00e7\u00e3o da felicidade das pessoas, tudo pode deixar de brilhar. Hoje a cultura do \u201ceu\u201d e do imediato, o facilitismo, a aus\u00eancia do pensar mais al\u00e9m, a \u201cvergonha\u201d ou a falta dela instalada em algumas cadeiras do \u201cpoder\u201d e a cultura da irresponsabilidade afastam as pessoas do sentido da verdade. Hoje, para uma certa camada geracional, que n\u00e3o digo os jovens, \u00e9 dif\u00edcil falar de \u201cJesus\u201d Homem Novo, desconcertante para todos estes gastos no seu destino fatalmente constru\u00eddo. Por isso o escutismo tem este dever em Igreja, devido \u00e0 sua verticalidade que assume pela pr\u00f3pria lei, de sempre perceber que no seu m\u00e9todo tem como fim de pista a felicidade. E para n\u00f3s, escuteiros cat\u00f3licos, a Felicidade \u00e9 Deus. \u201cS\u00f3 Ele \u00e9 o meu  ref\u00fagio, a minha salva\u00e7\u00e3o, e a minha fortaleza\u201d. <\/p>\n<p>Tamb\u00e9m integrados na din\u00e2mica do Plano da nossa Diocese, assumimos do Salmo 62: \u201cDeus, a \u00fanica esperan\u00e7a\u201d.<\/p>\n<p>Nestes tempos conturbados, o Escutismo em terras de Santa Joana Princesa vai ser, quer ser, um grito e um testemunho de esperan\u00e7a que traga os s\u00e9rios e de boa vontade a um sentido de vida, se calhar n\u00e3o t\u00e3o rico, nem esbanjador, porque como diz o nosso 9.\u00ba artigo da lei: \u201cO escuta \u00e9 s\u00f3brio, econ\u00f3mico e respeitador do bem alheio\u201d. Mais despojados, vai ser mais f\u00e1cil juntos encontrarmos a felicidade que perseguimos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Manuel Santos, 53 anos, gestor e empres\u00e1rio, iniciou no domingo passado o terceiro mandato \u00e0 frente do Corpo Nacional de Escutas (CNE) na Regi\u00e3o de Aveiro. Nesta entrevista, o chefe regional revela como deseja um escutismo de seriedade e alegria, alicer\u00e7ado na comunh\u00e3o com a Igreja, que conduza os jovens \u00e0 verdadeira felicidade, e informa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[57],"tags":[],"class_list":["post-18088","post","type-post","status-publish","format-standard","hentry","category-entrevista"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/18088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=18088"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/18088\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=18088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=18088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=18088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}