{"id":18095,"date":"2011-09-29T09:44:00","date_gmt":"2011-09-29T09:44:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=18095"},"modified":"2011-09-29T09:44:00","modified_gmt":"2011-09-29T09:44:00","slug":"papa-regressa-ao-vaticano-confiante-no-futuro-do-cristianismo-na-alemanha","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/papa-regressa-ao-vaticano-confiante-no-futuro-do-cristianismo-na-alemanha\/","title":{"rendered":"Papa regressa ao Vaticano confiante no &#8220;futuro do cristianismo&#8221; na Alemanha"},"content":{"rendered":"<p>Viagem de quatro dias marcada por apelos \u00e0 uni\u00e3o entre cat\u00f3licos e ao respeito pela liberdade religiosa na Europa p\u00f3s-Muro de Berlim.<\/p>\n<p>Bento XVI despediu-se da Alemanha, no domingo, 25, ap\u00f3s uma viagem de quatro dias, a primeira com estatuto de visita de Estado, marcada por v\u00e1rios apelos \u00e0 uni\u00e3o entre cat\u00f3licos e ao respeito pela dimens\u00e3o p\u00fablica da religi\u00e3o.<\/p>\n<p>\u201cRecordo com prazer as celebra\u00e7\u00f5es lit\u00fargicas comuns, a alegria de ouvir juntos a Palavra de Deus e de rezar unidos \u2013 e isto sobretudo nas partes do pa\u00eds onde, durante dec\u00e9nios, se tentou remover a religi\u00e3o da vida das pessoas. Isto enche-me de confian\u00e7a quanto ao futuro do cristianismo na Alemanha\u201d, disse o Papa no seu discurso final, proferido no aeroporto de Lahr, 50 quil\u00f3metros a norte de Friburgo, no sudoeste alem\u00e3o.<\/p>\n<p>Diante do presidente germ\u00e2nico, Christian Wulff, Bento XVI passou em revista a terceira viagem \u00e0 Alemanha, 21.\u00aa ao estrangeiro (16.\u00aa na Europa), que se iniciou na quinta-feira e contou com passagens por Berlim, Erfurt, Etzelsbach e Friburgo, tendo como lema \u201cOnde h\u00e1 Deus, h\u00e1 futuro\u201d.<\/p>\n<p>Uma visita que incluiu o primeiro discurso alguma vez proferida por um Papa no parlamento federal alem\u00e3o, o Bundestag, no qual apelou \u00e0 redescoberta do patrim\u00f3nio crist\u00e3o da Europa para defender o futuro do \u201cEstado de Direito\u201d no Velho Continente.<\/p>\n<p>V\u00e1rias interven\u00e7\u00f5es de Bento XVI visaram a tend\u00eancia de remeter a religi\u00e3o para o espa\u00e7o privado ou mesmo de a \u201cmarginalizar\u201d, preocupa\u00e7\u00e3o que partilhou com representantes mu\u00e7ulmanos e, antes, com l\u00edderes judaicos, junto dos quais lembrou as \u201chorr\u00edveis imagens que chegaram dos campos de concentra\u00e7\u00e3o\u201d nazi e o Holocausto.<\/p>\n<p>Ap\u00f3s a passagem pela capital germ\u00e2nica, o Papa entrou no territ\u00f3rio da antiga Rep\u00fablica Democr\u00e1tica Alem\u00e3, na qual homenageou a resist\u00eancia da f\u00e9 face \u00e0 ditadura nazi e ao regime comunista, que comparou a uma \u201cchuva \u00e1cida\u201d, sublinhando o papel dos cat\u00f3licos na queda do Muro de Berlim, em 1989.<\/p>\n<p>Na regi\u00e3o, em Erfurt, deu-se o encontro com membros da comunidade protestante, num antigo convento Agostinho em que viveu Martinho Lutero, um dos \u00abpais\u00bb da reforma do s\u00e9culo XVI.<\/p>\n<p>O Papa reafirmou dist\u00e2ncias quando se mostrou mais pr\u00f3ximo das Igrejas da Ortodoxia e disse aos luteranos que a viv\u00eancia da f\u00e9 n\u00e3o pode admitir qualquer \u201cadultera\u00e7\u00e3o\u201d para poder fazer face a um \u201cmundo secularizado\u201d.<\/p>\n<p>Nos discursos dirigidos aos cat\u00f3licos na Alemanha \u2013 que proporcionaram ao Papa v\u00e1rios banhos de multid\u00e3o \u2013, Bento XVI criticou os conflitos internos que afastam os cat\u00f3licos da sua liga\u00e7\u00e3o ao Vaticano e aos seus bispos, bem como a excessiva institucionaliza\u00e7\u00e3o das comunidades, defendendo a liberta\u00e7\u00e3o de qualquer \u201cfardo material e pol\u00edtico\u201d na Igreja para superar uma \u201ccrise de f\u00e9\u201d.<\/p>\n<p>Os \u201ctristes esc\u00e2ndalos\u201d de abusos sexuais de menores por membros do clero e em institui\u00e7\u00f5es eclesiais tamb\u00e9m mereceram a aten\u00e7\u00e3o do Papa, que recebeu um grupo de v\u00edtimas, ap\u00f3s ter admitido \u201ccompreender\u201d quem deixa a Igreja por se sentir \u201cescandalizado por estes crimes, que foram revelados nos \u00faltimos tempos\u201d. Um tempo dif\u00edcil para o qual Bento XVI pediu o apoio dos fi\u00e9is, declarando que \u201cpermanecer em Cristo\u201d significa \u201cpermanecer na Igreja\u201d.<\/p>\n<p>\u201cAgrade\u00e7o a todos por estes dias estupendos, por tantos encontros pessoais e pelos inumer\u00e1veis sinais de aten\u00e7\u00e3o e de estima que me manifestaram\u201d, disse o Papa, antes de regressar ao Vaticano, onde chegou esta noite ap\u00f3s mais de 2750 quil\u00f3metros percorridos em 84 horas e meia.<\/p>\n<p>Ag. Ecclesia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viagem de quatro dias marcada por apelos \u00e0 uni\u00e3o entre cat\u00f3licos e ao respeito pela liberdade religiosa na Europa p\u00f3s-Muro de Berlim. Bento XVI despediu-se da Alemanha, no domingo, 25, ap\u00f3s uma viagem de quatro dias, a primeira com estatuto de visita de Estado, marcada por v\u00e1rios apelos \u00e0 uni\u00e3o entre cat\u00f3licos e ao respeito [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"class_list":["post-18095","post","type-post","status-publish","format-standard","hentry","category-igreja-no-mundo"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/18095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=18095"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/18095\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=18095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=18095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=18095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}