{"id":18428,"date":"2011-11-09T09:31:00","date_gmt":"2011-11-09T09:31:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=18428"},"modified":"2011-11-09T09:31:00","modified_gmt":"2011-11-09T09:31:00","slug":"os-catolicos-conhecem-a-biblia","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/os-catolicos-conhecem-a-biblia\/","title":{"rendered":"Os cat\u00f3licos conhecem a B\u00edblia?"},"content":{"rendered":"<p>Painel <!--more--> Assun\u00e7\u00e3o Costa<\/p>\n<p>Directora do Secretariado Diocesano da Catequese de Inf\u00e2ncia e Adolesc\u00eancia. Orienta adultos que se preparam para o Baptismo<\/p>\n<p>Parece-me que n\u00e3o podemos dizer que desconhecem ou conhecem a B\u00edblia. A meu ver, est\u00e3o a caminhar com a B\u00edblia, na B\u00edblia. H\u00e1, de facto, uma descoberta que se est\u00e1 a fazer. H\u00e1 uma fome de Deus que se sente. Vejo pela minha experi\u00eancia, na caminhada de adultos para os sacramentos da inicia\u00e7\u00e3o crist\u00e3 [Baptismo, Confirma\u00e7\u00e3o, Eucaristia], que h\u00e1 um grande entusiasmo na descoberta da B\u00edblia, no descobrir Deus na sua Palavra, Jesus que d\u00e1 a vida por n\u00f3s e pelo qual &#8211; como uma jovem h\u00e1 pouco me dizia &#8211; \u00e9 bom que nos apaixonemos.<\/p>\n<p>O balan\u00e7o da forma\u00e7\u00e3o sobre a B\u00edblia que o Secretariado da Catequese est\u00e1 a promover \u00e9 muito positivo. Est\u00e3o 222 pessoas inscritas, catequistas e n\u00e3o catequistas. Ontem [3 de Novembro], numa noite de chuva terr\u00edvel, o sal\u00e3o do Semin\u00e1rio estava cheio. Fiquei de boca aberta ao ver muita gente molhada. Por alguma raz\u00e3o a B\u00edblia mexe c\u00e1 dentro.<\/p>\n<p>Ondina Matos<\/p>\n<p>Enfermeira. Directora do Secretariado Diocesano da Pastoral Juvenil e Vocacional<\/p>\n<p>Respondendo directamente, penso que n\u00e3o, de todo. Pelo que conhe\u00e7o, a come\u00e7ar pelos catequistas e animadores, a n\u00edvel paroquial e diocesano, h\u00e1 um grande desconhecimento, tanto da B\u00edblia como de outras \u00e1reas necess\u00e1rias para a ac\u00e7\u00e3o pastoral, da\u00ed que haja muitas pessoas e servi\u00e7os a motivar para a forma\u00e7\u00e3o. [O Secretariado da Pastoral Juvenil promove no pr\u00f3ximo s\u00e1bado um encontro que tem uma parte dedicada \u00e0 B\u00edblia].<\/p>\n<p>Sobretudo para conseguirmos ser testemunhas nos diversos contextos, \u00e9 importante ter conhecimentos b\u00edblicos e viver a Palavra Deus. Se eu estiver segura quanto \u00e0s bases a minha f\u00e9, n\u00e3o me fecho numa concha sem saber o que dizer quando sou interpelada. Ser crist\u00e3o tamb\u00e9m passa por saber argumentar quando somos questionados.<\/p>\n<p>Franclim Pacheco<\/p>\n<p>P\u00e1roco de Fermel\u00e3 e Canelas e professor. Doutorado em Ci\u00eancias B\u00edblicas<\/p>\n<p>De uma forma geral, estou convencido de que n\u00e3o. T\u00eam algumas hist\u00f3rias na cabe\u00e7a, leram qualquer coisa, mas conhecem pouco. Mas noto que da parte dos mais respons\u00e1veis, catequistas e outros, h\u00e1 vontade de querer saber mais. E surgem iniciativas nesse sentido. O curso que estou a dar sobre os Profetas, no Semin\u00e1rio de Aveiro [promovido pelo Secretariado da Catequese e ISCRA], \u00e9 uma delas. E com grande ades\u00e3o.<\/p>\n<p>A B\u00edblia, na tradi\u00e7\u00e3o cat\u00f3lica, era uma \u201ccoisa\u201d que passava ao lado. A Igreja desaconselhava a leitura da B\u00edblia e valorizava os dogmas.<\/p>\n<p>Quando se estuda a B\u00edblia, \u00e9 necess\u00e1rio procurar o sentido mais profundo dos textos. O risco de quem a estuda sem aprofundar \u00e9 pensar que \u201cs\u00e3o s\u00f3 historietas\u201d. \u00c9 preciso fazer este caminho ao ler o texto: \u201cDa forma como isto est\u00e1, vamos l\u00e1 ver o que quer dizer\u2026\u201d<\/p>\n<p>Fernando Cassola<\/p>\n<p>Programador inform\u00e1tico. Dirigente do CNE e colaborador da Diocese de Aveiro na \u00e1rea das tecnologias<\/p>\n<p>Penso que n\u00e3o conhecem muito, na medida em que a ideia que n\u00f3s, cat\u00f3licos, temos da B\u00edblia vem muito do que \u00e9 lido nas missas e, eventualmente, explicado nas homilias. Fora isso, os cat\u00f3licos, por natureza, n\u00e3o t\u00eam o h\u00e1bito de leitura e aprofundamento da Palavra de Deus atrav\u00e9s da B\u00edblia, contrariamente \u00e0s outras confiss\u00f5es crist\u00e3s.<\/p>\n<p>Perde, assim, a ac\u00e7\u00e3o pastoral na comunidade, devido \u00e0 falta de conhecimentos dos leigos, e a vida pessoal de cada crist\u00e3o. Os valores que os crist\u00e3os deveriam ter como pilar na vida quotidiana t\u00eam como fonte, por vezes, preceitos morais, costumes e tradi\u00e7\u00f5es que nem sempre bebem da Palavra de Deus.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Painel<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-18428","post","type-post","status-publish","format-standard","hentry","category-espaco-comum"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/18428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=18428"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/18428\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=18428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=18428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=18428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}