{"id":18429,"date":"2011-11-09T09:32:00","date_gmt":"2011-11-09T09:32:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=18429"},"modified":"2011-11-09T09:32:00","modified_gmt":"2011-11-09T09:32:00","slug":"repensar-a-pastoral-um-projecto-em-caminhada","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/repensar-a-pastoral-um-projecto-em-caminhada\/","title":{"rendered":"Repensar a pastoral, um projecto em caminhada"},"content":{"rendered":"<p>O Padre Manuel Moruj\u00e3o, secret\u00e1rio da Confer\u00eancia Episcopal Portuguesa, explica o percurso percorrido no projeto de \u00abRepensar a Pastoral da Igreja\u00bb, lan\u00e7ado em 2010, e quais os passos que se seguem nesta iniciativa. Entrevista conduzida por Paulo Rocha, da Ag\u00eancia Ecclesia.<\/p>\n<p>Qual o objectivo da iniciativa da Confer\u00eancia Episcopal Portuguesa \u201cRepensar a Pastoral da Igreja em Portugal\u00bb?<\/p>\n<p>Padre Manuel Moruj\u00e3o &#8211; A inspira\u00e7\u00e3o fundamental veio de Bento XVI, no seu discurso aos Bispos de Portugal, por ocasi\u00e3o da \u00faltima visita \u201cad limina\u201d, a Roma, em que o Papa fez um forte apelo \u00e0 renova\u00e7\u00e3o da Igreja em Portugal.<\/p>\n<p>O objectivo principal \u00e9 promover a renova\u00e7\u00e3o da ac\u00e7\u00e3o evangelizadora da Igreja, no contexto da actual sociedade portuguesa, discernindo prioridades e criando caminhos comuns de ac\u00e7\u00e3o, no respeito das justas autonomias das dioceses e par\u00f3quias, congrega\u00e7\u00f5es e movimentos de apostolado.<\/p>\n<p>Para novos problemas e desafios h\u00e1 que encontrar novas respostas. \u00c9 verdade que n\u00e3o h\u00e1 \u00abvarinhas m\u00e1gicas\u00bb apost\u00f3licas, solu\u00e7\u00f5es utopicamente ideais. Mas importa recuperar o fogo do Pentecostes e partir em miss\u00e3o para este mundo que Deus ama.<\/p>\n<p>De que forma \u00e9 que este projecto est\u00e1 a ser desenvolvido e que fases j\u00e1 se ultrapassaram?<\/p>\n<p>Pretendeu-se seguir um percurso sinodal (fazer caminho juntos), procurando que participasse o maior n\u00famero de agentes pastorais (bispos e padres, leigos\/as e religiosos\/as). A participa\u00e7\u00e3o gera responsabiliza\u00e7\u00e3o. Aos mais diversos n\u00edveis, j\u00e1 se realizaram reuni\u00f5es e encontros, em clima de discernimento pastoral, ou seja, n\u00e3o de mera reflex\u00e3o, mas de procura do que Deus quer de n\u00f3s, do que Cristo pede hoje \u00e0 sua Igreja em Portugal.<\/p>\n<p>As s\u00ednteses das sugest\u00f5es dos v\u00e1rios grupos (sombras e luzes na Igreja e no mundo; propostas de renova\u00e7\u00e3o da ac\u00e7\u00e3o pastoral da Igreja) foram enviadas para o Secretariado Geral do Episcopado que, por sua vez, elaborou um resumo com os pontos mais sublinhados e importantes. A necessidade de forma\u00e7\u00e3o, para a miss\u00e3o e na miss\u00e3o, foi muito sublinhada; a fam\u00edlia e os jovens foram campos de ac\u00e7\u00e3o indicados como priorit\u00e1rios.<\/p>\n<p>Que ades\u00e3o mereceu a proposta da Confer\u00eancia Episcopal Portuguesa junto das v\u00e1rias institui\u00e7\u00f5es?<\/p>\n<p>A ades\u00e3o a esta proposta da CEP foi razoavelmente positiva, o que n\u00e3o quer dizer que n\u00e3o pudesse ser mais abrangente e capilar. Envolveu milhares de pessoas comprometidas com a vida da Igreja, em que todos devemos ser pedras vivas, actores e n\u00e3o espectadores: Conselhos Presbiterais e Conselhos Pastorais das dioceses, por vezes tamb\u00e9m os Conselhos Pastorais das par\u00f3quias; diversos \u00f3rg\u00e3os e inst\u00e2ncias de congrega\u00e7\u00f5es religiosas e de movimentos e obras de apostolado dos leigos.<\/p>\n<p>Qual a pr\u00f3xima etapa para \u201cRepensar a pastoral da Igreja em Portugal\u201d?<\/p>\n<p>Actualmente est\u00e1 em curso uma sondagem \u00e0 opini\u00e3o p\u00fablica, coordenada pela Universidade Cat\u00f3lica Portuguesa, sobre o modo como os cidad\u00e3os do nosso pa\u00eds se posicionam perante a Igreja e quais as expectativas que t\u00eam a seu respeito, independentemente da sua filia\u00e7\u00e3o religiosa ou ideol\u00f3gica. A leitura sociol\u00f3gica dos dados recolhidos dar\u00e1 luz sobre o modo como actuar, j\u00e1 que a Igreja n\u00e3o vive a pensar em si pr\u00f3pria, mas na miss\u00e3o que Cristo lhe pede para servir melhor o mundo em que est\u00e1 presente, como fermento no meio da massa.<\/p>\n<p>Na pr\u00f3xima Assembleia Plen\u00e1ria dos Bispos [07-10 de Novembro, em F\u00e1tima, ver pag. 06] ser\u00e1 apresentado um programa de concretiza\u00e7\u00e3o da reflex\u00e3o feita at\u00e9 aqui e apontadas prioridades pastorais para a nova evangeliza\u00e7\u00e3o nos novos tempos em que vivemos.<\/p>\n<p>Bispos elegeram respons\u00e1veis das comiss\u00f5es<\/p>\n<p>Assembleia Plen\u00e1ria, reunida em F\u00e1tima (ver p\u00e1gina 6), elegeu os seguintes bispos para presidentes das Comiss\u00f5es Episcopais, assim constitu\u00eddas, para o tri\u00e9nio 2011-2014:<\/p>\n<p>&#8211; D. Ant\u00f3nio Francisco dos Santos, Bispo de Aveiro, Presidente da Comiss\u00e3o Episcopal da Educa\u00e7\u00e3o Crist\u00e3 e Doutrina da F\u00e9;<\/p>\n<p>-D. Jorge Ferreira da Costa Ortiga, Arcebispo de Braga, Presidente da Comiss\u00e3o Episcopal da Pastoral Social e Mobilidade Humana;<\/p>\n<p>&#8211; D. Antonino Eug\u00e9nio Fernandes Dias, Bispo de Portalegre-Castelo Branco, Presidente da Comiss\u00e3o Episcopal do Laicado e Fam\u00edlia;<\/p>\n<p>&#8211; D. Virg\u00edlio Nascimento Antunes, Bispo de Coimbra, Presidente da Comiss\u00e3o Episcopal das Voca\u00e7\u00f5es e Minist\u00e9rios;<\/p>\n<p>&#8211; D. Pio Gon\u00e7alo Alves de Sousa, Bispo Auxiliar do Porto, Presidente da Comiss\u00e3o Episcopal da Cultura, Bens Culturais e Comunica\u00e7\u00f5es Sociais;<\/p>\n<p>&#8211; D. Anacleto Cordeiro Gon\u00e7alves de Oliveira, Bispo de Viana do Castelo, Presidente da Comiss\u00e3o Episcopal da Liturgia e Espiritualidade;<\/p>\n<p>&#8211; D. Ant\u00f3nio Jos\u00e9 da Rocha Couto, Bispo auxiliar de Braga, Presidente da Comiss\u00e3o Episcopal da Miss\u00e3o e Nova Evangeliza\u00e7\u00e3o.<\/p>\n<p>A Assembleia Plen\u00e1ria elegeu os seguintes delegados para o tri\u00e9nio 2011-2014:<\/p>\n<p>-D. Manuel Neto Quintas, Bispo do Algarve, para as Rela\u00e7\u00f5es Bispos \/ Vida Consagrada;<\/p>\n<p>&#8211; D. Ant\u00f3nio Augusto dos Santos Marto, Bispo de Leiria-F\u00e1tima, para a Comiss\u00e3o dos Episcopados da Comunidade Europeia (COMECE).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Padre Manuel Moruj\u00e3o, secret\u00e1rio da Confer\u00eancia Episcopal Portuguesa, explica o percurso percorrido no projeto de \u00abRepensar a Pastoral da Igreja\u00bb, lan\u00e7ado em 2010, e quais os passos que se seguem nesta iniciativa. Entrevista conduzida por Paulo Rocha, da Ag\u00eancia Ecclesia. Qual o objectivo da iniciativa da Confer\u00eancia Episcopal Portuguesa \u201cRepensar a Pastoral da Igreja [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[57],"tags":[],"class_list":["post-18429","post","type-post","status-publish","format-standard","hentry","category-entrevista"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/18429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=18429"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/18429\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=18429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=18429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=18429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}