{"id":18576,"date":"2011-11-23T09:31:00","date_gmt":"2011-11-23T09:31:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=18576"},"modified":"2011-11-23T09:31:00","modified_gmt":"2011-11-23T09:31:00","slug":"a-igreja-nao-esta-a-chegar-ao-coracao-dos-residentes-da-paroquia-da-gloria","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/a-igreja-nao-esta-a-chegar-ao-coracao-dos-residentes-da-paroquia-da-gloria\/","title":{"rendered":"&#8220;A Igreja n\u00e3o est\u00e1 a chegar ao cora\u00e7\u00e3o dos residentes da par\u00f3quia da Gl\u00f3ria&#8221;"},"content":{"rendered":"<p>P.e Fausto Ara\u00fajo de Oliveira, ordenado em 1979, viveu os primeiros cinco anos de padre na par\u00f3quia da Gl\u00f3ria, at\u00e9 1985. Depois de passar por Albergaria-a-Velha e \u00cdlhavo, regressou \u00e0 \u201cpar\u00f3quia da S\u00e9\u201d. Mais do que um regresso foi um novo come\u00e7o, numa comunidade que \u00e9 uma \u201ccaixa de surpresas\u201d e em que os servi\u00e7os est\u00e3o estruturados em pessoas que n\u00e3o residem no espa\u00e7o geogr\u00e1fico da par\u00f3quia. Nesta entrevista, o p\u00e1roco da Gl\u00f3ria aponta como prioridades a Fam\u00edlia e a Eucaristia, bem como a pastoral dos jovens. Afirma que as Festas de Ver\u00e3o s\u00e3o para manter, mas descarta o Carnaval. Entrevista conduzida por Jorge Pires Ferreira.<\/p>\n<p>CORREIO DO VOUGA &#8211; O P.e Fausto est\u00e1 h\u00e1 um ano na par\u00f3quia da Gl\u00f3ria, embora j\u00e1 nela tivesse colaborado at\u00e9 1985. Que balan\u00e7o faz deste primeiro ano como p\u00e1roco de uma par\u00f3quia para a qual, por ter a catedral, se olha necessariamente com mais aten\u00e7\u00e3o?<\/p>\n<p>FAUSTO ARA\u00daJO DE OLIVEIRA \u2013 O facto de \u201cdividirmos\u201d a igreja com a diocese \u00e9 obst\u00e1culo e potencialidade. Pode gerar-se uma certa confus\u00e3o que n\u00e3o facilita o trabalho. O balan\u00e7o deste ano \u00e9 muito positivo, j\u00e1 que embora tendo algo a ver com o passado distante, esta par\u00f3quia foi uma grande novidade para mim. Neste primeiro ano \u2013 e em todos \u2013 \u00e9 necess\u00e1rio observar para respeitar, para saber interpretar, para acertar o passo. N\u00e3o venho impor passos, nem \u00e9 aos 65 anos que algu\u00e9m imp\u00f5e o que quer que seja. N\u00e3o \u00e9 essa a atitude do Evangelho. Sinto que tenho de acertar o passo para acompanhar o ritmo da comunidade que sirvo. Ao fim de um ano, h\u00e1 sectores em que se notam altera\u00e7\u00f5es de subst\u00e2ncia. Globalmente estou feliz por este trabalho e pelas respostas que v\u00e3o sendo dadas aos desafios que vou lan\u00e7ando.<\/p>\n<p>A que desafios concretos se refere e em que sectores se notam altera\u00e7\u00f5es de subst\u00e2ncia?<\/p>\n<p>Esta comunidade esteve absorvida nos \u00faltimos anos por obras, sem d\u00favida necess\u00e1rias \u2013 eu tamb\u00e9m tenho essa experi\u00eancia. As obras s\u00e3o necess\u00e1rias, mas tiram-nos, n\u00e3o digo o discernimento, mas aquela serenidade e capacidade de leitura da realidade pastoral que n\u00f3s devemos fazer. As obras t\u00eam encargos, trazem preocupa\u00e7\u00f5es\u2026<\/p>\n<p>No campo da catequese, mesmo de inf\u00e2ncia e especialmente de adolesc\u00eancia e jovens, este ano j\u00e1 h\u00e1 frutos vis\u00edveis com catequistas e animadores n\u00e3o s\u00f3 em n\u00famero mas tamb\u00e9m em quantidade. Insistimos no ano passado, pesc\u00e1mos \u00e0 linha, cativ\u00e1mos o mais poss\u00edvel. Agora temos todos os grupos com pelo menos dois animadores ou catequistas.<\/p>\n<p>Veio de uma par\u00f3quia, \u00cdlhavo, com um sector juvenil muito forte e vemos \u00e0 volta da Gl\u00f3ria par\u00f3quias que se distinguem na pastoral da juventude. Ora, a \u201cpar\u00f3quia da S\u00e9\u201d n\u00e3o se distingue pelos jovens. Vai haver mudan\u00e7as?<\/p>\n<p>N\u00e3o sei se vai haver mudan\u00e7as. Esta par\u00f3quia, como todas, \u00e9 uma caixa de surpresas.<\/p>\n<p>Refere-se a qu\u00ea?<\/p>\n<p>Quando sa\u00ed daqui, em 1985, j\u00e1 se notava, at\u00e9 porque a pastoral da cidade \u00e9 sempre diferente da de ambientes mais rurais, que esta \u00e9 uma comunidade mais de servi\u00e7os. Mas agora estamos perante uma realidade substantiva.<\/p>\n<p>Comunidade de servi\u00e7os quer dizer que as pessoas de outros lados v\u00eam pedir servi\u00e7os \u00e0 sua par\u00f3quia?<\/p>\n<p>N\u00e3o \u00e9 por facilitismos que isso acontece. O que quero dizer \u00e9 que esta comunidade est\u00e1 estruturada em pessoas que n\u00e3o residem c\u00e1. H\u00e1 dias, vimos num encontro com quase duas dezenas adultos que se preparam para o sacramento do Crisma que apenas um ou dois residem na \u00e1rea da par\u00f3quia da Gl\u00f3ria. Nenhum dos respons\u00e1veis dos animadores reside aqui. Na prepara\u00e7\u00e3o para o Matrim\u00f3nio, dos 17 pares que estiveram num encontro no final de Outubro, nenhum reside na Gl\u00f3ria. Dos casais que orientam a prepara\u00e7\u00e3o, s\u00f3 um reside na par\u00f3quia. E isto aplica-se tamb\u00e9m ao corpo de catequistas ou aos cantores que animam a liturgia. Dos 18 jovens crismados em Junho passado, quantos residiam na Gl\u00f3ria? Tr\u00eas. Todos os demais eram das par\u00f3quias \u00e0 volta. No encontro \u201cT\u00e1s convocado\u201d, com os nossos seminaristas (12 de Novembro), se n\u00e3o fossem os jovens de uma par\u00f3quia vizinha\u2026 Isto \u00e9 uma circunst\u00e2ncia que ainda n\u00e3o analisei bem, mas temos que fazer esse esfor\u00e7o. Onde \u00e9 que est\u00e3o os aveirenses da Gl\u00f3ria? Queremos envolv\u00ea-los na din\u00e2mica do jubileu, no pr\u00f3ximo ano. \u00c9 um dos principais desafios que vejo nesta comunidade. Julgo que os de dentro n\u00e3o v\u00e3o para fora. Mas de fora v\u00eam muitos. D\u00e3o-se pela par\u00f3quia da Gl\u00f3ria, mas isto cria dificuldades na ac\u00e7\u00e3o pastoral, na estabilidade e fidelidade. <\/p>\n<p>Quer dizer que a Igreja n\u00e3o chega a muitos dos que residem na par\u00f3quia?<\/p>\n<p>A Igreja n\u00e3o est\u00e1 a chegar ao cora\u00e7\u00e3o dos residentes da par\u00f3quia da Gl\u00f3ria. Sentimos que somos uma comunidade a envelhecer, que se vai demograficamente esvaindo, como acontece em quase todos os ambientes urbanos. A constru\u00e7\u00e3o est\u00e1 saturada e a que existe \u00e9 cara. Os filhos daqui v\u00e3o para fora. Quase metade das crian\u00e7as da catequese \u00e9 de fora. Talvez os av\u00f3s residam na Gl\u00f3ria. Alguns pais trabalham c\u00e1. A facilidade de inscrever os filhos na escola e catequese perto do local do trabalho dos pais explicar\u00e1 alguma coisa. E \u00e9 bom que as par\u00f3quias respondam \u00e0s dificuldades que os pais sentem na educa\u00e7\u00e3o dos filhos, at\u00e9 porque n\u00e3o sei se todas as par\u00f3quias se organizam em fun\u00e7\u00e3o das fam\u00edlias. A Igreja tem de ser assim, tem de responder \u00e0s solicita\u00e7\u00f5es da pessoa real, que bate \u00e0 porta, e n\u00e3o ao homem inventado.<\/p>\n<p>Neste regresso \u00e0 Gl\u00f3ria, passados 25 anos, as pessoas reconheceram-no?<\/p>\n<p>Isso ter\u00e1 de perguntar a elas. Tenho a impress\u00e3o que sim. Porventura sentiram algum desencanto (risos)\u2026 De facto, tenho sinais de que fui reconhecido e acolhido como sendo de casa. N\u00e3o constituiu grande novidade a minha vinda para servir esta comunidade. Do ponto de vista psicol\u00f3gico, o ambiente era \u00e0 partida favor\u00e1vel, compreensivo, aberto. N\u00e3o sinto resist\u00eancias, comparando com o per\u00edodo em que vivi aqui os meus primeiros cinco anos de padre. Est\u00e1vamos ent\u00e3o envolvidos num projecto que era o NIP \u2013 Nova Imagem de Par\u00f3quia. Dei a cara por ele. \u00c9 um projecto pastoral com que me identifico bastante devido \u00e0 sua din\u00e2mica e progressividade, abertura e envolv\u00eancia.<\/p>\n<p>Considera que a par\u00f3quia poderia envolver-se de novo num projecto pastoral similar?<\/p>\n<p>N\u00e3o sei se n\u00e3o teremos que equacionar um desafio renovador, at\u00e9 pelo jubileu que se aproxima. Temos de reflectir para ver se \u00e9 a resposta da Igreja nestas circunst\u00e2ncias. As coisas n\u00e3o podem ser transplantadas, mas h\u00e1 dinamismos que perduram, enquanto outros esmoreceram e enquistaram. Ent\u00e3o a equipa era jovem.<\/p>\n<p>Hoje, sinto a par\u00f3quia com pouca identidade, sem alma. Vive-se o fen\u00f3meno do entra a sai e sai-se mais do que se entra. E os que entram est\u00e3o mais soltos, sem sentido de perten\u00e7a a uma comunidade. N\u00e3o se enra\u00edzam, ainda que vivam com seriedade. Temos de repensar esta par\u00f3quia para amanh\u00e3. Se for s\u00f3 para hoje, os meus 65 est\u00e3o cada vez mais gastos e as equipas sacerdotais n\u00e3o t\u00eam tanta capacidade de rodagem e de frescura como tinham noutros tempos.<\/p>\n<p>Houve v\u00e1rias mudan\u00e7as nas equipas sacerdotais nos \u00faltimos tempos. Qual a sua rela\u00e7\u00e3o com o \u00faltimo p\u00e1roco, o P.e Manuel Jo\u00e3o, que saiu em circunst\u00e2ncias pouco esclarecidas?<\/p>\n<p>Tinha pouca rela\u00e7\u00e3o com ele, uma rela\u00e7\u00e3o de vir \u00e0 S\u00e9, de pouco mais que as meras formalidades. As circunst\u00e2ncias da sua sa\u00edda foram dolorosas. A sua despedida n\u00e3o foi bem explicada. As pessoas ficaram com muita pena. Senti no esp\u00edrito de algumas pessoas alguma penaliza\u00e7\u00e3o pessoal por n\u00e3o terem sabido ajudar e compreender. Achavam que at\u00e9 poderiam ter evitado esse desenlace. Foi um processo violento, \u00e1spero, de pouca informa\u00e7\u00e3o. Ele est\u00e1 no Brasil, mas n\u00e3o transparece qualquer tipo de informa\u00e7\u00e3o sobre o que faz, se \u00e9 feliz\u2026 H\u00e1 dias, foi contactado por causa da p\u00e1gina electr\u00f3nica da par\u00f3quia e respondeu prontamente. Devo dizer tamb\u00e9m que, passados uns dias de eu estar na par\u00f3quia, ele mandou um e-mail dirigido a mim, manifestando disponibilidade para qualquer tipo de informa\u00e7\u00e3o.<\/p>\n<p>Retomemos a quest\u00e3o das prioridades pastorais. Quais s\u00e3o para este ano?<\/p>\n<p>H\u00e1 dois pontos fortes para este ano. A import\u00e2ncia da liturgia e a ora\u00e7\u00e3o v\u00eam do ano passado, j\u00e1 que n\u00e3o foram t\u00e3o conseguidas. Por outro lado, temos a fam\u00edlia e a Eucaristia. S\u00e3o estes os dois pontos em que vamos procurar assentar o esfor\u00e7o pessoal, familiar, comunit\u00e1rio. Queremos envolver a fam\u00edlia no projecto catequ\u00e9tico. A catequese \u00e9 fundamental. Quando se foca demasiado a nossa aten\u00e7\u00e3o para determinado lado, h\u00e1 \u00e1reas que ficam difusas, na penumbra. Havia zonas da ac\u00e7\u00e3o pastoral um bocado na penumbra. A envolv\u00eancia da fam\u00edlia na catequese, na liturgia, especialmente na Eucaristia, \u00e9 fundamental.<\/p>\n<p>A aten\u00e7\u00e3o \u00e0 adolesc\u00eancia, \u00e0 juventude e \u00e0 p\u00f3s-juventude \u00e9 outra das prioridades. Mesmo a pastoral universit\u00e1ria. A nossa malta que vai para a universidade perde a liga\u00e7\u00e3o \u00e0 par\u00f3quia. N\u00e3o constru\u00edmos comunidade se cortamos com esses jovens. <\/p>\n<p>A par\u00f3quia se prepara para um grande investimento, um \u00f3rg\u00e3o de tubos. Quer explicar?<\/p>\n<p>O processo est\u00e1 a andar. H\u00e1 duas coisas, no campo da Rota das Catedrais [programa do governo, protocolado com a Confer\u00eancia Episcopal Portuguesa, para a reabilita\u00e7\u00e3o f\u00edsica das catedrais e sua dinamiza\u00e7\u00e3o cultural], que gostava de fazer: dotar a S\u00e9 de um \u00f3rg\u00e3o de tubos e colocar vitrais. No entanto, como j\u00e1 disse ao Sr. Bispo, da Rota das Catedrais n\u00e3o dever\u00e1 vir financiamento para isto. Mas s\u00e3o duas coisas priorit\u00e1rias para dar alma a esta igreja e dar uma resposta da Igreja \u00e0s exig\u00eancias culturais\u2026<\/p>\n<p>\u2026Grandes concertos? Apoio ao Coro da Catedral?<\/p>\n<p>Estou a falar de concertos, sim, mas tamb\u00e9m para o nosso servi\u00e7o normal.<\/p>\n<p>N\u00e3o chega reparar o \u00f3rg\u00e3o antigo o que j\u00e1 existe?<\/p>\n<p>No projecto da Rota das Catedrais est\u00e1 previsto restauro daquele \u00f3rg\u00e3o hist\u00f3rico, o que implica, por exemplo, retirar os elementos introduzidos pelo P.e Arm\u00e9nio Costa, que, no fim de contas, do ponto de vista do rigor hist\u00f3rico, adulteraram o \u00f3rg\u00e3o. H\u00e1 tr\u00eas anos falava-se de 146 mil euros para o restauro. Mas mesmo que o \u00f3rg\u00e3o seja restaurado, n\u00e3o responde verdadeiramente \u00e0 necessidades do pr\u00f3prio espa\u00e7o. Os registos que tem n\u00e3o fazem dele um \u00f3rg\u00e3o adequado. Mesmo reparado, ser\u00e1 um \u00f3rg\u00e3o insuficiente para a liturgia.<\/p>\n<p>O novo \u00f3rg\u00e3o ter\u00e1 de ser integralmente suportado pela par\u00f3quia?<\/p>\n<p>Sim, porque n\u00e3o est\u00e1 previsto na Rota das Catedrais. Quanto aos vitrais, na esperan\u00e7a de que possa um dia vir algum financiamento, o projecto foi apenso no ano passado \u00e0 nossa candidatura. Ser\u00e1 um investimento da ordem dos 300 mil euros \u2013 s\u00f3 os vitrais.<\/p>\n<p>A partir do momento em que comecei a rezar este espa\u00e7o f\u00edsico, convenci-me de que, para al\u00e9m das urg\u00eancias imediatas, apenas devemos investir no \u00f3rg\u00e3o e nos vitrais. Na ordem do agir, o \u00f3rg\u00e3o \u00e9 priorit\u00e1rio. Disse isso mesmo ao Sr. Bispo. \u00c9 uma convic\u00e7\u00e3o t\u00e3o grande em mim que me apanhou por dentro. Disse-o sem rodeios e sem preparar o ambiente. Houve pessoas que resistiram e resistem, mas quanto a isso n\u00e3o tenho problema.<\/p>\n<p>Resistiram por pensarem que \u00e9 um grande investimento em tempo de crise?<\/p>\n<p>Muita da resist\u00eancia vir\u00e1 por a\u00ed. Mas hei-de escrever sobre isso. Neste momento, o processo est\u00e1 em fase de propostas. At\u00e9 ao dia 30 de Novembro, t\u00eam de nos chegar as propostas dos mestres organeiros. Foram contactados oito, portugueses e estrangeiros. J\u00e1 nos chegaram duas propostas. Neste trabalho, confio numa \u201ctask force\u201d constitu\u00edda por Domingos Peixoto [m\u00fasico; professor], Ant\u00f3nio M\u00e1rio [m\u00fasico; maestro do Coro da Catedral], Paulo Cruz [padre; director da Escola Diocesana de M\u00fasica Sacra].<\/p>\n<p>S\u00e3o os seus consultores?<\/p>\n<p>S\u00e3o os que tecnicamente me podem dizer o que conv\u00e9m. Estabeleceu-se que at\u00e9 30 de Novembro as propostas devem estar c\u00e1. At\u00e9 ao diz 15 de Dezembro, saber-se-\u00e1 qual a proposta vencedora. At\u00e9 31 de Dezembro, dever\u00e1 estar assinado o contrato porque o prazo de entrega do \u00f3rg\u00e3o \u00e9 30 de Setembro de 2013, de forma a estar pronto no final do ano do jubileu.<\/p>\n<p>Seria uma esp\u00e9cie de oferta da par\u00f3quia \u00e0 Diocese de Aveiro pelos seus 75 anos, no dia 11 de Dezembro de 2013?<\/p>\n<p>Eu disse a D. Ant\u00f3nio Francisco a minha inten\u00e7\u00e3o e passa por a\u00ed.<\/p>\n<p>Quanto prev\u00ea que custe tal \u00f3rg\u00e3o?<\/p>\n<p>\u00c9 um \u00f3rg\u00e3o feito com determinados registos e potencialidades e a pensar no espa\u00e7o concreto da S\u00e9. Em princ\u00edpio, tendo cerca de oito metros de altura, ficar\u00e1 no transepto direito, onde est\u00e1 o coro, encostado \u00e0 parede.<\/p>\n<p>N\u00e3o diz o pre\u00e7o. Mas a par\u00f3quia tem dinheiro?<\/p>\n<p>N\u00e3o tem, mas tem de pensar em ter. Um dia, os \u00f3rg\u00e3os de comunica\u00e7\u00e3o social ser\u00e3o convocados para iniciar um processo que financeiramente seja sustent\u00e1vel. Anda na ordem das centenas de milhares de euros.<\/p>\n<p>A liturgia \u00e9 importante. Mas nesta altura de crise, algumas pessoas poder\u00e3o sempre sentir-se interrogadas sobre se realmente \u00e9 a melhor ocasi\u00e3o para este tipo de investimentos.<\/p>\n<p>Nunca as dificuldades do imediatismo nos dever\u00e3o bloquear para a realiza\u00e7\u00e3o de coisas para amanh\u00e3. Este \u00e9 um investimento para amanh\u00e3. E tamb\u00e9m para al\u00e9m de amanh\u00e3. Este tipo de investimento ter\u00e1 sempre algo de pol\u00e9mico, pela sua pr\u00f3pria natureza. Mas uma coisa \u00e9 certa: nunca me deixei bloquear pelas dificuldades do imediatismo quando queremos fazer alguma coisa de valor. Estou habituado a provocar que se fa\u00e7am obras sem a cobertura financeira no momento em que se iniciam. <\/p>\n<p>Estamos numa terra em que o ensino da m\u00fasica tem um grande estatuto: na Universidade de Aveiro, no Conservat\u00f3rio, nas associa\u00e7\u00f5es e bandas. A Igreja tamb\u00e9m tem de responder a estes desafios. \u201cNem s\u00f3 de p\u00e3o vive o homem\u201d. E seguramente que quando se constru\u00edram as catedrais, haveria muita fome e hoje abrimos a boca de espanto e de gratid\u00e3o para com essa gente que deixou a sua vida no cinzel e na arte da pedra. H\u00e1 coisas que se s\u00e3o avaliadas no imediato nunca temos f\u00f4lego e coragem para assumir. \u00c9 uma tenta\u00e7\u00e3o que a par\u00f3quia da Gl\u00f3ria deve evitar. Mas em rela\u00e7\u00e3o a isto, j\u00e1 pensei e rezei muito. H\u00e1 cada vez mais gente a dizer que vale a pena. N\u00e3o estou \u00e0 espera que todos digam \u201camen\u201d. Tamb\u00e9m me perguntam por que \u00e9 que ainda n\u00e3o se fala disto\u2026 Porque h\u00e1 um momento certo para come\u00e7ar a falar e agir e a angariar fundos. A exposi\u00e7\u00e3o medi\u00e1tica acontecer\u00e1 quando a minha \u201ctroika\u201d decidir que \u201cem fun\u00e7\u00e3o das caracter\u00edsticas, este \u00e9 o que melhor responde\u201d. Ent\u00e3o avan\u00e7amos. Na zona de Aveiro, n\u00e3o h\u00e1 nenhum \u00f3rg\u00e3o do g\u00e9nero. Talvez o de Vagos sirva de compara\u00e7\u00e3o, mas tem menos potencialidades, at\u00e9 porque o espa\u00e7o \u00e9 diferente.<\/p>\n<p>Como est\u00e1 a pastoral social na par\u00f3quia?<\/p>\n<p>Mal. Recebi com tristeza, mas n\u00e3o estou vencido nem convencido, que a Confer\u00eancia Vicentina anunciou a sua extin\u00e7\u00e3o com base em duas raz\u00f5es: n\u00e3o tem dinheiro e as institui\u00e7\u00f5es como as Florinhas do Vouga e a C\u00e1ritas esvaziam o seu campo de ac\u00e7\u00e3o. Como resposta, de facto, institucionalmente, as Florinhas do Vouga t\u00eam uma bela e ineg\u00e1vel resposta. O Patronato de Nossa Senhora de F\u00e1tima, em Vilar, tem uma ineg\u00e1vel e valiosa resposta, ainda que n\u00e3o t\u00e3o diversificada. A Confer\u00eancia Vicentina de Vilar vai fazendo o que pode. A n\u00edvel de servi\u00e7os, temos a Rouparia Solid\u00e1ria, no Bairro de Santiago. Estamos a envidar esfor\u00e7os para vertebr\u00e1-la, com mais consist\u00eancia organizativa e capacidade de resposta. Como resposta, pouco mais temos do que isto, al\u00e9m da ajuda pontual \u00e0queles que nos v\u00eam bater \u00e0 porta. H\u00e1 ainda o grupo de visitadores de doentes. Cada vez mais se faz sentir a sua necessidade n\u00e3o tanto por causa dos doentes mas da solid\u00e3o. H\u00e1 cada vez mais pessoas s\u00f3s.<\/p>\n<p>A pastoral social \u00e9 um ramo que temos de organizar com respostas mais alargadas. Senti que a Confer\u00eancia Vicentina podia e pode ser resposta, porque espa\u00e7o de interven\u00e7\u00e3o e falta de dinheiro n\u00e3o devem ser problema.<\/p>\n<p>H\u00e1 duas grandes manifesta\u00e7\u00f5es populares promovidas pela par\u00f3quia: o Carnaval e as Festas de Ver\u00e3o. S\u00e3o para continuar?<\/p>\n<p>O Carnaval surgiu como fazendo parte do plano de actividades quando a par\u00f3quia seguia um processo de renova\u00e7\u00e3o \u2013 o j\u00e1 referido NIP. Todos os meses havia uma ac\u00e7\u00e3o significativa para vivenciar um valor proposto. O Carnaval exigiu envolv\u00eancias e respondeu a um dinamismo que era preciso imprimir. Entretanto \u2013 a meu ver \u2013  deixou de ser uma ac\u00e7\u00e3o promovida pela Igreja para ser uma ac\u00e7\u00e3o que entrou, enfim, na normal actividade de qualquer tipo de associa\u00e7\u00e3o. E isso n\u00e3o \u00e9 t\u00edpico da ac\u00e7\u00e3o da igreja. Chego numa situa\u00e7\u00e3o de fim de linha. Encontro o Carnaval exausto, sem for\u00e7a, sem esp\u00edrito, sem grande vontade de ir \u00e0 rua enquanto movimento da Igreja, como algo que a Igreja inventou para dinamizar a comunidade crist\u00e3 e ajudar a vivenciar valores como a alegria, a proximidade, etc. A equipa n\u00e3o quis assumir o desafio de o fazer, tamb\u00e9m por raz\u00f5es financeiras, e eu apoiei da decis\u00e3o. O Carnaval, para n\u00f3s, morreu. Enquanto par\u00f3quia, n\u00e3o vamos tomar a iniciativa.<\/p>\n<p>Com as Festas de Ver\u00e3o \u00e9 diferente. N\u00e3o vamos prescindir delas. Proporcionam conv\u00edvio e, financeiramente, at\u00e9 d\u00e3o alguns meios. S\u00e3o sempre em Junho, no Parque, que \u00e9 um s\u00edtio \u00f3ptimo. Nelas ter\u00e1 lugar o dia da comunidade paroquial como momento culminante do ponto de vista religioso da proposta que queremos viver todos os anos. As Festas n\u00e3o nos custam muito, n\u00e3o h\u00e1 investimento a n\u00e3o ser f\u00edsico e an\u00edmico. Vamos, contudo, rever os aspectos culturais da anima\u00e7\u00e3o nocturna dos s\u00e1bados. A integra\u00e7\u00e3o do dia da comunidade nas Festas de Ver\u00e3o \u00e9 uma mais-valia que nos faz sempre pautar as coisas por outro tipo de valores que n\u00e3o penas a mera divers\u00e3o de arraial. Temos sempre de repensar, avaliar, inventar.<\/p>\n<p>Mais uma vez o P.e Fausto pensa no futuro. \u00c9 uma preocupa\u00e7\u00e3o constante olhar para al\u00e9m do hoje?<\/p>\n<p>N\u00e3o sou um homem de corridas fortes, de 100 metros. Sou mais de maratonas. Passo a passo com a consist\u00eancia necess\u00e1ria e com alguma ousadia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>P.e Fausto Ara\u00fajo de Oliveira, ordenado em 1979, viveu os primeiros cinco anos de padre na par\u00f3quia da Gl\u00f3ria, at\u00e9 1985. Depois de passar por Albergaria-a-Velha e \u00cdlhavo, regressou \u00e0 \u201cpar\u00f3quia da S\u00e9\u201d. Mais do que um regresso foi um novo come\u00e7o, numa comunidade que \u00e9 uma \u201ccaixa de surpresas\u201d e em que os servi\u00e7os [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[57],"tags":[],"class_list":["post-18576","post","type-post","status-publish","format-standard","hentry","category-entrevista"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/18576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=18576"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/18576\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=18576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=18576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=18576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}