{"id":18582,"date":"2011-11-23T09:37:00","date_gmt":"2011-11-23T09:37:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=18582"},"modified":"2011-11-23T09:37:00","modified_gmt":"2011-11-23T09:37:00","slug":"d-antonio-couto-nomeado-para-lamego","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/d-antonio-couto-nomeado-para-lamego\/","title":{"rendered":"D. Ant\u00f3nio Couto nomeado para Lamego"},"content":{"rendered":"<p>D. Ant\u00f3nio Couto, at\u00e9 agora bispo auxiliar de Braga, toma posse como bispo de Lamego no dia 29 de Janeiro de 2012.<\/p>\n<p>Bento XVI nomeou no s\u00e1bado, 19, como novo bispo de Lamego D. Ant\u00f3nio Couto, at\u00e9 agora auxiliar de Braga. O prelado, de 59 anos, substitui no cargo D. Jacinto Botelho, bispo de Lamego desde o ano 2000, que apresentara a sua ren\u00fancia ao Papa por ter atingido o limite de idade imposto pelo direito can\u00f3nico (75 anos), em 2010.<\/p>\n<p>\u201cSa\u00fado e abra\u00e7o a bela, antiga e ilustre Diocese de Lamego, todos os filhos e filhas de Deus que nela levantam as m\u00e3os e o cora\u00e7\u00e3o para Deus, desde os mais pequeninos at\u00e9 aos mais idosos, todos e todas as comunidades e par\u00f3quias, com os\/as seus\/suas catequistas, cantores, ac\u00f3litos, leitores, zeladoras, confrarias, movimentos, ministros da comunh\u00e3o, animadores da caridade, seminaristas, institutos religiosos e seculares, di\u00e1conos, presb\u00edteros, servi\u00e7os e secretariados, col\u00e9gio de consultores e cabido da S\u00e9 Catedral, e o meu querido amigo e irm\u00e3o no episcopado, D. Jacinto Tom\u00e1s de Carvalho Botelho, a quem sa\u00fado com particular afecto\u201d, assinala o novo bispo, na mensagem que endere\u00e7ou \u00e0 diocese.<\/p>\n<p>A tomada de posse est\u00e1 marcada para 29 de Janeiro de 2012. O prelado deixa uma palavra de \u201cafecto e gratid\u00e3o\u201d \u00e0 diocese de Braga, em particular ao arcebispo D. Jorge Ortiga e a D. Manuel Linda, bispo auxiliar.<\/p>\n<p>D. Ant\u00f3nio Jos\u00e9 da Rocha Couto nasceu a 18 de Abril de 1952 em Vila Boa do Bispo, concelho de Marco de Canaveses, distrito e diocese do Porto. Foi ordenado em 1980 como padre da Sociedade Mission\u00e1ria da Boa Nova. Estudou Teologia B\u00edblica em Roma, onde se doutorou, e foi professor de Sagrada Escritura no Semin\u00e1rio Maior de Luanda (1989-90). \u00c9 professor da Faculdade de Teologia da Universidade Cat\u00f3lica Portuguesa.<\/p>\n<p>O novo bispo de Lamego foi reitor do Semin\u00e1rio do Semin\u00e1rio da Boa Nova, de Valadares, de 1996 a 2002, ano em que foi eleito Superior Geral Sociedade Mission\u00e1ria da Boa Nova. D. Ant\u00f3nio Couto ocupou este cargo at\u00e9 \u00e0 data da sua ordena\u00e7\u00e3o episcopal, em 23 de Setembro de 2007, ap\u00f3s ter sido nomeado, por Bento XVI, bispo auxiliar de Braga. Membro da Congrega\u00e7\u00e3o para a Evangeliza\u00e7\u00e3o dos Povos desde 2004, o prelado \u00e9 presidente da Comiss\u00e3o Episcopal da Miss\u00e3o e Nova Evangeliza\u00e7\u00e3o.<\/p>\n<p>Com uma popula\u00e7\u00e3o de 144 mil pessoas e mais de 143 mil cat\u00f3licos, a diocese de Lamego, no distrito de Viseu, conta com mais de 220 par\u00f3quias e tem uma hist\u00f3ria que remonta ao s\u00e9culo VI.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D. Ant\u00f3nio Couto, at\u00e9 agora bispo auxiliar de Braga, toma posse como bispo de Lamego no dia 29 de Janeiro de 2012. Bento XVI nomeou no s\u00e1bado, 19, como novo bispo de Lamego D. Ant\u00f3nio Couto, at\u00e9 agora auxiliar de Braga. O prelado, de 59 anos, substitui no cargo D. Jacinto Botelho, bispo de Lamego [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53],"tags":[],"class_list":["post-18582","post","type-post","status-publish","format-standard","hentry","category-igreja-em-portugal"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/18582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=18582"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/18582\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=18582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=18582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=18582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}