{"id":18814,"date":"2011-12-14T10:47:00","date_gmt":"2011-12-14T10:47:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=18814"},"modified":"2011-12-14T10:47:00","modified_gmt":"2011-12-14T10:47:00","slug":"a-eloquencia-das-lagrimas-sentidas","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/a-eloquencia-das-lagrimas-sentidas\/","title":{"rendered":"A eloqu\u00eancia das l\u00e1grimas sentidas"},"content":{"rendered":"<p>Olhos na Rua <!--more--> N\u00e3o vi em directo, e tenho pena. Vi e li, depois, os ecos de quem viu e da comunica\u00e7\u00e3o social, tocada por aquele testemunho inesperado. Trata-se do gesto da ministra dos Assuntos Sociais de It\u00e1lia, que, ao ter de anunciar restri\u00e7\u00f5es aos idosos, exigidas pela crise econ\u00f3mica do pa\u00eds, chorou \u00e0 vista de toda a gente. Os governantes t\u00eam cora\u00e7\u00e3o e devem dar largas ao sentimento, quando \u00e9 caso. N\u00e3o se anunciam sacrif\u00edcios, como se anunciam festas. Tamb\u00e9m \u00e9 maneira de convencer, mostrar que as coisas passam por dentro de n\u00f3s. Os insens\u00edveis geram insensibilidade. E desta, j\u00e1 chega. Ser solid\u00e1rio sempre e nas dificuldades \u00e9 um grito que n\u00e3o se pode sufocar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Olhos na Rua<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[],"class_list":["post-18814","post","type-post","status-publish","format-standard","hentry","category-opiniao"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/18814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=18814"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/18814\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=18814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=18814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=18814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}