{"id":18815,"date":"2011-12-21T09:34:00","date_gmt":"2011-12-21T09:34:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=18815"},"modified":"2011-12-21T09:34:00","modified_gmt":"2011-12-21T09:34:00","slug":"desafio-radical","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/desafio-radical\/","title":{"rendered":"Desafio radical"},"content":{"rendered":"<p>O evangelho de Jo\u00e3o n\u00e3o faz o relato da institui\u00e7\u00e3o da Eucaristia. Em vez disso, enquadra na celebra\u00e7\u00e3o da Ceia a narrativa do lava-p\u00e9s. Para esc\u00e2ndalo dos Seus disc\u00edpulos, sobretudo de Pedro, Jesus, Mestre e Senhor, ajoelha-se a seus p\u00e9s para lhos lavar. E conclui que o Seu exemplo \u00e9 para ser seguido.<\/p>\n<p>Poderemos dizer que este gesto completa, de alguma forma, a cena do Pres\u00e9pio: o paradoxo do Senhor dos senhores feito o mais humilde e obediente dos homens, o servo dos servos\u2026 Um desafio permanente e radical a quantos se querem considerar seguidores do Mestre. Um programa de vida exigente, que desviamos com frequ\u00eancia da nossa rota crist\u00e3, inventando milhentas desculpas para moldarmos a vida como nos conv\u00e9m, em vez de acolhermos esta proposta radical.<\/p>\n<p>A li\u00e7\u00e3o do pres\u00e9pio, mais do que o apelo a recordar a simplicidade de Bel\u00e9m ou a vida discreta de Nazar\u00e9, \u00e9 o imperativo de uma forma de vida a cultivar em todo o tempo e lugar, como fermento de um mundo de sobriedade, de proximidade, de coopera\u00e7\u00e3o.<\/p>\n<p>Sabemos como foi estropiado, pervertido, o sentido do Natal. Os interesses comerciais, a perda de valores, paganizaram por completo este acontecimento que mudou a hist\u00f3ria da Humanidade. E a tal ponto que n\u00e3o sobra, em muitos casos, nem sequer a mem\u00f3ria do motivo destas \u201cfestas\u201d.<\/p>\n<p>Recuperar o seu sentido n\u00e3o \u00e9 apenas restabelecer a poesia do pres\u00e9pio, fomentar a reuni\u00e3o das Fam\u00edlias, entronizar a imagem do Menino, solenizar a liturgia natal\u00edcia\u2026 \u00c9 recome\u00e7ar, isso sim, paulatinamente este estilo novo de vida que torna o mundo diferente.<\/p>\n<p>A ternura da gruta, a alegria dos pastores, a busca dos magos, a universalidade da Luz que para n\u00f3s nasceu, s\u00e3o outras tantas atitudes que nos guiar\u00e3o nesse novo estilo de vida, a semear nas fam\u00edlias e nos grupos, a interiorizar e tornar pr\u00e1tico todos os dias do ano. Tal pr\u00e1tica n\u00e3o se compraz com os nossos ego\u00edsmos e vaidades, com as nossas invejas e gan\u00e2ncias, com as nossas sedes de poder e dom\u00ednio.<\/p>\n<p>Os valores do Reino, nascidos do Pres\u00e9pio, ir\u00e3o seguramente vencer. Temos a garantia disso! Mas a sua presen\u00e7a e visibilidade neste mundo dependem tamb\u00e9m da nossa ousadia em assumir o desfio radical do Natal!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O evangelho de Jo\u00e3o n\u00e3o faz o relato da institui\u00e7\u00e3o da Eucaristia. Em vez disso, enquadra na celebra\u00e7\u00e3o da Ceia a narrativa do lava-p\u00e9s. Para esc\u00e2ndalo dos Seus disc\u00edpulos, sobretudo de Pedro, Jesus, Mestre e Senhor, ajoelha-se a seus p\u00e9s para lhos lavar. E conclui que o Seu exemplo \u00e9 para ser seguido. Poderemos dizer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[],"class_list":["post-18815","post","type-post","status-publish","format-standard","hentry","category-editorial"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/18815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=18815"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/18815\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=18815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=18815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=18815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}