{"id":19295,"date":"2012-02-22T15:02:00","date_gmt":"2012-02-22T15:02:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=19295"},"modified":"2012-02-22T15:02:00","modified_gmt":"2012-02-22T15:02:00","slug":"eua-31","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/eua-31\/","title":{"rendered":"EUA"},"content":{"rendered":"<p>Crist\u00e3os no Mundo <!--more--> O presidente da Liga Cat\u00f3lica, Bill Donohue, assinalou que a atua\u00e7\u00e3o da rapper Nicki Minaj nos pr\u00e9mios Grammy foi um grave ataque ao catolicismo, que se soma a outros que sofrem os membros da Igreja neste pa\u00eds. No domingo, 12, Minaj subiu ao palco dos Grammy com um vestido vermelho que simulava um h\u00e1bito de religiosa, acompanhada de um homem disfar\u00e7ado de Papa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Crist\u00e3os no Mundo<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"class_list":["post-19295","post","type-post","status-publish","format-standard","hentry","category-igreja-no-mundo"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/19295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=19295"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/19295\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=19295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=19295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=19295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}