{"id":20073,"date":"2011-02-16T09:36:00","date_gmt":"2011-02-16T09:36:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=20073"},"modified":"2011-02-16T09:36:00","modified_gmt":"2011-02-16T09:36:00","slug":"vaticano-revela-aumento-de-14-no-numero-de-padres","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/vaticano-revela-aumento-de-14-no-numero-de-padres\/","title":{"rendered":"Vaticano revela aumento de 1,4% no n\u00famero de padres"},"content":{"rendered":"<p>A nova edi\u00e7\u00e3o do Anu\u00e1rio Estat\u00edstico da Igreja Cat\u00f3lica revela um aumento de 1,4% no n\u00famero de padres em todo o mundo entre 1999 e 2009, adiantou o Vaticano. O volume elenca 410 mil sacerdotes, dos quais mais de 275 mil diocesanos e cerca de 135 mil de ordens e congrega\u00e7\u00f5es religiosas.<\/p>\n<p>O \u00abAnnuarium Statisticum Ecclesiae 2009\u00bb \u00e9 redigido pelo departamento central de estat\u00edstica da Igreja e publicado pela Livraria Editora Vaticana. Segundo os dados adiantados, o n\u00famero de padres ordenados em 2009 ultrapassou o dos sacerdotes que faleceram ou abandonaram este minist\u00e9rio, situa\u00e7\u00e3o que n\u00e3o acontecia desde 1999.<\/p>\n<p>Na Europa, contudo, o n\u00famero de mortes continua a ultrapassar o das ordena\u00e7\u00f5es sacerdotais. O novo Anu\u00e1rio Estat\u00edstico da Igreja mostra que o n\u00famero de padres e de cat\u00f3licos aumenta na \u00c1frica, \u00c1sia e Am\u00e9rica Latina, caindo na Europa e Am\u00e9rica do Norte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A nova edi\u00e7\u00e3o do Anu\u00e1rio Estat\u00edstico da Igreja Cat\u00f3lica revela um aumento de 1,4% no n\u00famero de padres em todo o mundo entre 1999 e 2009, adiantou o Vaticano. O volume elenca 410 mil sacerdotes, dos quais mais de 275 mil diocesanos e cerca de 135 mil de ordens e congrega\u00e7\u00f5es religiosas. O \u00abAnnuarium Statisticum [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"class_list":["post-20073","post","type-post","status-publish","format-standard","hentry","category-igreja-no-mundo"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/20073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=20073"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/20073\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=20073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=20073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=20073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}