{"id":20125,"date":"2012-05-23T14:57:00","date_gmt":"2012-05-23T14:57:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=20125"},"modified":"2012-05-23T14:57:00","modified_gmt":"2012-05-23T14:57:00","slug":"bispo-de-aveiro-129","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/bispo-de-aveiro-129\/","title":{"rendered":"Bispo de Aveiro"},"content":{"rendered":"<p>Dia 17 de maio: D. Ant\u00f3nio Francisco reuniu com a Comiss\u00e3o da Casa Sacerdotal.<\/p>\n<p>Dia 18: Participou no Encontro Nacional dos Alunos de Moral do 1.\u00ba Ciclo, em F\u00e1tima.<\/p>\n<p>Dia 19: participou na inaugura\u00e7\u00e3o do Lar de A-dos-Ferreiros; participou na inaugura\u00e7\u00e3o do Lar da Funda\u00e7\u00e3o C\u00f3nego Filipe Figueiredo; participou no Festival da can\u00e7\u00e3o dos jovens.<\/p>\n<p>Dia 20: Participou e presidiu \u00e0 Festa Diocesana das Fam\u00edlias.<\/p>\n<p>Dia 21: Participou na reuni\u00e3o dos bispos do Centro, em Coimbra.<\/p>\n<p>De 21 a 27: Estar\u00e1 em visita pastoral \u00e0 par\u00f3quia de Vagos.<\/p>\n<p>Dia 22: Reuniu com os bispos da prov\u00edncia eclesi\u00e1stica de Braga, em Lamego.<\/p>\n<p>Dia 24: Celebrar\u00e1 a Eucaristia na S\u00e9, no dia em que a Fam\u00edlia Dominicana celebra a Translada\u00e7\u00e3o de S. Domingos de Gusm\u00e3o.<\/p>\n<p>Dia 26: Celebrar\u00e1 a Eucaristia e o sacramento do Crisma na par\u00f3quia da Gl\u00f3ria.<\/p>\n<p>Dia 27: Celebrar\u00e1 a Eucaristia de encerramento da visita pastoral \u00e0 par\u00f3quia de Vagos<\/p>\n<p>Dia 28: Celebrar\u00e1 a Eucaristia de encerramento da visita pastoral ao arciprestado de Vagos, nas festividades de Santa Maria de Vagos.<\/p>\n<p>Dia 29: Reunir\u00e1 com o Conselho Pastoral Social.<\/p>\n<p>Dia 31: Reunir\u00e1 com o Conselho de Arciprestes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dia 17 de maio: D. Ant\u00f3nio Francisco reuniu com a Comiss\u00e3o da Casa Sacerdotal. Dia 18: Participou no Encontro Nacional dos Alunos de Moral do 1.\u00ba Ciclo, em F\u00e1tima. Dia 19: participou na inaugura\u00e7\u00e3o do Lar de A-dos-Ferreiros; participou na inaugura\u00e7\u00e3o do Lar da Funda\u00e7\u00e3o C\u00f3nego Filipe Figueiredo; participou no Festival da can\u00e7\u00e3o dos jovens. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70],"tags":[],"class_list":["post-20125","post","type-post","status-publish","format-standard","hentry","category-diocese"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/20125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=20125"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/20125\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=20125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=20125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=20125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}