{"id":20317,"date":"2012-06-14T10:31:00","date_gmt":"2012-06-14T10:31:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=20317"},"modified":"2012-06-14T10:31:00","modified_gmt":"2012-06-14T10:31:00","slug":"criancas-encheram-santuario-de-fatima-apesar-da-chuva","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/criancas-encheram-santuario-de-fatima-apesar-da-chuva\/","title":{"rendered":"Crian\u00e7as encheram Santu\u00e1rio de F\u00e1tima apesar da chuva"},"content":{"rendered":"<p>Peregrina\u00e7\u00e3o infantil <!--more--> Dezenas de milhares de crian\u00e7as, acompanhadas por pais e catequistas, participaram na peregrina\u00e7\u00e3o anual ao Santu\u00e1rio de F\u00e1tima, evento que decorreu debaixo de chuva, sendo presidido pelo bispo de Coimbra.<\/p>\n<p>Na homilia que proferiu na missa final, D. Virg\u00edlio Antunes, exortou os mais novos a cumprirem os seus compromissos com Deus, e apelou a atitudes de \u201cconfian\u00e7a\u201d, \u201cdisponibilidade\u201d, \u201ccompromisso\u201d e \u201cfidelidade a Deus\u201d.<\/p>\n<p>A peregrina\u00e7\u00e3o subordinou-se \u00e0 pergunta \u2018Que \u00e9 que vossemec\u00ea me quer?\u2019, que L\u00facia dirigiu a 13 de maio de 1917 \u00e0 Virgem Maria, aquando da primeira das seis apari\u00e7\u00f5es que ocorreram at\u00e9 outubro desse ano.<\/p>\n<p>O momento foi lembrado pelo bispo de Coimbra e antigo reitor do Santu\u00e1rio de F\u00e1tima, que recordou a experi\u00eancia dos pastorinhos: \u201cDali para a frente eles ficaram t\u00e3o amigos de Jesus e de Nossa Senhora, passaram a ter uma rela\u00e7\u00e3o t\u00e3o boa com Eles, que se sentiam da sua fam\u00edlia, tinham muita confian\u00e7a e estavam dispostos a fazer tudo o que lhes dissessem\u201d.<\/p>\n<p>A iniciativa foi antecedida pela \u201ccampanha de maio\u201d, que visou aprofundar nos mais novos o acolhimento \u00e0 vontade da m\u00e3e de Cristo.<\/p>\n<p>As 18 mil crian\u00e7as que aderiram \u00e0 iniciativa escolheram palavras associadas \u00e0 disponibilidade e escreveram-nas num postal, dentro de folhas de azinheira desenhadas, uma refer\u00eancia \u00e0 \u00e1rvore ainda hoje plantada junto \u00e0 Capelinha das Apari\u00e7\u00f5es e onde a Virgem apareceu pela primeira vez, segundo o relato dos pastorinhos.<\/p>\n<p>No final da missa da Peregrina\u00e7\u00e3o das Crian\u00e7as, o atual reitor do Santu\u00e1rio de F\u00e1tima, padre Carlos Cabecinhas, pediu que uma \u2018surpresa recorda\u00e7\u00e3o\u2019 da peregrina\u00e7\u00e3o fosse distribu\u00edda \u00e0s crian\u00e7as presentes na celebra\u00e7\u00e3o.<\/p>\n<p>Os participantes receberam uma pequena bolota das 35 mil que foram feitas, em pl\u00e1stico, para lembrar as bolotas da Azinheira Grande que est\u00e1 ao lado da Capelinha das Apari\u00e7\u00f5es, recheada com um bombom e uma fita em tecido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Peregrina\u00e7\u00e3o infantil<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51],"tags":[],"class_list":["post-20317","post","type-post","status-publish","format-standard","hentry","category-jovens"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/20317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=20317"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/20317\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=20317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=20317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=20317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}