{"id":20691,"date":"2012-09-19T16:57:00","date_gmt":"2012-09-19T16:57:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=20691"},"modified":"2012-09-19T16:57:00","modified_gmt":"2012-09-19T16:57:00","slug":"tapetes-que-contam-historias","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/tapetes-que-contam-historias\/","title":{"rendered":"Tapetes que contam hist\u00f3rias"},"content":{"rendered":"<p>\u00cdlhavo <!--more--> H\u00e1 tapetes que n\u00e3o s\u00e3o para limpar os p\u00e9s, mas que contam hist\u00f3rias. Feitos de tecido, revelando cores, formas e volumes, os contapetes beb\u00e9s s\u00e3o um espa\u00e7o de descoberta onde adulto e crian\u00e7a exploram sons, s\u00edlabas e palavras, dando os primeiros passos no territ\u00f3rio fant\u00e1stico da narrativa.<\/p>\n<p>E cada contapete beb\u00e9 tem o seu livro correspondente, o que permite repetir as aventuras uma e outra vez. As pequen\u00edssimas hist\u00f3rias, partilhadas entre todos os que est\u00e3o \u00e0 volta do tapete ou do livro, desafiam a brincar com sons e sentidos, propondo associa\u00e7\u00f5es entre cor e espa\u00e7o, forma e som, ritmo e textura, e incitando as primeiras articula\u00e7\u00f5es e constru\u00e7\u00f5es fr\u00e1sicas. Ver, tocar e sentir organizam-se, assim, numa aventura partilhada e expressam-se finalmente sob a forma de palavra.<\/p>\n<p>\u201cContapetes\u201d, para beb\u00e9s e crian\u00e7as at\u00e9 5 anos, no Centro Cultural de \u00cdlhavo,  dia 23 de setembro, das 10h \u00e0s 11h30. Bilhetes a 3,50 euros (0-5 anos) e 5,5 euros (acompanhantes).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00cdlhavo<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[67],"tags":[],"class_list":["post-20691","post","type-post","status-publish","format-standard","hentry","category-ver-ouvir-sair"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/20691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=20691"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/20691\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=20691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=20691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=20691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}