{"id":21728,"date":"2011-03-09T09:28:00","date_gmt":"2011-03-09T09:28:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=21728"},"modified":"2011-03-09T09:28:00","modified_gmt":"2011-03-09T09:28:00","slug":"desistir-nunca","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/desistir-nunca\/","title":{"rendered":"Desistir? Nunca!"},"content":{"rendered":"<p>O desencontro entre o Minist\u00e9rio da Educa\u00e7\u00e3o, entre o Governo, e o Pa\u00eds continua com manifesta\u00e7\u00f5es constantes e de profunda gravidade. A par da tentativa de estrangulamento da iniciativa particular e cooperativa como integrante do servi\u00e7o p\u00fablico de educa\u00e7\u00e3o, vem agora a quest\u00e3o da revis\u00e3o curricular do Ensino B\u00e1sico e Secund\u00e1rio.<\/p>\n<p>Ao inverso do que vai acontecendo em pa\u00edses que est\u00e3o na primeira linha do sucesso educativo (Jap\u00e3o, Nova Zel\u00e2ndia, Coreia do Sul, pa\u00edses n\u00f3rdicos\u2026), que apostam na partilha da tarefa educativa pela sociedade civil, num vasto leque de possibilidades, acrescido com uma autonomia curricular real, as tend\u00eancias centralizadoras e monopolistas s\u00e3o a filosofia que preside \u00e0s pol\u00edticas governamentais em Portugal, sem grande dist\u00e2ncia de um figurino estalinista.<\/p>\n<p>E, mais grave: n\u00e3o se tecem considera\u00e7\u00f5es pedag\u00f3gicas em torno da problem\u00e1tica da Educa\u00e7\u00e3o, em busca de rumos acertados, que resultem n\u00e3o apenas em sucessos escolar, como tamb\u00e9m em verdadeira capacita\u00e7\u00e3o de homens e mulheres que sonhem, desenhem e construam o nosso futuro.<\/p>\n<p>Na realidade, quem dirige as pol\u00edticas educativas \u00e9 um cego Minist\u00e9rio das Finan\u00e7as, que corta sem d\u00f3 nem piedade em quest\u00f5es fundamentais, sem atender &#8211; porque n\u00e3o o pode perceber &#8211; ao que seja formar as novas gera\u00e7\u00f5es. Pior: \u00e9 leg\u00edtimo suspeitar que essa \u201cfrente de batalha\u201d para regular as contas p\u00fablicas esconde inten\u00e7\u00f5es mais subtis de formatar ideologicamente os cidad\u00e3os.<\/p>\n<p>Come\u00e7amos a ver professores, assistentes operacionais, pais e alunos, perplexos e desmotivados, interrogando-se os primeiros sobre o seu futuro profissional, questionando-se sobre o futuro de tantos projectos educativos, perguntando-se os segundos sobre a liberdade que lhes assiste de serem os primeiros e irrenunci\u00e1veis educadores dos filhos.<\/p>\n<p>\u201cDesistir \u00e9 proibido\u201d &#8211; exclamava recentemente D. Ant\u00f3nio Marcelino. \u00c9 isso mesmo: n\u00e3o podemos renunciar a direitos fundamentais! N\u00e3o est\u00e3o apenas entrar despudoradamente no bolso dos mais pobres! Est\u00e3o a roubar-nos a liberdade, est\u00e3o a encurralar-nos numa debilidade de for\u00e7as, para esmagar com o poder toda a possibilidade de reac\u00e7\u00e3o!<\/p>\n<p>Urge reunir for\u00e7as, potenciar sinergias, imaginar alternativas, para que o poder n\u00e3o seja mais domina\u00e7\u00e3o, mas servi\u00e7o; para que n\u00e3o seja mais \u201cilumina\u00e7\u00e3o\u201d de uns tantos rotulando a multid\u00e3o de incompet\u00eancia e ocultismo! Desistir? Nunca! <\/p>\n","protected":false},"excerpt":{"rendered":"<p>O desencontro entre o Minist\u00e9rio da Educa\u00e7\u00e3o, entre o Governo, e o Pa\u00eds continua com manifesta\u00e7\u00f5es constantes e de profunda gravidade. A par da tentativa de estrangulamento da iniciativa particular e cooperativa como integrante do servi\u00e7o p\u00fablico de educa\u00e7\u00e3o, vem agora a quest\u00e3o da revis\u00e3o curricular do Ensino B\u00e1sico e Secund\u00e1rio. Ao inverso do que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[],"class_list":["post-21728","post","type-post","status-publish","format-standard","hentry","category-editorial"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/21728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=21728"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/21728\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=21728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=21728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=21728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}