{"id":21917,"date":"2013-02-28T10:48:00","date_gmt":"2013-02-28T10:48:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=21917"},"modified":"2013-02-28T10:48:00","modified_gmt":"2013-02-28T10:48:00","slug":"arder-ate-ao-fim","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/arder-ate-ao-fim\/","title":{"rendered":"Arder at\u00e9 ao fim"},"content":{"rendered":"<p>A conversa levou-nos para apreciarmos entregas e reservas, alegrias e desilus\u00f5es, trabalhos e lazer\u2026 A senten\u00e7a final foi lapidar: \u201cAntes quero arder durante cinco anos do que fumegar durante vinte e cinco!\u201d &#8211; rematou o colega.<\/p>\n<p>Vem a prop\u00f3sito, neste tempo de calculismo comodista, de pesar e medir e cobrar tudo o que se faz, repetir at\u00e9 \u00e0 exaust\u00e3o este pensamento, sobretudo para aqueles a quem o Senhor diz de forma expl\u00edcita: \u201cRecebestes de gra\u00e7a, dai de gra\u00e7a\u201d. Sem menosprezar a certeza de que o trabalhador \u00e9 digno do seu sal\u00e1rio, \u00e9 fundamental redescobrir este gosto de \u201carder em chama viva\u201d naquilo que se \u00e9, naquilo que se faz, na condi\u00e7\u00e3o de disc\u00edpulo de Jesus Cristo, na condi\u00e7\u00e3o de minist\u00e9rio assumido no seio da Comunidade.<\/p>\n<p>Sai o nosso jornal do \u201cCorreio do Vouga\u201d pela \u00faltima vez sob o pontificado de Bento XVI. \u00c9 hora de lhe agradecermos o fogo que brilhou no seu minist\u00e9rio petrino. Independentemente de, porventura, se n\u00e3o estar de acordo com tudo, \u00e9 ineg\u00e1vel que ele deu todas as suas capacidades &#8211; \u00fanicas! &#8211; e deu-se, sem reservas, na condu\u00e7\u00e3o desta Barca de Pedro, atrav\u00e9s do oceano encapelado da hist\u00f3ria dos nossos dias. Gra\u00e7as a Deus pelo Papa que nos deu! Gra\u00e7as a Bento XVI pelo vigor com que serviu a Igreja e a Humanidade!<\/p>\n<p>N\u00e3o foi longo o seu pontificado. Mas foi fecundo. N\u00e3o foi imenso o seu magist\u00e9rio escrito. Mas foi marcante, conciso, clarividente, de elevada qualidade. Afrontou problemas dolorosos, dialogou frontalmente com a cultura e a ci\u00eancia, sentou-se \u00e0 mesa com as outras religi\u00f5es, ousou interpelar pol\u00edticos e sistemas\u2026 Foi chama que se consumiu depressa, mas com intensidade!<\/p>\n<p>Nada mais injusto do que dizer que \u201cdesceu da cruz\u201d. Continua a ser chama viva a humildade do sil\u00eancio e da ora\u00e7\u00e3o, da vida oculta, por amor \u00e0 Igreja, a que decidiu dedicar-se. Essa, a vida contemplativa, \u00e9 outra forma de arder at\u00e9 ao fim. A sua perman\u00eancia na cruz \u00e9 exatamente a corajosa simplicidade de se recolher, submetendo-se, mais uma vez, \u00e0 cr\u00edtica de quem quer que seja.<\/p>\n<p>Vivemos uma semana que vence seis s\u00e9culos de hist\u00f3ria. Pela coragem de um Ho-mem, de um Bispo, de um Papa, que preferiu arder por um certo tempo, a fumegar eter-namente sem aquecer nem iluminar ningu\u00e9m.<\/p>\n<p>O Esp\u00edrito o amparar\u00e1 neste novo servi\u00e7o ao Mundo e \u00e0 Igreja. O Esp\u00edrito nos dar\u00e1, para surpresa dos malabaristas dos c\u00e1lculos e das apostas, o Papa que precisamos para a Igreja possa continuar a sulcar a hist\u00f3ria dos homens marcando-a com uma sementeira de Esperan\u00e7a, de Verdade, de aut\u00eantica Caridade. Assim o desejamos. Assim o esperamos! <\/p>\n","protected":false},"excerpt":{"rendered":"<p>A conversa levou-nos para apreciarmos entregas e reservas, alegrias e desilus\u00f5es, trabalhos e lazer\u2026 A senten\u00e7a final foi lapidar: \u201cAntes quero arder durante cinco anos do que fumegar durante vinte e cinco!\u201d &#8211; rematou o colega. Vem a prop\u00f3sito, neste tempo de calculismo comodista, de pesar e medir e cobrar tudo o que se faz, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[],"class_list":["post-21917","post","type-post","status-publish","format-standard","hentry","category-editorial"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/21917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=21917"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/21917\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=21917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=21917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=21917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}