{"id":22931,"date":"2011-05-18T09:28:00","date_gmt":"2011-05-18T09:28:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=22931"},"modified":"2011-05-18T09:28:00","modified_gmt":"2011-05-18T09:28:00","slug":"vicentinos-convidam-outros-grupos-porque-juntos-servicos-melhor","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/vicentinos-convidam-outros-grupos-porque-juntos-servicos-melhor\/","title":{"rendered":"Vicentinos convidam outros grupos porque &#8220;juntos servi\u00e7os melhor&#8221;"},"content":{"rendered":"<p>O Conselho Central de Aveiro da Sociedade S\u00e3o Vicente de Paulo (SSVP) vai realizar no s\u00e1bado, 21 de Maio, \u00e0s 14h30, no audit\u00f3rio do Semin\u00e1rio de Aveiro, uma assembleia vicentina subordinada ao tema \u201cJuntos servimos melhor\u201d.<\/p>\n<p>Contar\u00e1 com a presen\u00e7a do presidente nacional da SSVP, Correia Saraiva, e com o Bispo de Aveiro, D. Ant\u00f3nio Francisco, e ter\u00e1 como convidados a C\u00e1ritas, Florinhas do Vouga, APAV e ADAV.<\/p>\n<p>\u201cAtentos aos sinais dos tempos e \u00e0s novas formas de pobreza, somos desafiados a dar uma resposta cada vez mais eficaz \u00e0s solicita\u00e7\u00f5es de quem nos procura. Estamos conscientes que essa resposta n\u00e3o depender\u00e1 s\u00f3 das Confer\u00eancias Vicentinas, mas da articula\u00e7\u00e3o e do conhecimento concreto das respostas sociais de outras associa\u00e7\u00f5es\u201d, afirma Fernanda Capit\u00e3o, que integra a direc\u00e7\u00e3o diocesana deste servi\u00e7o aos mais carenciados. A respons\u00e1vel relembra as palavras de Bento XVI h\u00e1 um ano em F\u00e1tima, que apelou ao amor, \u00e0 caridade e \u00e0 fraternidade universal, na \u00f3ptica da \u201cbusca de solu\u00e7\u00f5es que estejam na l\u00f3gica da efic\u00e1cia\u201d, numa manifesta\u00e7\u00e3o da import\u00e2ncia da articula\u00e7\u00e3o das redes sociais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho Central de Aveiro da Sociedade S\u00e3o Vicente de Paulo (SSVP) vai realizar no s\u00e1bado, 21 de Maio, \u00e0s 14h30, no audit\u00f3rio do Semin\u00e1rio de Aveiro, uma assembleia vicentina subordinada ao tema \u201cJuntos servimos melhor\u201d. Contar\u00e1 com a presen\u00e7a do presidente nacional da SSVP, Correia Saraiva, e com o Bispo de Aveiro, D. Ant\u00f3nio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70],"tags":[],"class_list":["post-22931","post","type-post","status-publish","format-standard","hentry","category-diocese"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/22931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=22931"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/22931\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=22931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=22931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=22931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}