{"id":22932,"date":"2011-05-18T09:28:00","date_gmt":"2011-05-18T09:28:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=22932"},"modified":"2011-05-18T09:28:00","modified_gmt":"2011-05-18T09:28:00","slug":"encerramento-da-visita-pastoral-a-oliveira-do-bairro","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/encerramento-da-visita-pastoral-a-oliveira-do-bairro\/","title":{"rendered":"Encerramento da visita pastoral a Oliveira do Bairro"},"content":{"rendered":"<p>Depois de ter visitado as dez par\u00f3quias do arciprestado, D. Ant\u00f3nio Francisco conclui a visita pastoral presidindo \u00e0 Eucaristia, no Espa\u00e7o Inova\u00e7\u00e3o, em Vila Verde, Oliveira do Bairro, dia 22 de Maio, \u00e0s 15h. Em mensagem que dirigiu ao arciprestado, publicada neste jornal na semana passada, o Bispo de Aveiro convidou \u201ctodas as comunidades crist\u00e3s, movimentos, associa\u00e7\u00f5es, grupos e agentes de pastoral\u201d para a celebra\u00e7\u00e3o que pretende ser \u201cum grande momento de alegria, ora\u00e7\u00e3o, festa e esperan\u00e7a\u201d para todos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depois de ter visitado as dez par\u00f3quias do arciprestado, D. Ant\u00f3nio Francisco conclui a visita pastoral presidindo \u00e0 Eucaristia, no Espa\u00e7o Inova\u00e7\u00e3o, em Vila Verde, Oliveira do Bairro, dia 22 de Maio, \u00e0s 15h. Em mensagem que dirigiu ao arciprestado, publicada neste jornal na semana passada, o Bispo de Aveiro convidou \u201ctodas as comunidades crist\u00e3s, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70],"tags":[],"class_list":["post-22932","post","type-post","status-publish","format-standard","hentry","category-diocese"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/22932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=22932"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/22932\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=22932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=22932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=22932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}