{"id":22935,"date":"2011-05-18T09:33:00","date_gmt":"2011-05-18T09:33:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=22935"},"modified":"2011-05-18T09:33:00","modified_gmt":"2011-05-18T09:33:00","slug":"maria-clara-um-rosto-da-ternura-e-da-misericordia-de-deus","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/maria-clara-um-rosto-da-ternura-e-da-misericordia-de-deus\/","title":{"rendered":"Maria Clara, um rosto da ternura e da miseric\u00f3rdia de Deus"},"content":{"rendered":"<p>A irm\u00e3 Maria Clara do Menino Jesus (1843-1899), fundadora das Franciscanas Hospitaleiras, vai ser beatificada no pr\u00f3ximo s\u00e1bado, em Lisboa.<\/p>\n<p>Vai ter lugar no pr\u00f3ximo s\u00e1bado, 21 Maio, no Est\u00e1dio do Restelo, Lisboa, com in\u00edcio \u00e0s 10h30, a beatifica\u00e7\u00e3o da irm\u00e3 Maria Clara do Menino Jesus (1843-1899), fundadora da Congrega\u00e7\u00e3o das Irm\u00e3s Franciscanas Hospitaleiras da Imaculada Concei\u00e7\u00e3o (CONFHIC).<\/p>\n<p>A celebra\u00e7\u00e3o ser\u00e1 presidida pelo Cardeal-Patriarca, D. Jos\u00e9 da Cruz Policarpo, sendo representante do Papa o Cardeal Angelo Amato, Prefeito da Congrega\u00e7\u00e3o para as Causas dos Santos.<\/p>\n<p>\u00abMaria Clara, um rosto de ternura e da miseric\u00f3rdia de Deus\u00bb \u00e9 o slogan escolhido para a celebra\u00e7\u00e3o, que foi preparada por diversas iniciativas de divulga\u00e7\u00e3o e forma\u00e7\u00e3o sobre a futura beata, incluindo uma p\u00e1gina na Internet (ver p\u00e1g. 19).<\/p>\n<p>O ritual da beatifica\u00e7\u00e3o inclui a leitura da Carta Apost\u00f3lica e a \u201cchamada prociss\u00e3o das rel\u00edquias\u201d, que neste caso ser\u00e1 um osso da Madre Maria Clara.<\/p>\n<p>O processo conheceu o seu ponto culminante quando, no dia 10 de Dezembro de 2010, Bento XVI assinou o Decreto de aprova\u00e7\u00e3o do milagre atribu\u00eddo \u00e0 intercess\u00e3o da Irm\u00e3 Maria Clara, relativo \u00e0 cura de uma cat\u00f3lica espanhola, Georgina Troncoso Monteagudo, afectada por um grave problema de pele.<\/p>\n<p>\u201cM\u00e3e Clara\u201d<\/p>\n<p>Lib\u00e2nia do Carmo Galv\u00e3o Meixa de Moura Telles e Albuquerque nasceu na Amadora, em Lisboa, a 15 de Junho de 1843. Recebeu o h\u00e1bito de Capuchinha, em 1869, escolhendo o nome de Irm\u00e3 Maria Clara do Menino Jesus.<\/p>\n<p>A futura beata foi enviada a Calais, Fran\u00e7a, a 10 de Fevereiro de 1870, para fazer o noviciado, na inten\u00e7\u00e3o de fundar, depois, em Portugal, uma nova Congrega\u00e7\u00e3o. Abriu a primeira comunidade da CONFHIC em S. Patr\u00edcio &#8211; Lisboa, no dia 3 de Maio de 1871 e, cinco anos depois, a 27 de Mar\u00e7o de 1876, a Congrega\u00e7\u00e3o \u00e9 aprovada pela Santa S\u00e9. Hoje est\u00e1 presente em 14 pa\u00edses.<\/p>\n<p>A \u00abM\u00e3e Clara\u00bb, como \u00e9 popularmente conhecida, morreu em Lisboa, no dia 1 de Dezembro de 1899 e o processo de canoniza\u00e7\u00e3o viria a iniciar-se em 1995. Os seus restos mortais repousam na Cripta da Casa-M\u00e3e da Congrega\u00e7\u00e3o, em Linda-a-Pastora, onde acorrem in\u00fameros devotos a implorar a sua intercess\u00e3o junto de Deus.<\/p>\n<p>O milagre atribu\u00eddo \u00e0 religiosa ocorreu a 12 de Novembro de 2003, em Baiona (Espanha), numa \u201cdevota\u201d que, em 1998, foi ao seu t\u00famulo e pediu a cura de um pioderma gangrenoso (doen\u00e7a cut\u00e2nea ulcerativa). Georgina Troncoso Monteagudo estar\u00e1 presente na beatifica\u00e7\u00e3o da \u00abM\u00e3e Clara\u00bb.<\/p>\n<p>CV\/Ecclesia<\/p>\n<p>Seis beatos e um santo nos \u00faltimos dez anos<\/p>\n<p>Maria Clara do Menino Jesus junta-se a cinco portugueses beatificados nos \u00faltimos dez anos: os Pastorinhos Francisco e Jacinta, de F\u00e1tima (13 de Maio de 2000); frei Bartolomeu dos M\u00e1rtires (4 de Novembro de 2001); Alexandrina de Balasar (25 de Abril de 2004, no Vaticano) e Rita Amada de Jesus (28 de Maio de 2006, em Viseu). Tamb\u00e9m neste per\u00edodo foi beatificado o Imperador Carlos de \u00c1ustria (3 de Outubro de 2004), que faleceu no Funchal, e canonizado Nuno \u00c1lvares Pereira, o Santo Condest\u00e1vel (26 de Abril de 2009, no Vaticano).<\/p>\n<p>Nova beata \u00e9 \u201cincentivo e apoio\u201d para os tempos actuais<\/p>\n<p>Os bispos portugueses escreveram no in\u00edcio de Maio deste ano uma nota pastoral sobre Maria Clara, real\u00e7ando que \u201cna segunda metade do s\u00e9culo XIX, apesar das grandes dificuldades que o catolicismo portugu\u00eas enfrentava\u201d, a religiosa \u201csoube manifest\u00e1-lo do modo mais criativo e fecundo, com ardente amor a Jesus e generoso servi\u00e7o dos pobres\u201d. E acrescentam: \u201cNa segunda d\u00e9cada do s\u00e9culo XXI, face \u00e0s dificuldades acrescidas de tantos concidad\u00e3os nossos, quanto \u00e0 sobreviv\u00eancia condigna e ao sentido mais profundo da vida, o exemplo e a intercess\u00e3o da nova Beata ser-nos-\u00e3o de grande incentivo e apoio, na mesma senda da caridade verdadeira\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A irm\u00e3 Maria Clara do Menino Jesus (1843-1899), fundadora das Franciscanas Hospitaleiras, vai ser beatificada no pr\u00f3ximo s\u00e1bado, em Lisboa. Vai ter lugar no pr\u00f3ximo s\u00e1bado, 21 Maio, no Est\u00e1dio do Restelo, Lisboa, com in\u00edcio \u00e0s 10h30, a beatifica\u00e7\u00e3o da irm\u00e3 Maria Clara do Menino Jesus (1843-1899), fundadora da Congrega\u00e7\u00e3o das Irm\u00e3s Franciscanas Hospitaleiras da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53],"tags":[],"class_list":["post-22935","post","type-post","status-publish","format-standard","hentry","category-igreja-em-portugal"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/22935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=22935"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/22935\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=22935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=22935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=22935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}