{"id":23400,"date":"2011-11-23T09:32:00","date_gmt":"2011-11-23T09:32:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=23400"},"modified":"2011-11-23T09:32:00","modified_gmt":"2011-11-23T09:32:00","slug":"bispo-de-aveiro-176","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/bispo-de-aveiro-176\/","title":{"rendered":"Bispo de Aveiro"},"content":{"rendered":"<p>Dia 19:<\/p>\n<p>D. Ant\u00f3nio Francisco reuniu com a Comiss\u00e3o Diocesana Justi\u00e7a e Paz; participou na assembleia dos di\u00e1conos permanentes; celebrou a Eucaristia e o sacramento do Crisma na par\u00f3quia da Gafanha da Encarna\u00e7\u00e3o;<\/p>\n<p>Dia 20:<\/p>\n<p>Celebrou a Eucaristia na par\u00f3quia de Eirol; participou na ordena\u00e7\u00e3o episcopal de D. Nuno Br\u00e1s, em Lisboa;<\/p>\n<p>Dia 22:<\/p>\n<p>Reuniu com o Secretariado Nacional da Educa\u00e7\u00e3o Crist\u00e3; participou no ciclo de confer\u00eancias Di\u00e1logo na Cidade, com o tema \u201cElogio \u00e0 Fraternidade: uma ousadia?\u201d;<\/p>\n<p>Dia 23:<\/p>\n<p>Re\u00fane com o Conselho de Arciprestes; <\/p>\n<p>Dia 26:<\/p>\n<p>Reunir\u00e1 com a direc\u00e7\u00e3o da ORBIS<\/p>\n<p>Dia 27:<\/p>\n<p>Celebrar\u00e1 a Eucaristia e o sacramento do Crisma nas par\u00f3quias da Barra e da Costa Nova; celebrar\u00e1 Eucaristia na S\u00e9, no in\u00edcio do Advento.<\/p>\n<p>Dia 29:<\/p>\n<p>Reunir\u00e1 com os bispos da Prov\u00edncia Eclesi\u00e1stica de Braga.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dia 19: D. Ant\u00f3nio Francisco reuniu com a Comiss\u00e3o Diocesana Justi\u00e7a e Paz; participou na assembleia dos di\u00e1conos permanentes; celebrou a Eucaristia e o sacramento do Crisma na par\u00f3quia da Gafanha da Encarna\u00e7\u00e3o; Dia 20: Celebrou a Eucaristia na par\u00f3quia de Eirol; participou na ordena\u00e7\u00e3o episcopal de D. Nuno Br\u00e1s, em Lisboa; Dia 22: Reuniu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70],"tags":[],"class_list":["post-23400","post","type-post","status-publish","format-standard","hentry","category-diocese"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/23400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=23400"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/23400\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=23400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=23400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=23400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}