{"id":23490,"date":"2012-01-18T14:48:00","date_gmt":"2012-01-18T14:48:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=23490"},"modified":"2012-01-18T14:48:00","modified_gmt":"2012-01-18T14:48:00","slug":"restos-mortais-do-fundador-dos-salesianos-chegam-a-portugal-sem-setembro","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/restos-mortais-do-fundador-dos-salesianos-chegam-a-portugal-sem-setembro\/","title":{"rendered":"Restos mortais do fundador dos salesianos chegam a Portugal sem setembro"},"content":{"rendered":"<p>Os restos mortais (rel\u00edquias) de S\u00e3o Jo\u00e3o Bosco (1815-1888), fundador dos Salesianos, congrega\u00e7\u00e3o cat\u00f3lica dedicada \u00e0 educa\u00e7\u00e3o da inf\u00e2ncia e juventude, v\u00e3o passar por Portugal de 1 a 18 de setembro para serem veneradas. O an\u00fancio foi feito no s\u00e1bado passado num encontro que reuniu em F\u00e1tima \u201cmais de 600\u201d religiosos e leigos pertencentes \u00e0 fam\u00edlia salesiana.<\/p>\n<p>As rel\u00edquias est\u00e3o a passar por v\u00e1rios pa\u00edses com vista \u00e0s celebra\u00e7\u00f5es do bicenten\u00e1rio do nascimento do fundador, em 2015.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os restos mortais (rel\u00edquias) de S\u00e3o Jo\u00e3o Bosco (1815-1888), fundador dos Salesianos, congrega\u00e7\u00e3o cat\u00f3lica dedicada \u00e0 educa\u00e7\u00e3o da inf\u00e2ncia e juventude, v\u00e3o passar por Portugal de 1 a 18 de setembro para serem veneradas. O an\u00fancio foi feito no s\u00e1bado passado num encontro que reuniu em F\u00e1tima \u201cmais de 600\u201d religiosos e leigos pertencentes \u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53],"tags":[],"class_list":["post-23490","post","type-post","status-publish","format-standard","hentry","category-igreja-em-portugal"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/23490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=23490"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/23490\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=23490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=23490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=23490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}