{"id":24177,"date":"2013-02-21T12:07:00","date_gmt":"2013-02-21T12:07:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=24177"},"modified":"2013-02-21T12:07:00","modified_gmt":"2013-02-21T12:07:00","slug":"que-papa","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/que-papa\/","title":{"rendered":"Que Papa?"},"content":{"rendered":"<p>A curiosidade de muitos, a indiscri\u00e7\u00e3o n\u00e3o raro doentia de certos meios de comunica\u00e7\u00e3o social, os amigos da teia vaticana burocr\u00e1tica, por alguns desejada, sem d\u00favida complexa, envolvem a atual conjuntura eclesial de um misto de receio, de expetativa, de esperan\u00e7a.<\/p>\n<p>Ocorrem-me, a prop\u00f3sito desta situa\u00e7\u00e3o, as palavras de Bento XVI na sua primeira mensagem aos Cardeais que o elegeram. \u201cConvivem no meu cora\u00e7\u00e3o nestas horas dois sentimentos contrastantes. Por um lado, um sentido de inaptid\u00e3o e de humana perturba\u00e7\u00e3o pela responsabilidade que ontem me foi confiada, como Sucessor do Ap\u00f3stolo Pedro nesta Sede de Roma, diante da Igreja universal. Por outro lado, sinto viva em mim uma profunda gratid\u00e3o a Deus, que, como nos faz cantar a liturgia, n\u00e3o abandona o seu rebanho, mas o guia atrav\u00e9s dos tempos, sob a guia de quantos Ele mesmo elegeu vig\u00e1rios do seu Filho e constituiu pastores (cf. Pref\u00e1cio dos Ap\u00f3stolos I).\u201d<\/p>\n<p>Estas palavras definem bem a \u00edntima predisposi\u00e7\u00e3o do eleito: a consci\u00eancia da responsabilidade assumida e da exig\u00eancia de capacidades espec\u00edficas que ela comporta; e a certeza de que o \u00fanico Pastor da Igreja \u00e9 Jesus Cristo, que a guia pelo Esp\u00edrito Santo. Afinal, a responsabilidade que se assume n\u00e3o \u00e9 mais do que emprestar ao Senhor aquilo que se \u00e9, enquanto se for capaz de o fazer de forma digna e nobre.<\/p>\n<p>E o Papa prossegue com ternura salutar. \u201cCar\u00edssimos, este reconhecimento \u00edntimo por um dom da divina miseric\u00f3rdia prevalece, apesar de tudo, no meu cora\u00e7\u00e3o. E considero este facto uma gra\u00e7a especial que me foi obtida pelo meu venerado Predecessor, Jo\u00e3o Paulo II. Tenho a impress\u00e3o de sentir a sua m\u00e3o forte que estreita a minha; parece que vejo os seus olhos sorridentes e que ou\u00e7o as suas palavras, dirigidas neste momento particularmente a mim: \u201cN\u00e3o tenhas medo!\u201d\u201d. <\/p>\n<p>O te\u00f3logo l\u00facido e penetrante n\u00e3o tem receio de reconhecer a sua pequenez e a depend\u00eancia da gra\u00e7a divina e do benef\u00edcio da comunh\u00e3o eclesial. \u00c9 com elas que conta para o exerc\u00edcio da miss\u00e3o a que foi chamado.<\/p>\n<p>Entendeu que as condi\u00e7\u00f5es da sua sa\u00fade f\u00edsica e psicol\u00f3gica j\u00e1 lhe n\u00e3o permitem emprestar ao Pastor \u00fanico as for\u00e7as convenientes para guiar o rebanho. A mesma humildade do in\u00edcio leva-o a perceber que o seu minist\u00e9rio terminou: completou a sua carreira; fez o que estava ao seu alcance; outro poder\u00e1 tomar o seu lugar, com benef\u00edcio para toda a Igreja. \u00c9 a express\u00e3o clara do seu amor \u00e0 Igreja!<\/p>\n<p>Naturalmente que h\u00e1 quest\u00f5es pr\u00e1ticas a resolver. E que se resolvam, sem preconceitos, nem interesses ocultos, sem receios de que o Senhor abandone a barca! Que n\u00e3o seja a intriga a inventar problemas onde eles n\u00e3o existem. Uma pessoa desta envergadura n\u00e3o est\u00e1 a fazer jogo de interesses, n\u00e3o criar\u00e1 obst\u00e1culos ao seu sucessor, n\u00e3o reclamar\u00e1 benesses do desempenho de um minist\u00e9rio que, em consci\u00eancia e liberdade, entende dever ter um termo.<\/p>\n<p>Venha outro Papa! Aquele que o Esp\u00edrito Santo quiser. Mais novo?&#8230; Parece conveniente. Pastor?&#8230; Exig\u00eancia fundamental! Preto, branco, amarelo?&#8230; Escolham, senhores Cardeais, com o Esp\u00edrito Santo! De F\u00e9 inabal\u00e1vel, convicto de que a Hist\u00f3ria da Salva\u00e7\u00e3o continua a desenrolar-se no mundo de hoje com a complexidade que ele tem! E ser\u00e1 o melhor Papa!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A curiosidade de muitos, a indiscri\u00e7\u00e3o n\u00e3o raro doentia de certos meios de comunica\u00e7\u00e3o social, os amigos da teia vaticana burocr\u00e1tica, por alguns desejada, sem d\u00favida complexa, envolvem a atual conjuntura eclesial de um misto de receio, de expetativa, de esperan\u00e7a. Ocorrem-me, a prop\u00f3sito desta situa\u00e7\u00e3o, as palavras de Bento XVI na sua primeira mensagem [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[],"class_list":["post-24177","post","type-post","status-publish","format-standard","hentry","category-editorial"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/24177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=24177"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/24177\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=24177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=24177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=24177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}