{"id":5024,"date":"2006-04-03T14:44:00","date_gmt":"2006-04-03T14:44:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=5024"},"modified":"2006-04-03T14:44:00","modified_gmt":"2006-04-03T14:44:00","slug":"designer-da-ua-premiado-em-chicago","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/designer-da-ua-premiado-em-chicago\/","title":{"rendered":"Designer da UA premiado em Chicago"},"content":{"rendered":"<p>Carlos Aguiar concorreu com o puxador \u201cTecnho Bionic A\u201d <!--more--> Carlos Aguiar, professor da Universidade de Aveiro, ganhou recentemente o pr\u00e9mio \u201cGood Design 2004\u201d, do Chicago Athenaeum: Museum of Architecture and Design, prestigiada institui\u00e7\u00e3o cultural de Chicago e \u00fanico museu de arquitectura e design dos EUA. O docente do Departamento de Comunica\u00e7\u00e3o e Arte concorreu com o projecto da ferragem de porta \u201cTecnho Bionic A\u201d, que se distinguiu pela \u201cconcep\u00e7\u00e3o, funcionalidade, utilidade e est\u00e9tica\u201d. Este puxador j\u00e1 tinha sido finalista de um outro concurso de n\u00edvel mundial, o IF Design Award de Hannover 2004.<\/p>\n<p>A atribui\u00e7\u00e3o deste pr\u00e9mio constitui, para o designer Carlos Aguiar, \u201cmais uma prova da excel\u00eancia e maioridade do design industrial portugu\u00eas, que, ao contr\u00e1rio do \u2018mito\u2019 que ainda subsiste em grande parte do nosso tecido empresarial, pode competir de igual para igual com os autores estrangeiros, se para isso tiver um m\u00ednimo de condi\u00e7\u00f5es da ind\u00fastria. Vem ainda confirmar a pertin\u00eancia e actualidade da forma\u00e7\u00e3o na \u00e1rea do design ministrada na Universidade de Aveiro, nomeadamente na sua aposta de fus\u00e3o do ensino base num s\u00f3 curso global refor\u00e7ando a capacidade de interven\u00e7\u00e3o dos licenciados no tecido econ\u00f3mico\u201d. <\/p>\n<p>Carlos Aguiar tem desenvolvido ao longo dos \u00faltimos 17 anos um trabalho consistente de design na \u00e1rea da metalomec\u00e2nica. No seu curr\u00edculo, entre v\u00e1rios pr\u00e9mios nacionais e internacionais, constam o Pr\u00e9mio Design para a Ind\u00fastria, do Centro Portugu\u00eas de Design, por tr\u00eas vezes, e o Pr\u00e9mio Designer, atribu\u00eddo excepcionalmente em 1994 pelo Centro Portugu\u00eas de Design, devido \u00e0 \u201ccontribui\u00e7\u00e3o demonstrada para a afirma\u00e7\u00e3o do Design Global nas empresas, assim como nos m\u00e9todos utilizados na investiga\u00e7\u00e3o, concep\u00e7\u00e3o e desenvolvimento de novos produtos\u201d. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carlos Aguiar concorreu com o puxador \u201cTecnho Bionic A\u201d<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[],"class_list":["post-5024","post","type-post","status-publish","format-standard","hentry","category-cultura"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/5024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=5024"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/5024\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=5024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=5024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=5024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}