{"id":5118,"date":"2006-04-03T14:44:00","date_gmt":"2006-04-03T14:44:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=5118"},"modified":"2006-04-03T14:44:00","modified_gmt":"2006-04-03T14:44:00","slug":"candidatos-presidenciais-perfilam-se","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/candidatos-presidenciais-perfilam-se\/","title":{"rendered":"Candidatos presidenciais perfilam-se"},"content":{"rendered":"<p>M\u00e1rio Soares anuncia hoje a sua candidatura \u00e0 Presid\u00eancia da Rep\u00fablica, depois de ter ocupado o cargo entre 1986 e 1996. Pelo PCP, candidata-se Jer\u00f3nimo de Sousa. O actual l\u00edder do partido j\u00e1 havia sido o candidato dos comunistas em 1996, tendo na altura desistido em favor Jorge Sampaio. Esperam-se ainda as candidaturas do Bloco de Esquerda e possivelmente de Manuel Alegre. Cavaco Silva j\u00e1 fez saber que s\u00f3 depois das aut\u00e1rquicas dir\u00e1 se \u00e9 candidato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1rio Soares anuncia hoje a sua candidatura \u00e0 Presid\u00eancia da Rep\u00fablica, depois de ter ocupado o cargo entre 1986 e 1996. Pelo PCP, candidata-se Jer\u00f3nimo de Sousa. O actual l\u00edder do partido j\u00e1 havia sido o candidato dos comunistas em 1996, tendo na altura desistido em favor Jorge Sampaio. Esperam-se ainda as candidaturas do Bloco [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[],"class_list":["post-5118","post","type-post","status-publish","format-standard","hentry","category-nacional"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/5118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=5118"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/5118\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=5118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=5118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=5118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}