{"id":5119,"date":"2006-04-03T14:44:00","date_gmt":"2006-04-03T14:44:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=5119"},"modified":"2006-04-03T14:44:00","modified_gmt":"2006-04-03T14:44:00","slug":"partidos-inflaccionam-orcamentos","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/partidos-inflaccionam-orcamentos\/","title":{"rendered":"Partidos inflaccionam or\u00e7amentos"},"content":{"rendered":"<p>O or\u00e7amento apresentado pelo PSD para a campanha aut\u00e1rquica \u00e9 de 45,6 milh\u00f5es de euros (cerca de 9 milh\u00f5es de contos). O PS prev\u00ea gastar 27,2 milh\u00f5es de euros, enquanto CDS aponta para os 23,6 milh\u00f5es de euros. A CDU refere 9,9 milh\u00f5es e o Bloco de Esquerda 2,3 milh\u00f5es de euros. Os n\u00fameros foram apresentados \u00e0 Entidade das Contas e Financiamentos Pol\u00edticos e alguns dirigentes j\u00e1 viveram afirmar que inflaccionaram os n\u00fameros com a finalidade de receberam o m\u00e1ximo de apoio estatal. O Estado dever\u00e1 gastar em subven\u00e7\u00f5es para a campanha das aut\u00e1rquicas cerca de 42 milh\u00f5es de euros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O or\u00e7amento apresentado pelo PSD para a campanha aut\u00e1rquica \u00e9 de 45,6 milh\u00f5es de euros (cerca de 9 milh\u00f5es de contos). O PS prev\u00ea gastar 27,2 milh\u00f5es de euros, enquanto CDS aponta para os 23,6 milh\u00f5es de euros. A CDU refere 9,9 milh\u00f5es e o Bloco de Esquerda 2,3 milh\u00f5es de euros. Os n\u00fameros foram [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[],"class_list":["post-5119","post","type-post","status-publish","format-standard","hentry","category-nacional"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/5119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=5119"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/5119\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=5119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=5119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=5119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}