{"id":5720,"date":"2006-04-03T14:44:00","date_gmt":"2006-04-03T14:44:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=5720"},"modified":"2006-04-03T14:44:00","modified_gmt":"2006-04-03T14:44:00","slug":"museu-nacional-do-azulejo","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/museu-nacional-do-azulejo\/","title":{"rendered":"Museu Nacional do Azulejo"},"content":{"rendered":"<p>Oliveira do Bairro <!--more--> No Museu Nacional do Azulejo, em Lisboa, est\u00e1 patente ao p\u00fablico, at\u00e9 ao dia 15 de Janeiro de 2006, uma exposi\u00e7\u00e3o de azulejos assinados pela estilista Ana Salazar, e que representam quinze anos de colabora\u00e7\u00e3o entre aquela conhecida criadora de roupas e a empresa Recer, sediada em Oliveira do Bairro.<\/p>\n<p>Na inaugura\u00e7\u00e3o da exposi\u00e7\u00e3o, para al\u00e9m de Ana Salazar, do director do Museu Nacional do Azulejo e do presidente do conselho de administra\u00e7\u00e3o da Recer, respectivamente Paulo Henriques e Antero Calvo, estiveram presentes, entre outras personalidades, a cantora Teresa Salgueiro, a estilista F\u00e1tima Lopes, a directora do Museu do Traje e o Embaixador da Bulg\u00e1ria.<\/p>\n<p>O evento foi aproveitado para lan\u00e7ar a 21\u00aa s\u00e9rie \u201cColec\u00e7\u00e3o Ana Salazar\u201d produzida pela Recer, denominada \u201cPrintings e Texturas\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oliveira do Bairro<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[],"class_list":["post-5720","post","type-post","status-publish","format-standard","hentry","category-regioes"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/5720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=5720"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/5720\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=5720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=5720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=5720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}