{"id":5852,"date":"2006-04-03T14:44:00","date_gmt":"2006-04-03T14:44:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=5852"},"modified":"2006-04-03T14:44:00","modified_gmt":"2006-04-03T14:44:00","slug":"colectivas-de-natal","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/colectivas-de-natal\/","title":{"rendered":"Colectivas de Natal"},"content":{"rendered":"<p>Nas Galerias Vera Cruz e Op Art <!--more--> Na Galeria Vera Cruz, situada no Largo da Apresenta\u00e7\u00e3o (Vera Cruz), em Aveiro, est\u00e1 patente ao p\u00fablico, at\u00e9 31 de Dezembro, a Exposi\u00e7\u00e3o Colectiva de Dezembro, com trabalhos dos artistas Albino Moura, Alfredo Luz, Ant\u00f3nio Neves, Artur Bual, Cruzeiro Seixas, Dami\u00e3o Porto, Fernanda Amado, Fernando Gaspar, Francisco Geraldo, Gil Teixeira Lopes, Gracinda Candeias, Guilherme Parente, Jo\u00e3o Cutileiro, J\u00falio Resende, Manuel Cargaleiro, Manuel Tavares, M\u00e1rio Cesariny, M\u00e1rio Portugal, Mota Urgueiro, Noronha da Costa, Paulo Ossi\u00e3o, Pedro Buisel, Querubim Lapa, Ricardo Paulo, Rog\u00e9rio de Abreu, Rog\u00e9rio Ribeiro e Z\u00e9 Augusto Castro.<\/p>\n<p>Tamb\u00e9m at\u00e9 31 de Dezembro, a Galeria Op Art, localizada na Avenida Jos\u00e9 Estev\u00e3o, na Gafanha da Nazar\u00e9, apresenta a Exposi\u00e7\u00e3o Colectiva de Natal, na qual se destacam obras dos artistas Ant\u00f3nio Neves, Carlos Mouro, Filinto Viana, Il\u00eddio, Isabel Carlos, J\u00falio Pires, Lopes de Sousa, Marco Rodrigues, M\u00e1rio Portugal, M\u00e1rio Silva, Rosando e  Sandra Ferro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nas Galerias Vera Cruz e Op Art<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[],"class_list":["post-5852","post","type-post","status-publish","format-standard","hentry","category-cultura"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/5852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=5852"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/5852\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=5852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=5852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=5852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}