{"id":6224,"date":"2006-04-03T14:44:00","date_gmt":"2006-04-03T14:44:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=6224"},"modified":"2006-04-03T14:44:00","modified_gmt":"2006-04-03T14:44:00","slug":"eleicoes-no-iraque-catastroficas-para-os-cristaos","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/eleicoes-no-iraque-catastroficas-para-os-cristaos\/","title":{"rendered":"Elei\u00e7\u00f5es no Iraque &#8220;catastr\u00f3ficas&#8221; para os crist\u00e3os"},"content":{"rendered":"<p>O bispo auxiliar de Bagdad, D. Andreas Abouna, considera que as elei\u00e7\u00f5es de 15 de Dezembro, no Iraque, constitu\u00edram \u201cum pesadelo\u201d para a comunidade crist\u00e3, uma vez que garantiram a vit\u00f3ria aos extremistas mu\u00e7ulmanos da chamada \u201clinha dura\u201d. Com apenas 3 deputados, os crist\u00e3os n\u00e3o ter\u00e3o, seguramente, uma voz activa no novo Parlamento. A Alian\u00e7a Iraquiana Unificada (AIU), ligada aos religiosos xiitas, obteve cerca de 48% dos votos, podendo alcan\u00e7ar 270 lugares na Assembleia Nacional atrav\u00e9s de uma coliga\u00e7\u00e3o com a Alian\u00e7a Curda, apoiada pelo cl\u00e9rigo Ali al-Sistani.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O bispo auxiliar de Bagdad, D. Andreas Abouna, considera que as elei\u00e7\u00f5es de 15 de Dezembro, no Iraque, constitu\u00edram \u201cum pesadelo\u201d para a comunidade crist\u00e3, uma vez que garantiram a vit\u00f3ria aos extremistas mu\u00e7ulmanos da chamada \u201clinha dura\u201d. Com apenas 3 deputados, os crist\u00e3os n\u00e3o ter\u00e3o, seguramente, uma voz activa no novo Parlamento. A Alian\u00e7a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44],"tags":[],"class_list":["post-6224","post","type-post","status-publish","format-standard","hentry","category-igreja"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/6224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=6224"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/6224\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=6224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=6224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=6224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}