{"id":6529,"date":"2006-04-03T14:44:00","date_gmt":"2006-04-03T14:44:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=6529"},"modified":"2006-04-03T14:44:00","modified_gmt":"2006-04-03T14:44:00","slug":"a-biblia-em-perguntas-e-respostas-13","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/a-biblia-em-perguntas-e-respostas-13\/","title":{"rendered":"A B\u00edblia em Perguntas e Respostas"},"content":{"rendered":"<p>1. O Evangelho de S. Lucas \u00e9 representado por um Touro, segundo a tradi\u00e7\u00e3o que se inspira em Ezequiel 1,10 e que atribui o le\u00e3o a S. Marcos, o homem (ou anjo) a S. Mateus e a \u00e1guia a S. Jo\u00e3o. Qual a explica\u00e7\u00e3o tradicional para o Evangelho de S. Lucas ser representado por um touro?<\/p>\n<p>a) porque o Evangelho come\u00e7a no templo, local onde se sacrificavam touros<\/p>\n<p>b) porque as palavras Lucas e touro, em grego, s\u00e3o muito parecidas<\/p>\n<p>c) n\u00e3o existe explica\u00e7\u00e3o<\/p>\n<p>d) porque \u00e9 o Evangelho que refere a presen\u00e7a de um touro (boi) no pres\u00e9pio, em Bel\u00e9m.<\/p>\n<p>2. Esa\u00fa, filho primog\u00e9nito de Isaac, um dia, regressando do campo muito cansado, troca com o seu irm\u00e3o Jacob o direito de primogenitura (direitos e privil\u00e9gios do filho mais velho, especialmente a sucess\u00e3o paterna e respectiva b\u00ean\u00e7\u00e3o) por&#8230;<\/p>\n<p>a) um prato de codornizes<\/p>\n<p>b) um prato de man\u00e1<\/p>\n<p>c) um guisado de lentilhas<\/p>\n<p>d) um guisado de carneiro.<\/p>\n<p>3. H\u00e1 pormenores na B\u00edblia que, sem significado aparente, d\u00e3o um toque muito humano aos relatos. Na sua vida de pregador itinerante, Jesus diz que \u201co Filho do Homem n\u00e3o tem uma pedra onde reclinar a cabe\u00e7a\u201d. No entanto, na passagem da tempestade acalmada, enquanto os disc\u00edpulos est\u00e3o com medo que o barco v\u00e1 ao fundo, Jesus dorme sobre&#8230;<\/p>\n<p>a) &#8230;uma almofada<\/p>\n<p>b) &#8230;uma pedra<\/p>\n<p>c) &#8230;o ombro de um disc\u00edpulo<\/p>\n<p>d) &#8230;um tronco.<\/p>\n<p>4. Os israelitas fogem da escravid\u00e3o do Egipto e entram no deserto. Com a aridez do deserto, vem a fome e a primeira queixa. Come\u00e7am ent\u00e3o a pensar que, se calhar, era prefer\u00edvel continuarem escravos, mas ao menos terem para comer&#8230;<\/p>\n<p>a) &#8230;o p\u00e3o do Egipto<\/p>\n<p>b) &#8230;as cebolas do Egipto<\/p>\n<p>c) &#8230;a carne do Egipto<\/p>\n<p>d) &#8230;as batatas do Egipto.<\/p>\n<p>Respostas<\/p>\n<p>1. a) Porque a narrativa evang\u00e9lica tem in\u00edcio no templo, onde Zacarias, pai de Jo\u00e3o Baptista, era sacerdote; e termina&#8230; no templo. \u201cEstavam continuamente no templo a bendizer a Deus\u201d, diz o \u00faltimo vers\u00edculo do Evangelho (Lc 24,53). E, de facto, no templo eram sacrificados animais.<\/p>\n<p>2. c) Um guisado de lentilhas. Pode ler o epis\u00f3dio em G\u00e9nesis 25,29-34.<\/p>\n<p>3. a) Uma almofada, pormenor apenas referido por S. Marcos. \u201cDesencadeou-se, ent\u00e3o, um grande turbilh\u00e3o de vento, e as ondas arrojavam-se contra o barco, de forma que este j\u00e1 estava quase cheio de \u00e1gua. Jesus, \u00e0 popa, dormia sobre uma almofada\u201d (Mc 4,37s).<\/p>\n<p>4. b) &#8230;a carne do Egipto. A queixa era esta: \u201cQuem dera que tiv\u00e9ssemos morrido pela m\u00e3o do Senhor na terra do Egipto, quando est\u00e1vamos descansados junto da panela da carne, quando com\u00edamos com fartura\u201d (Ex 16,3). Mais tarde, aparecem tamb\u00e9m as saudades das cebolas, mas a primeira queixa \u00e9 relativa \u00e0 \u201cpanela de carne\u201d. Quanto \u00e0s batatas, n\u00e3o s\u00e3o alimento b\u00edblico. Vieram da Am\u00e9rica do Sul, mas s\u00f3 na \u00e9poca dos Descobrimentos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>1. O Evangelho de S. Lucas \u00e9 representado por um Touro, segundo a tradi\u00e7\u00e3o que se inspira em Ezequiel 1,10 e que atribui o le\u00e3o a S. Marcos, o homem (ou anjo) a S. Mateus e a \u00e1guia a S. Jo\u00e3o. Qual a explica\u00e7\u00e3o tradicional para o Evangelho de S. Lucas ser representado por um [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-6529","post","type-post","status-publish","format-standard","hentry","category-desporto"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/6529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=6529"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/6529\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=6529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=6529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=6529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}