{"id":7641,"date":"2006-07-12T12:22:00","date_gmt":"2006-07-12T12:22:00","guid":{"rendered":"http:\/\/localhost:81\/wp1\/?p=7641"},"modified":"2006-07-12T12:22:00","modified_gmt":"2006-07-12T12:22:00","slug":"40-anos","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/cv\/40-anos\/","title":{"rendered":"40 anos"},"content":{"rendered":"<p>Ponta de Lan\u00e7a <!--more--> Falh\u00e1mos!<\/p>\n<p>No \u00faltimo n\u00famero perspectiv\u00e1vamos ser poss\u00edvel o t\u00edtulo de campe\u00f5es do mundo em futebol. Isso n\u00e3o aconteceu. Foi pena!<\/p>\n<p>A pena, o lamento com que se reveste esta aventura no mundial de futebol de 2006, na Alemanha, cont\u00e9m diversos factores caracter\u00edsticos do nosso \u201cser portugu\u00eas\u201d e do \u201cser humano\u201d, numa amplitude mais alargada.<\/p>\n<p>Alguns aspectos do ser portugu\u00eas, quer se queira quer n\u00e3o, de matriz cultural judaico-crist\u00e3, e com toda a influ\u00eancia das v\u00e1rias civiliza\u00e7\u00f5es que constru\u00edram o ocidente europeu, est\u00e3o tamb\u00e9m intrinsecamente ligados \u00e0s suas simbologias. \u00c9 o caso do quarenta. <\/p>\n<p>O n\u00famero quarenta figura como significado do tempo deste mundo. Pois quatro s\u00e3o as partes do mundo e quatro s\u00e3o tamb\u00e9m os elementos de que est\u00e1 constitu\u00edda toda a criatura vis\u00edvel. J\u00e1 o dez indica plenitude: tanto a do bem como a do mal. E dez por quatro d\u00e1 quarenta! <\/p>\n<p>O quarenta \u00e9 n\u00famero que representa misticamente a Antiga Lei e o Evangelho. Quarenta \u00e9 o n\u00famero da perman\u00eancia no deserto. O salmista (Sl 94,10) refere tamb\u00e9m: \u201cDurante quarenta anos desgostou-me aquela gera\u00e7\u00e3o\u201d; e, no dil\u00favio, foi por esse n\u00famero de dias e de noites que Deus fez chover sobre a terra. E no livro de Jonas (3,4) est\u00e1 escrito: \u201cDaqui a quarenta dias, N\u00ednive ser\u00e1 destru\u00edda\u201d, o que n\u00e3o chegou a ocorrer com aquela cidade, mas na apocal\u00edptica ocorrer\u00e1 com o mundo por ela figurado. Quarenta s\u00e3o as gera\u00e7\u00f5es de Abra\u00e3o a Jesus Cristo. No Evangelho de Mateus (Mt 4,1) e sin\u00f3pticos o Senhor \u201cfoi conduzido pelo Esp\u00edrito ao deserto por quarenta dias\u201d. Representa tamb\u00e9m a Ressurrei\u00e7\u00e3o do Jesus, pois est\u00e1 escrito em Actos (1,3) que \u201capareceu-lhes durante quarenta dias\u201d. <\/p>\n<p>Ou seja, terminado o mundial de futebol\u2026 daqui a quarenta anos, depois de 66 e 2006, voltaremos a fazer figura!? \u00c9 sina?! <\/p>\n<p>Desportivamente\u2026 pelo desporto!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ponta de Lan\u00e7a<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-7641","post","type-post","status-publish","format-standard","hentry","category-desporto"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/7641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/comments?post=7641"}],"version-history":[{"count":0,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/posts\/7641\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/media?parent=7641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/categories?post=7641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/cv\/wp-json\/wp\/v2\/tags?post=7641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}