{"id":1596446576,"date":"2013-11-01T00:00:00","date_gmt":"2013-11-01T00:00:00","guid":{"rendered":"https:\/\/www.educris.com\/v3\/326-vaticano\/10440-papa-francisco-pede-estilo-de-deus-aos-novos-sacerdotes"},"modified":"2025-11-07T16:34:40","modified_gmt":"2025-11-07T16:34:40","slug":"papa-francisco-pede-estilo-de-deus-aos-novos-sacerdotes","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/educris\/papa-francisco-pede-estilo-de-deus-aos-novos-sacerdotes\/","title":{"rendered":"Papa Francisco pede \u00abestilo de Deus\u00bb aos novos sacerdotes"},"content":{"rendered":"<p class=\"img\"><img decoding=\"async\" src=\"https:\/\/sites.ecclesia.pt\/educris\/imagens\/papa_ordenacos_2021_210425080701.jpeg\" \/><\/p>\n<p><p><em>Francisco ordenou hoje nove novos padres para a igreja de Roma e recomendou uma \u201cvida ao estilo de Deus\u201d, na \u201cproximidade, compaix\u00e3o e ternura\u201d. O Papa sustentou que o sacerd\u00f3cio &#8220;n\u00e3o \u00e9 uma carreira, mas um servi\u00e7o&#8221;<\/em><\/p>\n<p>Leia, na \u00edntegra, a homilia do Santo Padre<\/p>\n<p>Queridos irm\u00e3os, estes nossos filhos foram chamados \u00e0 ordem do presbiterato. Reflitamos, cuidadosamente, sobre o minist\u00e9rio que eles ser\u00e3o elevados na Igreja.<\/p>\n<p>Como voc\u00eas sabem, irm\u00e3os, o Senhor Jesus \u00e9 o \u00fanico sumo sacerdote do Novo Testamento; mas nele tamb\u00e9m todo o povo santo de Deus foi constitu\u00eddo um povo sacerdotal. No entanto, entre todos os seus disc\u00edpulos, o Senhor Jesus quis escolher alguns em particular, para que, exercendo publicamente o of\u00edcio sacerdotal na Igreja, em seu nome em favor de todos os homens, continuassem a sua miss\u00e3o pessoal de mestre, sacerdote e pastor.<\/p>\n<p>Depois de uma reflex\u00e3o madura, vamos agora elevar estes irm\u00e3os \u00e0 ordem dos sacerdotes, para que no servi\u00e7o a Cristo mestre, sacerdote e pastor, cooperem na edifica\u00e7\u00e3o do corpo de Cristo, que \u00e9 a Igreja, no povo de Deus e no santo templo do Esp\u00edrito.<\/p>\n<p>Quanto a v\u00f3s, amados filhos, que estais em vias de ser admitidos \u00e0 ordem do presbiterato, considerai que, exercendo o minist\u00e9rio da sagrada doutrina, participareis na miss\u00e3o de Cristo, o \u00fanico Mestre. V\u00f3s sereis pastores como ele, \u00e9 isso que ele quer de v\u00f3s. Pastores. Pastores do santo povo fiel de Deus. Pastores que caminham com o povo de Deus: por vezes diante do rebanho, por vezes no meio ou atr\u00e1s, mas sempre ali, com o povo de Deus.<\/p>\n<p>Antigamente &#8211; na linguagem do passado &#8211; falava-se da &#8220;carreira eclesi\u00e1stica&#8221;, que n\u00e3o tinha o mesmo significado que hoje det\u00e9m. N\u00e3o se trata de uma &#8220;carreira&#8221;: \u00e9 um servi\u00e7o, um servi\u00e7o como o que Deus fez ao seu povo. E esse servi\u00e7o de Deus ao seu povo tem &#8220;tra\u00e7os&#8221;, tem um estilo, um estilo que v\u00f3s deveis seguir. Estilo de proximidade, estilo de compaix\u00e3o e estilo de ternura. Este \u00e9 o estilo de Deus: proximidade, compaix\u00e3o, ternura.<\/p>\n<p>A proximidade. S\u00e3o quatro as proximidades do padre. Proximidade com Deus na ora\u00e7\u00e3o, nos sacramentos, na Missa. Falar com o Senhor, estar pr\u00f3ximo do Senhor. Ele que se fez pr\u00f3ximo a n\u00f3s no seu Filho. Toda a hist\u00f3ria do seu filho. Ele tamb\u00e9m esteve perto de ti, de cada um de v\u00f3s, no caminho da vossa vida at\u00e9 este momento. Mesmo nos tempos dif\u00edceis de pecado, ele estava l\u00e1. Proximidade. Sede pr\u00f3ximos do santo povo fiel de Deus. Mas antes de tudo perto de Deus, com a ora\u00e7\u00e3o. Um padre que n\u00e3o reza lentamente apaga o fogo do Esp\u00edrito dentro de si. Proximidade com Deus.<\/p>\n<p>\u00a0<\/p>\n<p>Segundo: proximidade ao Bispo e, neste caso, com o &#8220;auxiliar&#8221;. Ficai perto, porque no Bispo ids encontrar a unidade. V\u00f3s sois, n\u00e3o quero dizer servos \u2013 sede servidores de Deus &#8211; mas colaboradores do Bispo. Proximidade. Lembro-me de uma vez, h\u00e1 muito tempo, de um padre que teve o azar &#8211; por assim dizer &#8211; de \u201cescorregar\u201d &#8230; A primeira coisa que pensou foi chamar o Bispo. Mesmo nos momentos dif\u00edceis, chama o Bispo para ficar perto dele. Proximidade com Deus na ora\u00e7\u00e3o, proximidade com o Bispo. \u201cMas eu n\u00e3o gosto deste bispo\u2026\u201d. Mas ele \u00e9 o teu pai. &#8220;Mas este bispo trata-me mal &#8230;&#8221;. Sede humilde, e ide ter com o Bispo.<\/p>\n<p>Terceiro: proximidade entre v\u00f3s. E sugiro-lhes uma resolu\u00e7\u00e3o a tomar neste dia: nunca faleis mal de um irm\u00e3o sacerdote. Se tendes algo contra o outro, sede homens, tendes cal\u00e7as: ide ter com ele e dizei-lho na cara. &#8220;Mas isso \u00e9 d uma brutalidade\u2026 n\u00e3o sei como vai reagir &#8230;&#8221;. Ide ter com o Bispo, que te ajuda. Mas nunca, nunca fa\u00e7ais coscuvilhices. N\u00e3o sejais coscuvilheiros. \u00a0N\u00e3o caiais no mal dizer. Unidade entre v\u00f3s: no conselho presbiteral, nas comiss\u00f5es, no trabalho. Proximidade entre v\u00f3s e o Bispo.<\/p>\n<p>E quarto: para mim, depois de Deus, a proximidade mais importante \u00e9 para com o fiel povo santo de Deus, nenhum de v\u00f3s estudou para ser sacerdote. Estudastes as ci\u00eancias eclesi\u00e1sticas, como a Igreja diz que deve ser feito. Mas fostes eleitos, retirados do povo de Deus. O Senhor disse a David: &#8220;Eu tirei o rebanho de ti&#8221;. N\u00e3o te esque\u00e7as de onde vieste: da tua fam\u00edlia, do teu povo &#8230; N\u00e3o percas o sentido do povo de Deus. Paulo disse a Tim\u00f3teo: &#8220;Lembra-te da tua m\u00e3e, da tua av\u00f3 &#8230;&#8221;. Sim, de onde viestes. E aquele povo de Deus &#8230; Diz o autor da Carta aos Hebreus: \u00abLembrai-vos daqueles que vos introduziram na f\u00e9\u00bb. Padres do povo, n\u00e3o cl\u00e9rigos de Estado!<\/p>\n<p>A quatro proximidades do sacerdote: proximidade com Deus, proximidade com o Bispo, proximidade entre v\u00f3s, proximidade com o povo de Deus. O estilo de proximidade que \u00e9 o estilo de Deus. Mas o estilo de Deus \u00e9 tamb\u00e9m um estilo de compaix\u00e3o e de ternura. N\u00e3o fecheis o vosso cora\u00e7\u00e3o aos problemas. E vereis tantos! Quando as pessoas v\u00eam para contar os seus problemas e para serem acompanhadas &#8230; perdei tempo ouvindo e consolando. Compaix\u00e3o, que leva ao perd\u00e3o, \u00e0 miseric\u00f3rdia. Por favor: sede misericordiosos, perdoai. Porque Deus tudo perdoa, nunca se cansa de perdoar, somos n\u00f3s que nos cansamos de pedir perd\u00e3o. Proximidade e compaix\u00e3o. Mas terna compaix\u00e3o, com aquela ternura de fam\u00edlia, de irm\u00e3os, de pai &#8230; com aquela ternura que te faz sentir que est\u00e1s na casa de Deus.<\/p>\n<p>Desejo para v\u00f3s este estilo, este estilo que \u00e9 o estilo de Deus.<\/p>\n<p>Por fim, na sacristia disse-vos algo que gostaria de dizer agora, diante de falar aqui diante do povo de Deus. Por favor, afastai-vos da vaidade, do orgulho do dinheiro. O diabo entra &#8220;pelos bolsos&#8221;. Pensai sobre isto. Sede pobres, porque s\u00e3o pobres os santos fi\u00e9is de Deus, pobres que amam os pobres. N\u00e3o sejais alpinistas. \u00a0A &#8220;carreira eclesi\u00e1stica&#8221; &#8230; A\u00ed vos tornareis um funcion\u00e1rio, e quando um sacerdote come\u00e7a a ser empres\u00e1rio, tanto na par\u00f3quia quanto na escola &#8230;, onde quer que esteja, perde aquela proximidade com o povo, perde aquela pobreza que o torna semelhante a Cristo pobre e crucificado, e torna-se empres\u00e1rio, empres\u00e1rio sacerdote e n\u00e3o servo. Ouvi uma hist\u00f3ria que me emocionou. Um padre muito inteligente, muito pr\u00e1tico, muito capaz, que tinha muitas administra\u00e7\u00f5es nas m\u00e3os, um dia ficou com o cora\u00e7\u00e3o apegado \u00e0quele of\u00edcio, porque viu que um dos seus funcion\u00e1rios, um homem idoso, cometeu um erro, e repreende-o, expulsando-o. E aquele anci\u00e3o morreu por causa disto. Este homem foi ordenado sacerdote e acabou como um empres\u00e1rio implac\u00e1vel. Tende sempre esta imagem, tende sempre esta imagem.<\/p>\n<p>Pastores pr\u00f3ximos de Deus, do Bispo, entre v\u00f3s e do povo de Deus. Pastores: servos como pastores, n\u00e3o empres\u00e1rios. E ficai longe do dinheiro.<\/p>\n<p>E ent\u00e3o, lembrai-vos que este caminho das quatro proximidades \u00e9 bela, esta estrada de ser pastores, porque Jesus conforta os pastores, porque Ele \u00e9 o Bom Pastor. E buscai consolo em Jesus, buscai consolo em Nossa Senhora &#8211; n\u00e3o vos esque\u00e7ais da M\u00e3e &#8211; buscai sempre consolo ali: ser consolado a\u00ed.<\/p>\n<p>E carregai as cruzes &#8211; haver\u00e1 algumas na nossa vida &#8211; nas m\u00e3os de Jesus e de Nossa Senhora. E n\u00e3o tenhais medo, n\u00e3o tenhais medo. Se est\u00e1s perto do Senhor, do Bispo, entre v\u00f3s e do povo de Deus, se tendes o estilo de Deus &#8211; proximidade, compaix\u00e3o e ternura &#8211; n\u00e3o tenhais medo, que tudo ficar\u00e1 bem.<\/p>\n<p>Tradu\u00e7\u00e3o Educris a partir do <a href=\"https:\/\/www.vatican.va\/content\/francesco\/it\/events\/event.dir.html\/content\/vaticanevents\/it\/2021\/4\/25\/ordinazioni-sacerdotali.html\" target=\"_blank\">original em italiano<\/a><\/p>\n<p>Imagem: Vatican Media<\/p>\n<p>25.04.2021<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Francisco ordenou hoje nove novos padres para a igreja de Roma e recomendou uma \u201cvida ao estilo de Deus\u201d, na [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2451316210,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[5],"tags":[64],"class_list":["post-1596446576","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-vaticano"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/posts\/1596446576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/comments?post=1596446576"}],"version-history":[{"count":1,"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/posts\/1596446576\/revisions"}],"predecessor-version":[{"id":4294995944,"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/posts\/1596446576\/revisions\/4294995944"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/media\/2451316210"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/media?parent=1596446576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/categories?post=1596446576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/tags?post=1596446576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}