{"id":3595519656,"date":"2013-09-20T16:55:41","date_gmt":"2013-09-20T16:55:41","guid":{"rendered":"https:\/\/www.educris.com\/v3\/44-destaques\/3569-programa-da-semana-nacional-2013"},"modified":"2025-11-03T13:18:33","modified_gmt":"2025-11-03T13:18:33","slug":"programa-da-semana-nacional-2013-2","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/educris\/programa-da-semana-nacional-2013-2\/","title":{"rendered":"Programa da Semana Nacional 2013"},"content":{"rendered":"<p class=\"img\"><img decoding=\"async\" src=\"https:\/\/sites.ecclesia.pt\/educris\/imagens\/educris2_130923032023.jpg\" \/><\/p>\n<p>De 29 de setembro a 6 de outubro decorre a Semana Nacional da Educa\u00e7\u00e3o Crist\u00e3. Esta iniciativa, da Comiss\u00e3o Episcopal da Educa\u00e7\u00e3o Crist\u00e3 e Doutrina da F\u00e9 (CEEDF) pretende, ano ap\u00f3s ano, mostrar o que se vai fazendo no pa\u00eds nesta \u00e1rea t\u00e3o importante.<\/p>\n<p>Para a ocasi\u00e3o a CEEDF redigiu uma Nota Pastoral intitulada <a href=\"https:\/\/www.educris.com\/v2\/centrorecursos\/outras\/noticias\/1299-guarda-a-fe-guardar-o-outro\">&#8220;Guardar a F\u00e9 -Guardar o outro<\/a>&#8221; e que d\u00e1 tamb\u00e9m o mote para o tema da Semana Nacional 2013<\/p>\n<p><strong>Programa Completo da Semana Nacional 2013<\/strong><\/p>\n<p align=\"left\"><em>29 de setembro<\/em><\/p>\n<p align=\"left\">11.00 h \u2013<strong><span style=\"color: #231f20; font-family: Calibri-Bold; font-size: small;\"><span style=\"color: #231f20; font-family: Calibri-Bold; font-size: small;\"><span style=\"color: #231f20; font-family: Calibri-Bold; font-size: small;\">Celebra\u00e7\u00e3o Eucar\u00edstica, <\/span><\/span><\/span><\/strong><span style=\"color: #231f20; font-family: Calibri; font-size: small;\"><span style=\"color: #231f20; font-family: Calibri; font-size: small;\"><span style=\"color: #231f20; font-family: Calibri; font-size: small;\">transmitida da Igreja da Par\u00f3quia do Cartaxo, (diocese de<\/span><\/span><\/span><\/p>\n<p align=\"left\">Santar\u00e9m), pela TVI \u2013<strong><span style=\"color: #231f20; font-family: Calibri-Bold; font-size: small;\"><span style=\"color: #231f20; font-family: Calibri-Bold; font-size: small;\"><span style=\"color: #231f20; font-family: Calibri-Bold; font-size: small;\">presidida por D. Manuel Pelino Domingues<\/span><\/span><\/span><\/strong><\/p>\n<p align=\"left\">12.15 h \u2013 Programa <strong><span style=\"color: #231f20; font-family: Calibri-Bold; font-size: small;\"><span style=\"color: #231f20; font-family: Calibri-Bold; font-size: small;\"><span style=\"color: #231f20; font-family: Calibri-Bold; font-size: small;\">8\u00ba Dia <\/span><\/span><\/span><\/strong><span style=\"color: #231f20; font-family: Calibri; font-size: small;\"><span style=\"color: #231f20; font-family: Calibri; font-size: small;\"><span style=\"color: #231f20; font-family: Calibri; font-size: small;\">(TVI)<\/span><\/span><\/span><\/p>\n<p align=\"left\"><em>4 a 6 de outubro<\/em><\/p>\n<p align=\"left\"><a href=\"https:\/\/www.educris.com\/v2\/catequese\/3557-jnc-2013-chamados-a-salvacao-pela-fe-em-jesus-cristo\" target=\"_blank\" rel=\"noopener\">Jornadas Nacionais de Catequistas<\/a> <span style=\"color: #231f20; font-family: Calibri; font-size: small;\"><span style=\"color: #231f20; font-family: Calibri; font-size: small;\"><span style=\"color: #231f20; font-family: Calibri; font-size: small;\">\u2013 Centro Pastoral Paulo VI, em F\u00e1tima<\/span><\/span><\/span><\/p>\n<p align=\"left\"><em>5 de outubro<\/em><\/p>\n<p align=\"left\">Jornada Nacional das Escolas Cat\u00f3licas \u201c<a href=\"https:\/\/www.educris.com\/v2\/escolas-catolicas\/3466-apec-partilhar-e-urgente\" target=\"_blank\" rel=\"noopener\">Partilhar \u00e9 Urgente<\/a>\u201d<\/p>\n<p align=\"left\"><span style=\"color: #231f20; font-family: Calibri; font-size: small;\"><span style=\"color: #231f20; font-family: Calibri; font-size: small;\"><span style=\"color: #231f20; font-family: Calibri; font-size: small;\">(<\/span><\/span><\/span>recolha de produtos em superf\u00edcies comerciaisa favor de fam\u00edlias carenciadas) em colabora\u00e7\u00e3o com a APEC &#8211; Associa\u00e7\u00e3o Portuguesa de Escolas Cat\u00f3licas e a C\u00e1ritas Portuguesa<\/p>\n<p align=\"left\"><em>6 de outubro<\/em><\/p>\n<p align=\"left\">11.00 h \u2013<strong><span style=\"color: #231f20; font-family: Calibri-Bold; font-size: small;\"><span style=\"color: #231f20; font-family: Calibri-Bold; font-size: small;\"><span style=\"color: #231f20; font-family: Calibri-Bold; font-size: small;\">Celebra\u00e7\u00e3o Eucar\u00edstica <\/span><\/span><\/span><\/strong><span style=\"color: #231f20; font-family: Calibri; font-size: small;\"><span style=\"color: #231f20; font-family: Calibri; font-size: small;\"><span style=\"color: #231f20; font-family: Calibri; font-size: small;\">(encerramento da Semana) transmitida da Igreja Paroquial de<\/span><\/span><\/span><\/p>\n<p align=\"left\">Unhos (Patriarcado de Lisboa) pela R\u00e1dio Renascen\u00e7a \u2013<strong><span style=\"color: #231f20; font-family: Calibri-Bold; font-size: small;\"><span style=\"color: #231f20; font-family: Calibri-Bold; font-size: small;\"><span style=\"color: #231f20; font-family: Calibri-Bold; font-size: small;\">presidida por D. Nuno Br\u00e1s da Silva Martins<\/span><\/span><\/span><\/strong><\/p>\n<p><strong><em>Ao longo da semana<\/em><\/strong><\/p>\n<p>No \u00e2mbito da EMRC e perspetivando a aten\u00e7\u00e3o aos que mais precisam, ao longo do ano letivo, ser\u00e3o apresentadas \u00e0s escolas propostas que desenvolvem a ideia de \u201cguardi\u00e3o\u201d do outro, no sentido que lhe deu o Papa Francisco na sua homilia de 19 de mar\u00e7o de 2013, e se concretizam em atividades que envolvam e comprometam os diversos membros da comunidade educativa de cada escola.<\/p>\n<p>Aceda \u00e0s propostas da disciplina <a href=\"https:\/\/www.educris.com\/v2\/emrc\/3572-propostas-emrc-para-a-semana-nacional-2013\" target=\"_blank\" rel=\"noopener\">aqui<\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De 29 de setembro a 6 de outubro decorre a Semana Nacional da Educa\u00e7\u00e3o Crist\u00e3. Esta iniciativa, da Comiss\u00e3o Episcopal [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":984106853,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[5],"tags":[49],"class_list":["post-3595519656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-emrc"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/posts\/3595519656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/comments?post=3595519656"}],"version-history":[{"count":1,"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/posts\/3595519656\/revisions"}],"predecessor-version":[{"id":4294991739,"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/posts\/3595519656\/revisions\/4294991739"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/media\/984106853"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/media?parent=3595519656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/categories?post=3595519656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/tags?post=3595519656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}