{"id":423908576,"date":"2013-11-01T00:00:00","date_gmt":"2013-11-01T00:00:00","guid":{"rendered":"https:\/\/www.educris.com\/v3\/326-vaticano\/9028-angelus-discricao-e-temperanca-nas-comunidades-a-exemplo-de-maria"},"modified":"2025-11-07T16:34:35","modified_gmt":"2025-11-07T16:34:35","slug":"angelus-discricao-e-temperanca-nas-comunidades-a-exemplo-de-maria","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/educris\/angelus-discricao-e-temperanca-nas-comunidades-a-exemplo-de-maria\/","title":{"rendered":"\u00c2ngelus: \u00abDiscri\u00e7\u00e3o e temperan\u00e7a\u00bb nas comunidades a exemplo de Maria"},"content":{"rendered":"<p class=\"img\"><img decoding=\"async\" src=\"https:\/\/sites.ecclesia.pt\/educris\/imagens\/papa_angelus_1_150201125427-1.jpg\" \/><\/p>\n<p><p><strong><em>Na solenidade da Imaculada Concei\u00e7\u00e3o o Papa Francisco recordou o exemplo de servi\u00e7o da &#8220;toda bela&#8221; m\u00e3e do &#8220;Mestre&#8221; e convidou os fi\u00e9is a seguirem o exemplo de &#8220;Discri\u00e7\u00e3o e temperan\u00e7a&#8221; da &#8220;toda santa&#8221; para &#8220;todas as comunidades crist\u00e3s&#8221;.<\/em><\/strong><\/p>\n<p>Leia, na \u00edntegra, a alocus\u00e3o do Santo Padre.<\/p>\n<p>\u00a0<\/p>\n<p>Queridos irm\u00e3os e irm\u00e3s, bom dia!<\/p>\n<p>Hoje celebramos a solenidade de Maria Imaculada, que \u00e9 colocada no contexto do Advento, um tempo de espera: Deus cumprir\u00e1 o que prometeu. Mas na celebra\u00e7\u00e3o de hoje \u00e9-nos anunciado que algo j\u00e1 foi realizado, na pessoa e na vida da Virgem Maria. Hoje consideramos o in\u00edcio desta realiza\u00e7\u00e3o, que est\u00e1 ainda antes do nascimento da M\u00e3e do Senhor. De facto, a sua concep\u00e7\u00e3o imaculada leva-nos ao momento preciso em que a vida de Maria come\u00e7ou a palpitar no ventre de sua m\u00e3e: j\u00e1 havia o amor santificador de Deus, preservando-a do cont\u00e1gio do mal, que \u00e9 uma heran\u00e7a comum da fam\u00edlia humana.<\/p>\n<p>No Evangelho de hoje ressoa a sauda\u00e7\u00e3o do anjo a Maria: \u00abAlegra-te cheia de gra\u00e7a: o Senhor est\u00e1 contigo\u00bb (Lc 1, 28). Deus sempre pensou e desejou, em seu des\u00edgnio inescrut\u00e1vel, uma criatura cheia de gra\u00e7a, cheia do seu amor. Mas, para ser preenchido \u00e9 necess\u00e1rio deixar espa\u00e7o, esvaziar-se, p\u00f4r-se \u00e0 parte. Assim como Maria, que sabia ouvir a Palavra de Deus e confiar totalmente na sua vontade, aceitando-a sem reservas na sua vida. Tanto \u00e9 assim que nela a Palavra se tornou carne. Isto foi poss\u00edvel gra\u00e7as ao seu \u2018sim\u2019. Ao anjo que pede a sua disponibilidade para ser m\u00e3e de Jesus, Maria responde: \u00abEis a serva do Senhor; fa\u00e7a-se para mim segundo a tua palavra\u00bb (v. 38).<\/p>\n<p>Maria n\u00e3o se perde em tantos argumentos, n\u00e3o coloca obst\u00e1culos ao caminho do Senhor, mas confia rapidamente e deixa espa\u00e7o para a a\u00e7\u00e3o do Esp\u00edrito Santo. Subitamente coloca-se \u00e0 disposi\u00e7\u00e3o de Deus com todo o seu ser e a sua hist\u00f3ria pessoal, para que a Palavra e a vontade de Deus possam mold\u00e1-la e complet\u00e1-la. Assim, correspondendo perfeitamente ao plano de Deus para ela, Maria torna-se a &#8220;toda bela&#8221;, a &#8220;toda santa&#8221;, mas sem o menor ind\u00edcio de complac\u00eancia. Ela \u00e9 humilde. Ela \u00e9 uma obra-prima, mas permanece humilde, pequena, pobre. Nela se reflete a beleza de Deus, que \u00e9 todo amor, gra\u00e7a, doa\u00e7\u00e3o.<\/p>\n<p>Tamb\u00e9m gosto de enfatizar a palavra com que Maria se define na sua rendi\u00e7\u00e3o a Deus: professa-se &#8220;a serva do Senhor&#8221;. O &#8220;sim&#8221; de Maria a Deus assume desde o princ\u00edpio a atitude de servi\u00e7o, de aten\u00e7\u00e3o \u00e0s necessidades dos outros. Testemunha-o concretamente o acontecimento da sua visita a Isabel, que se segue imediatamente ao epis\u00f3dio da anuncia\u00e7\u00e3o. A disponibilidade para Deus \u00e9 encontrada na disposi\u00e7\u00e3o de atender \u00e0s necessidades dos outros. Tudo isto sem clamor e ostenta\u00e7\u00e3o, sem buscar lugares de honra, sem publicidade, porque a caridade e as obras de miseric\u00f3rdia n\u00e3o precisam de ser exibidas como trof\u00e9u. As obras de miseric\u00f3rdia s\u00e3o feitas em sil\u00eancio, em segredo, sem se gabar por t\u00ea-las feito. Mesmo nas nossas comunidades, somos chamados a seguir o exemplo de Maria, praticando o estilo de discri\u00e7\u00e3o e temperan\u00e7a.<\/p>\n<p>A festa de nossa M\u00e3e ajuda-nos a tornar toda a nossa vida um \u2018sim\u2019 a Deus, um \u2018sim\u2019 feito de adora\u00e7\u00e3o a Ele e gestos di\u00e1rios de amor e servi\u00e7o.<\/p>\n<p>Tradu\u00e7\u00e3o Educris a partir do <a href=\"http:\/\/w2.vatican.va\/content\/francesco\/it\/angelus\/2019\/documents\/papa-francesco_angelus_20191208.html\" target=\"_blank\">original em italiano<\/a><\/p>\n<p>08.09.2019<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na solenidade da Imaculada Concei\u00e7\u00e3o o Papa Francisco recordou o exemplo de servi\u00e7o da &#8220;toda bela&#8221; m\u00e3e do &#8220;Mestre&#8221; e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4294987888,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[5],"tags":[64],"class_list":["post-423908576","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-vaticano"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/posts\/423908576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/comments?post=423908576"}],"version-history":[{"count":1,"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/posts\/423908576\/revisions"}],"predecessor-version":[{"id":4294995815,"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/posts\/423908576\/revisions\/4294995815"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/media\/4294987888"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/media?parent=423908576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/categories?post=423908576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/educris\/wp-json\/wp\/v2\/tags?post=423908576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}