{"id":4079,"date":"2020-04-28T18:45:37","date_gmt":"2020-04-28T18:45:37","guid":{"rendered":"http:\/\/sites.ecclesia.pt\/ocpm\/?p=4079"},"modified":"2020-04-28T18:45:37","modified_gmt":"2020-04-28T18:45:37","slug":"covid-19-pascoa-dos-emigrantes-no-luxemburgo-vivida-na-fidelidade-a-tradicoes-de-portugal-c-video","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/ocpm\/covid-19-pascoa-dos-emigrantes-no-luxemburgo-vivida-na-fidelidade-a-tradicoes-de-portugal-c-video\/","title":{"rendered":"Covid-19: P\u00e1scoa dos emigrantes no Luxemburgo vivida na \u00abfidelidade\u00bb a tradi\u00e7\u00f5es de Portugal (c\/v\u00eddeo)"},"content":{"rendered":"<p><em>Padre Rui Pedro, na Miss\u00e3o Cat\u00f3lica de\u00a0L\u00edngua Portuguesa, tra\u00e7a a realidade vivida neste tempo pascal em isolamento<\/em><\/p>\n<p>Lisboa, 14 abr 2020 (Ecclesia) \u2013 O respons\u00e1vel pela Miss\u00e3o Cat\u00f3lica de L\u00edngua Portuguesa do Sul do Luxemburgo disse \u00e0 Ag\u00eancia ECCLESIA que os emigrantes celebraram a P\u00e1scoa em isolamento social, sem visitar as terras de origem e na \u201cfidelidade\u201d a tradi\u00e7\u00f5es pascais de Portugal.<\/p>\n<p>\u201cVemos mais uma vez a grande ousadia dos nossos emigrantes, que mostram a sua fidelidade \u00e0 sua f\u00e9 e n\u00e3o t\u00eam vergonha em mostrar que s\u00e3o crist\u00e3os! E este ano houve uma multiplica\u00e7\u00e3o de cruzes, de diferentes materiais e diferentes cores, uma aut\u00eantica beleza\u201d, disse \u00e0 Ag\u00eancia ECCLESIA Padre Rui Pedro.<\/p>\n<p>Devido \u00e0 pandemia Covid-19 os emigrantes portugueses viram-se impedidos de passar a \u00e9poca da P\u00e1scoa em Portugal, onde \u201cmuitos s\u00e3o mordomos e ajudam nas tradi\u00e7\u00f5es pascais\u201d, lembrou o sacerdote\u00a0scalabriniano e \u00e9 o respons\u00e1vel pela Miss\u00e3o Cat\u00f3lica de\u00a0L\u00edngua Portuguesa do Sul do Luxemburgo, com sede em Esch-sur-Alzette.<\/p>\n<p>\u201cEste isolamento social em tempo de Quaresma, tempo de vivacidade com muitas celebra\u00e7\u00f5es, pegou-nos em intensa atividade, importante para as pessoas. Aqui grande parte das pessoas que pertencem a esta comunidade s\u00e3o do norte de Portugal e, por exemplo, este ano todos colocavam imagens do compasso pascal nas redes sociais\u201d, refere.<\/p>\n<p><a href=\"https:\/\/sites.ecclesia.pt\/ocpm\/wp-content\/uploads\/Pascoa_Luxemburgo1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-4085\" src=\"https:\/\/sites.ecclesia.pt\/ocpm\/wp-content\/uploads\/Pascoa_Luxemburgo1.jpg\" alt=\"\" width=\"215\" height=\"160\" \/><\/a>\u00a0\u00a0 <a href=\"https:\/\/sites.ecclesia.pt\/ocpm\/wp-content\/uploads\/Pascoa_Luxemburgo2.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-4086\" src=\"https:\/\/sites.ecclesia.pt\/ocpm\/wp-content\/uploads\/Pascoa_Luxemburgo2.png\" alt=\"\" width=\"279\" height=\"157\" \/><\/a>\u00a0\u00a0 <a href=\"https:\/\/sites.ecclesia.pt\/ocpm\/wp-content\/uploads\/Pascoa_Luxemburgo3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4087 alignnone\" src=\"https:\/\/sites.ecclesia.pt\/ocpm\/wp-content\/uploads\/Pascoa_Luxemburgo3.jpg\" alt=\"\" width=\"199\" height=\"169\" \/><\/a><\/p>\n<p>Um tempo de P\u00e1scoa diferente para todos onde esta comunidade do sul do Luxemburgo conta com 400 crian\u00e7as na catequese, viveram uma \u201cinterrup\u00e7\u00e3o muito brusca\u201d e os catequistas tentam \u201catrav\u00e9s das redes sociais manter contacto com os pais\u201d, com novas propostas.<\/p>\n<p>\u201cPenso que, se no Natal se fazia o pres\u00e9pio, agora talvez vamos fazer com as crian\u00e7as o calv\u00e1rio, um h\u00e1bito que n\u00e3o t\u00ednhamos\u201d, aponta o religioso.<\/p>\n<p>O padre Rui Pedro falou ainda da realidade das pessoas que vivem mais isoladas, e que a \u201cintensifica\u00e7\u00e3o de contactos por email e pelo telefone\u201d se foi concretizando.<\/p>\n<p>\u201cVivemos sempre em comunh\u00e3o com todos; a Igreja continua aberta mas sem celebra\u00e7\u00f5es; \u00a0t\u00ednhamos um grupo de missa di\u00e1ria e v\u00e3o \u00e0s igrejas que est\u00e3o abertas e temos colocado uma mesa com livros para as pessoas levar e se possam cultivar na f\u00e9\u201d, conta.<\/p>\n<p>Tamb\u00e9m as transmiss\u00f5es atrav\u00e9s da televis\u00e3o portuguesa foram importantes para esta comunidade \u201cque conseguiu parar para participar, sentar no sof\u00e1 ou na cadeira e acompanhar a missa\u201d.<\/p>\n<p>\u201cNeste tr\u00edduo pascal acompanharam as celebra\u00e7\u00f5es onde se percebeu uma grande inten\u00e7\u00e3o de dar beleza \u00e0s celebra\u00e7\u00f5es, foram muito sentidas e multiplicadas nas redes sociais pelos nossos emigrantes\u201d, destacou.<\/p>\n<p>O sacerdote da Congrega\u00e7\u00e3o Mission\u00e1ria de S\u00e3o Carlos adiantou ainda que o tempo de isolamento tem sido desafiante e uma descoberta para a pr\u00f3pria comunidade que assumiu tr\u00eas atitudes: a comunh\u00e3o, atrav\u00e9s das partilhas em redes sociais, a comunica\u00e7\u00e3o, na intensifica\u00e7\u00e3o de envio de emails e contactos telef\u00f3nicos e ainda a ora\u00e7\u00e3o.<\/p>\n<p><em>\u201cAqui na comunidade somos quatro sacerdotes, que estamos a celebrar sem o povo. Saibam que estamos em ora\u00e7\u00e3o e rezamos por eles, pelas fam\u00edlias e os filhos, se j\u00e1 a realidade dos emigrantes \u00e9 as fam\u00edlias estarem separadas, agora aqui aumentou a separa\u00e7\u00e3o\u201d, constatou.<\/em><\/p>\n<p>O padre Rui Pedro acrescentou ainda que tem sido um \u201cmomento desafiante\u201d para a comunidade de religiosos, com \u201ctempos de ora\u00e7\u00e3o mais sossegado\u201d, trazendo para as \u201ccelebra\u00e7\u00f5es as inten\u00e7\u00f5es que s\u00e3o enviadas por email\u201d.<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"YSxi6gfcr2\"><p><a href=\"https:\/\/agencia.ecclesia.pt\/portal\/covid-19-pascoa-dos-emigrantes-no-luxemburgo-vivida-na-fidelidade-a-tradicoes-de-portugal-c-video\/\">Covid-19: P\u00e1scoa dos emigrantes no Luxemburgo vivida na \u00abfidelidade\u00bb a tradi\u00e7\u00f5es de Portugal (c\/v\u00eddeo)<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" title=\"&#8220;Covid-19: P\u00e1scoa dos emigrantes no Luxemburgo vivida na \u00abfidelidade\u00bb a tradi\u00e7\u00f5es de Portugal (c\/v\u00eddeo)&#8221; &#8212; Ag\u00eancia ECCLESIA\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/covid-19-pascoa-dos-emigrantes-no-luxemburgo-vivida-na-fidelidade-a-tradicoes-de-portugal-c-video\/embed\/#?secret=YSxi6gfcr2\" data-secret=\"YSxi6gfcr2\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Padre Rui Pedro, na Miss\u00e3o Cat\u00f3lica de\u00a0L\u00edngua Portuguesa, tra\u00e7a a realidade vivida neste tempo pascal em isolamento Lisboa, 14 abr 2020 (Ecclesia) \u2013 O respons\u00e1vel pela Miss\u00e3o Cat\u00f3lica de L\u00edngua Portuguesa do Sul do Luxemburgo disse \u00e0 Ag\u00eancia ECCLESIA que os emigrantes celebraram a P\u00e1scoa em isolamento social, sem visitar as terras de origem e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4081,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[55,19,7],"tags":[],"class_list":["post-4079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-migrantes","category-missoes","category-recortes"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/ocpm\/wp-json\/wp\/v2\/posts\/4079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/ocpm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/ocpm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/ocpm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/ocpm\/wp-json\/wp\/v2\/comments?post=4079"}],"version-history":[{"count":1,"href":"https:\/\/sites.ecclesia.pt\/ocpm\/wp-json\/wp\/v2\/posts\/4079\/revisions"}],"predecessor-version":[{"id":4089,"href":"https:\/\/sites.ecclesia.pt\/ocpm\/wp-json\/wp\/v2\/posts\/4079\/revisions\/4089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/ocpm\/wp-json\/wp\/v2\/media\/4081"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/ocpm\/wp-json\/wp\/v2\/media?parent=4079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/ocpm\/wp-json\/wp\/v2\/categories?post=4079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/ocpm\/wp-json\/wp\/v2\/tags?post=4079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}