{"id":45,"date":"2002-07-01T00:00:00","date_gmt":"2002-07-01T00:00:00","guid":{"rendered":""},"modified":"2015-05-22T15:48:28","modified_gmt":"2015-05-22T15:48:28","slug":"nao-esquecer-quem-criou-a-ocpm","status":"publish","type":"post","link":"https:\/\/sites.ecclesia.pt\/ocpm\/nao-esquecer-quem-criou-a-ocpm\/","title":{"rendered":"N\u00e3o esquecer quem criou a OCPM"},"content":{"rendered":"<p>N\u00e3o esquecer quem criou a Obra Cat\u00f3lica Portuguesa de Migra\u00e7\u00f5es<br \/>\nA revela\u00e7\u00e3o da Igreja ao mundo portugu\u00eas forjou-se nos \u00faltimos quarenta anos atrav\u00e9s tamb\u00e9m da Obra Cat\u00f3lica Portuguesa de Migra\u00e7\u00f5es. N\u00e3o o sublinho pelo exerc\u00edcio de fun\u00e7\u00f5es; chamo simplesmente a aten\u00e7\u00e3o para um acontecimento da hist\u00f3ria da Igreja em Portugal, com in\u00edcio no \u00faltimo s\u00e9culo.<br \/>\nConforme o temos repetido, a resposta da Igreja, num per\u00edodo forte de emigra\u00e7\u00e3o, contrasta com a falta da sensibilidade em geral. S\u00f3 n\u00e3o entendo, na l\u00f3gica de uma certa hist\u00f3ria, porque \u00e9 que n\u00e3o se exercitou noutras \u00e1reas de car\u00eancias sociais o mesmo af\u00e3.<br \/>\nTer\u00e1 sido porque os encargos da solidariedade se jogavam muito longe da p\u00e1tria, onde, ao tempo, era indevida problematizar a mis\u00e9ria imerecida?<br \/>\nDesde a 1\u00aa hora, destaque-se a clarivid\u00eancia para tornar presentes os crit\u00e9rios do Evangelho junto de comunidades, doando-lhes sacerdotes que, pelas suas fun\u00e7\u00f5es espec\u00edficas, se tornaram um porto de abrigo. Pai, irm\u00e3o, amigo e pr\u00f3ximo, o padre junto de emigrantes significou e significa a forma\u00e7\u00e3o da f\u00e9, a comunh\u00e3o solid\u00e1ria, a promo\u00e7\u00e3o cultural, num halo de confian\u00e7a e sensibilidade tal, que as comunidades sempre o entenderam como confidente e procurador de todas as dificuldades. N\u00e3o esque\u00e7o, antes evoco a minha estada em Paris na d\u00e9cada de sessenta e per\u00edodos subsequentes.<br \/>\nAs in\u00fameras situa\u00e7\u00f5es &#8211; limites ajudaram-me a entender muitas coisas.<br \/>\nUnir fronteiras, ligar pessoas, sensibilizar culturas, a Igreja local e seus padres e demais agentes de pastoral, contactar afastados, empenhar-se em grupos e associa\u00e7\u00f5es, acompanhar o aproveitamento dos tempos livres, numa palavra, defender a dignidade de cada uma das pessoas, foi programa e ac\u00e7\u00e3o.<br \/>\nBispos, padres e leigos, respons\u00e1veis incarnaram a mem\u00f3ria da Justi\u00e7a e da fraternidade. N\u00e3o esqueceram os Portugueses (as), sempre t\u00e3o s\u00f3s!<br \/>\nNa mod\u00e9stia de suas vidas, os emigrantes lamuriavam-se a v\u00e1rios t\u00edtulos pelas durezas de uma condi\u00e7\u00e3o, que o tempo n\u00e3o tem curado com sufici\u00eancia. \u00c9 que, de &#8220;estranhos num pa\u00eds que n\u00e3o \u00e9 nosso, passamos a cidad\u00e3os de segunda, quando vamos a Portugal&#8221;, diziam e continuam a dizer&#8230;<br \/>\nMas o Evangelho da Obra Cat\u00f3lica sempre os proclamou portugueses (as) de primeira&#8230;<br \/>\nPor outro lado, na altura de um cap\u00edtulo inverso, entraram-nos casa adentro milhares de homens e mulheres pela saga da imigra\u00e7\u00e3o. Tem-se escrito muito sobre esta mat\u00e9ria, e pelo que leio e ou\u00e7o nos \u00faltimos tempos, vamos continuar a defrontar-nos com aspectos intoler\u00e1veis.<br \/>\nO pa\u00eds tem sabido de que lado t\u00eam estado os baptizados em Portugal. Nesta e por esta quest\u00e3o. Mas, infelizmente, as oportunidades n\u00e3o acabaram. Se a Obra Cat\u00f3lica de Migra\u00e7\u00f5es n\u00e3o existisse, teria sido urgente cri\u00e1-la. Mas, como existia, comprometeu-se com tal denodo, que at\u00e9 teve honras de ser acusada, em algumas horas, de negligenciar a emigra\u00e7\u00e3o, para se virar &#8220;para pretos e outras ra\u00e7as&#8230;&#8221;. Que honra!<br \/>\nO seu testemunho em alargados sectores eclesiais e o di\u00e1logo com quem est\u00e1 interessado por quest\u00f5es da humanidade, fora da Igreja, tem sido ponte e comunh\u00e3o.<br \/>\n&#8220;N\u00e3o fechar a porta a Cristo que bate \u00e0 porta do teu pa\u00eds na pessoa do imigrante (Jo\u00e3o Paulo II), \u00e9 uma dor de cabe\u00e7a para sectores e multid\u00f5es.<br \/>\nA Obra Cat\u00f3lica j\u00e1 criou um estilo. Mas n\u00e3o lhe ser\u00e1 f\u00e1cil, mais uma vez, o servi\u00e7o aos pobres, buscando solu\u00e7\u00f5es e apoios da dignidade. Por isso n\u00e3o h\u00e1 festejos. Os quarenta anos clamam ainda mais por decis\u00e3o.<br \/>\n+ Janu\u00e1rio Torgal Mendes Ferreira<br \/>\n(Presidente da Comiss\u00e3o Episcopal de Migra\u00e7\u00f5es e Turismo)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Palavra do presidente da Comiss\u00e3o Epsicopal de Migra\u00e7\u00f5es e Turismo<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3],"tags":[],"class_list":["post-45","post","type-post","status-publish","format-standard","hentry","category-quem-somos"],"_links":{"self":[{"href":"https:\/\/sites.ecclesia.pt\/ocpm\/wp-json\/wp\/v2\/posts\/45","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ecclesia.pt\/ocpm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ecclesia.pt\/ocpm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/ocpm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/ocpm\/wp-json\/wp\/v2\/comments?post=45"}],"version-history":[{"count":1,"href":"https:\/\/sites.ecclesia.pt\/ocpm\/wp-json\/wp\/v2\/posts\/45\/revisions"}],"predecessor-version":[{"id":1617,"href":"https:\/\/sites.ecclesia.pt\/ocpm\/wp-json\/wp\/v2\/posts\/45\/revisions\/1617"}],"wp:attachment":[{"href":"https:\/\/sites.ecclesia.pt\/ocpm\/wp-json\/wp\/v2\/media?parent=45"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/ocpm\/wp-json\/wp\/v2\/categories?post=45"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ecclesia.pt\/ocpm\/wp-json\/wp\/v2\/tags?post=45"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}